{"id":926608,"date":"2026-05-11T22:11:38","date_gmt":"2026-05-11T22:11:38","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/926608\/"},"modified":"2026-05-11T22:11:38","modified_gmt":"2026-05-11T22:11:38","slug":"tuer-par-arme-blanche-le-mode-operatoire-le-plus-frequent-en-france","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/926608\/","title":{"rendered":"Tuer par arme blanche\u00a0: le mode op\u00e9ratoire le plus fr\u00e9quent en France"},"content":{"rendered":"<p>Dans une note confidentielle de la Direction nationale de la police judiciaire (DNPJ) que nos confr\u00e8res de France\u00a0Info avaient pu consulter en\u00a02024, il apparaissait, statistiques \u00e0 l\u2019appui, qu\u2019en France, <a href=\"https:\/\/www.laprovence.com\/article\/france-monde\/31495797617815\/adolescente-tuee-a-larme-blanche-au-college-parents-et-enfants-face-a-lhorreur-absolue\" target=\"_blank\" rel=\"nofollow noopener\">tuer par arme blanche<\/a> est le mode op\u00e9ratoire le plus fr\u00e9quent.<\/p>\n<p>Plus \u00e9difiant encore, selon le document consult\u00e9, les homicides par arme blanche sont principalement commis dans un contexte d\u2019altercation entre connaissances. Viennent ensuite ceux qui se produisent dans la sph\u00e8re familiale (35\u00a0%) et plus sp\u00e9cifiquement dans le <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/484215166714814\/marseille-une-femme-dune-trentaine-dannees-tuee-a-coups-de-couteau-a-la-cabucelle\" target=\"_blank\" rel=\"nofollow noopener\">couple<\/a> (22\u00a0%). Par ailleurs, depuis\u00a02019, la totalit\u00e9 des <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/1236639044684415\/attentat-de-mulhouse-hommage-a-la-victime-ce-lundi\" target=\"_blank\" rel=\"nofollow noopener\">actes terroristes<\/a> ont \u00e9t\u00e9 commis \u00e0 l\u2019aide d\u2019une arme blanche et 58\u00a0% des homicides li\u00e9s aux rivalit\u00e9s entre bandes. Pr\u00e8s de quatre homicides par arme blanche sur dix se produisent sur la voie publique.<\/p>\n<p>Dans la moiti\u00e9 des cas la victime d\u00e9c\u00e8de avant l\u2019intervention des secours<\/p>\n<p>Concernant le profil des victimes, elles sont plut\u00f4t jeunes (38\u00a0ans en moyenne) et sont connues des services de police dans 46\u00a0% des cas. Dans la plupart des cas, les victimes re\u00e7oivent plusieurs coups de couteau et dans la moiti\u00e9 des cas, la victime d\u00e9c\u00e8de avant l\u2019intervention des secours.<\/p>\n<p>Les mis en cause pour homicide par arme blanche sont de leur c\u00f4t\u00e9 majoritairement des <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/1401863245589515\/un-homme-dune-vingtaine-dannees-tue-a-coups-de-couteau-au-quartier-sainte-anne-a-marseille\" target=\"_blank\" rel=\"nofollow noopener\">hommes<\/a> (87\u00a0% des cas) plut\u00f4t jeunes (33\u00a0ans en moyenne). La moiti\u00e9 d\u2019entre eux sont sans emploi, un tiers est sous l\u2019emprise de l\u2019alcool et 63\u00a0% sont connus de la justice.\u00a0Ce type d\u2019homicide est plus souvent commis dans des milieux sociaux plut\u00f4t d\u00e9favoris\u00e9s et marqu\u00e9s par des in\u00e9galit\u00e9s sociales.<\/p>\n<p>La note pr\u00e9cise \u00e9galement que les auteurs sont plus souvent de nationalit\u00e9 \u00e9trang\u00e8re que ceux qui ont eu recours \u00e0 un autre proc\u00e9d\u00e9 pour tuer (27\u00a0% contre 13\u00a0%) et que lorsque le mis en cause pour homicide par arme blanche est \u00e9tranger, la victime est \u00e9galement de <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/6331574\/marseille-attentat-terroriste-de-la-gare-saint-charles-en-2017-le-recit-dune-impasse-judici\" target=\"_blank\" rel=\"nofollow noopener\">nationalit\u00e9 \u00e9trang\u00e8re<\/a> dans 65\u00a0% des cas.<\/p>\n<p>Des amendes contre les lames<\/p>\n<p>Depuis\u00a02024, la justice exp\u00e9rimente, dans les ressorts d\u2019une douzaine de tribunaux judiciaires, dont celui de Marseille, l\u2019<a href=\"https:\/\/www.laprovence.com\/article\/france-monde\/36983956988176\/poignards-couteaux-et-matraques-experimentation-de-lamende-forfaitaire-pour-le-port-dune-arme-blanche\" target=\"_blank\" rel=\"nofollow noopener\">amende forfaitaire<\/a> pour sanctionner le port d\u2019arme de cat\u00e9gorie\u00a0D, soit les armes blanches\u00a0: 500\u00a0euros d\u2019amende (ou 400\u00a0euros si le contrevenant paie tout de suite), ainsi que la saisie et la destruction de l\u2019arme. <\/p>\n<p>En juin\u00a02025, le minist\u00e8re de l\u2019Int\u00e9rieur observait de \u00ab\u00a0premiers retours d\u2019exp\u00e9rience d\u00e9montrant que sont verbalis\u00e9es des personnes errant en centres urbains \u00e0 proximit\u00e9 des gares\u00a0\u00bb. Les efforts de sanctuarisation autour de la gare <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/7952992407426114\/un-homme-grievement-blesse-apres-avoir-ete-blesse-au-couteau-a-la-gare-saint-charles-a-marseille\" target=\"_blank\" rel=\"nofollow noopener\">Saint-Charles<\/a>, Belsunce ou Noailles se poursuivent\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"Dans une note confidentielle de la Direction nationale de la police judiciaire (DNPJ) que nos confr\u00e8res de France\u00a0Info&hellip;\n","protected":false},"author":2,"featured_media":926609,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[5734,11,10268,8386,274,1011,27,985,12,61940,5912,378,25,20054],"class_list":{"0":"post-926608","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-france","8":"tag-5734","9":"tag-actualites","10":"tag-arme","11":"tag-blanche","12":"tag-faits-divers-justice","13":"tag-fr","14":"tag-france","15":"tag-mode","16":"tag-news","17":"tag-operatoire","18":"tag-par","19":"tag-plus","20":"tag-republique-francaise","21":"tag-tuer"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116558239449767709","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/926608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=926608"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/926608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/926609"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=926608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=926608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=926608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}