{"id":927202,"date":"2026-05-12T04:50:27","date_gmt":"2026-05-12T04:50:27","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/927202\/"},"modified":"2026-05-12T04:50:27","modified_gmt":"2026-05-12T04:50:27","slug":"nancy-suspension-pour-stups-ou-alcool-une-commission-medicale-en-prefecture","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/927202\/","title":{"rendered":"Nancy. Suspension pour stups ou alcool\u00a0: une commission m\u00e9dicale en pr\u00e9fecture"},"content":{"rendered":"<p class=\"heading\">&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s<\/p>\n<p class=\"subtitle\">et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site et l&rsquo;application mobile<\/p>\n<p class=\"price-detail\">&#13;<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de 1 \u20ac  le 1er mois, sans engagement de dur\u00e9e&#13;\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p class=\"listSKU\" style=\"display:none\">{&lsquo;skus&rsquo;: [&lsquo;lerswgpremium16&rsquo;]}<\/p>\n<p class=\"google-sub-infos\">Google : 1\u20ac le 1er mois puis 12,99\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site&hellip;\n","protected":false},"author":2,"featured_media":927203,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9635],"tags":[1111,11,1704,1777,674,1011,27,775,3457,1702,1703,12,25,2803],"class_list":{"0":"post-927202","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nancy","8":"tag-actu","9":"tag-actualites","10":"tag-edition-nancy-et-agglomeration","11":"tag-eu","12":"tag-europe","13":"tag-fr","14":"tag-france","15":"tag-grand-est","16":"tag-meurthe-et-moselle","17":"tag-nancy","18":"tag-nancy-ville-54b","19":"tag-news","20":"tag-republique-francaise","21":"tag-transport"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116559808227735835","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/927202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=927202"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/927202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/927203"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=927202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=927202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=927202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}