{"id":930064,"date":"2026-05-13T11:51:42","date_gmt":"2026-05-13T11:51:42","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/930064\/"},"modified":"2026-05-13T11:51:42","modified_gmt":"2026-05-13T11:51:42","slug":"hantavirus-le-patient-du-chu-de-rennes-transfere-a-lhopital-bichat-a-paris-et-deux","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/930064\/","title":{"rendered":"Hantavirus\u00a0: le patient du CHU de Rennes transf\u00e9r\u00e9 \u00e0 l\u2019h\u00f4pital Bichat \u00e0 Paris et deux"},"content":{"rendered":"<p>Le minist\u00e8re de la Sant\u00e9 est tr\u00e8s avare en information tout comme les Agences r\u00e9gionales de sant\u00e9\u00a0(ARS). Selon nos informations, <a href=\"https:\/\/quimper.maville.com\/actu\/actudet_-info-ouest-france.-hantavirus-parmi-les-22-cas-contacts-un-breton-confine-chez-lui-avant-son-transfert-a-rennes-_52674-7314512_actu.Htm\" rel=\"nofollow noopener\" target=\"_blank\">le cas contact<\/a> \u00e0 l\u2019hantavirus, mardi 12\u00a0mai 2026 \u00e0 midi <a href=\"https:\/\/quimper.maville.com\/actu\/actudet_-hantavirus-cas-contact-en-finistere-nous-suivons-la-situation-avec-la-plus-grande-attention-confie-le-maire-_6-7314830_actu.Htm\" rel=\"nofollow noopener\" target=\"_blank\">de Concarneau<\/a> au CHU de Rennes, <a href=\"https:\/\/quimper.maville.com\/actu\/actudet_--qu-est-ce-qu-il-se-passe-avec-l-arrivee-d-un-cas-contact-a-l-hantavirus-le-chu-de-rennes-sous-haute-protection-_52674-7316017_actu.Htm\" rel=\"nofollow noopener\" target=\"_blank\">sous haute protection,<\/a> n\u2019est pas rest\u00e9 longtemps sur place. Il a \u00e9t\u00e9 transf\u00e9r\u00e9 dans la journ\u00e9e vers le centre hospitalier Bichat \u00e0 Paris. Originaire de la r\u00e9gion parisienne, il voulait se rapprocher de sa famille.<\/p>\n<p>Il devrait rester 15\u00a0jours, au minimum, en observation dans une chambre \u00e0 l\u2019atmosph\u00e8re r\u00e9gul\u00e9e. P\u00e9riode qui pourrait s\u2019\u00e9tendre \u00e0 42\u00a0jours correspondant \u00e0 la dur\u00e9e maximale d\u2019incubation.<\/p>\n<p>Le CHU de Rennes centre expert<\/p>\n<p>Toujours selon nos informations, le CHU de Rennes devrait accueillir deux nouveaux cas contact \u00e0 l\u2019hantavirus, sans que l\u2019on connaisse leur provenance. Probablement de Bretagne ou de d\u00e9partements limitrophes.<\/p>\n<p>Le CHU de Rennes est l\u2019un des dix centres fran\u00e7ais experts dans la prise en charge de ce type de maladie. Le service des maladies infectieuses dispose de plusieurs chambres individuelles \u00e0 pression n\u00e9gative et son personnel form\u00e9 \u00e0 ce type de prise en charge.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Le minist\u00e8re de la Sant\u00e9 est tr\u00e8s avare en information tout comme les Agences r\u00e9gionales de sant\u00e9\u00a0(ARS). Selon&hellip;\n","protected":false},"author":2,"featured_media":930065,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2821],"tags":[1111,11,86462,10180,98874,829,4309,1777,674,1011,27,97699,100,12,1113,626,9532,3086,584,25,41001],"class_list":{"0":"post-930064","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-rennes","8":"tag-actu","9":"tag-actualites","10":"tag-admissions","11":"tag-attendues","12":"tag-bichat","13":"tag-bretagne","14":"tag-chu","15":"tag-eu","16":"tag-europe","17":"tag-fr","18":"tag-france","19":"tag-hantavirus","20":"tag-hopital","21":"tag-news","22":"tag-nouvelles","23":"tag-paris","24":"tag-patient","25":"tag-redon","26":"tag-rennes","27":"tag-republique-francaise","28":"tag-transfere"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116567126221960373","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/930064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=930064"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/930064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/930065"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=930064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=930064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=930064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}