{"id":6298,"count":5,"description":"","link":"https:\/\/www.europesays.com\/fr\/tag\/pierre-francois-le-louet\/","name":"Pierre-Fran\u00e7ois Le Lou\u00ebt","slug":"pierre-francois-le-louet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags\/6298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts?tags=6298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}