{"id":68878,"count":1,"description":"","link":"https:\/\/www.europesays.com\/fr\/tag\/giscard-et-leurope-chronique-dun-reve-inacheve-documentaire\/","name":"Giscard et l&#x27;Europe chronique d&#x27;un r\u00eave inachev\u00e9 Documentaire","slug":"giscard-et-leurope-chronique-dun-reve-inacheve-documentaire","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags\/68878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts?tags=68878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}