{"id":69105,"count":2,"description":"","link":"https:\/\/www.europesays.com\/fr\/tag\/quinzieme-journee\/","name":"quinzi\u00e8me journ\u00e9e","slug":"quinzieme-journee","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags\/69105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts?tags=69105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}