{"id":369769,"date":"2026-03-05T20:53:27","date_gmt":"2026-03-05T20:53:27","guid":{"rendered":"https:\/\/www.europesays.com\/ie\/369769\/"},"modified":"2026-03-05T20:53:27","modified_gmt":"2026-03-05T20:53:27","slug":"harvey-weinstein-to-face-rape-retrial-next-month-%c2%b7-thejournal-ie","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ie\/369769\/","title":{"rendered":"Harvey Weinstein to face rape retrial next month \u00b7 TheJournal.ie"},"content":{"rendered":"<p class=\"contribution-prompt-banner-title\">We need your help now<\/p>\n<p><strong>Support from readers like you keeps The Journal open.<\/strong><\/p>\n<p>You are visiting us because we have something you value. Independent, unbiased news that tells the truth. Advertising revenue goes some way to support our mission, but this year it has not been enough.<\/p>\n<p>If you&#8217;ve seen value in our reporting, please contribute what you can, so we can continue to produce accurate and meaningful journalism. For everyone who needs it.<\/p>\n","protected":false},"excerpt":{"rendered":"We need your help now Support from readers like you keeps The Journal open. You are visiting us&hellip;\n","protected":false},"author":2,"featured_media":369770,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[18,117,85009,1239,19,17,116748,34144,968,171135],"class_list":{"0":"post-369769","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entertainment","8":"tag-eire","9":"tag-entertainment","10":"tag-harvey-weinstein","11":"tag-hollywood","12":"tag-ie","13":"tag-ireland","14":"tag-me-too","15":"tag-metoo","16":"tag-new-york","17":"tag-retrial"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ie\/116178557515403624","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/posts\/369769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/comments?post=369769"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/posts\/369769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/media\/369770"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/media?parent=369769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/categories?post=369769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/tags?post=369769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}