{"id":69880,"count":1,"description":"","link":"https:\/\/www.europesays.com\/ie\/tag\/college-romance-movies\/","name":"College romance movies","slug":"college-romance-movies","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/tags\/69880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/ie\/wp-json\/wp\/v2\/posts?tags=69880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}