{"id":100643,"date":"2025-09-10T22:38:10","date_gmt":"2025-09-10T22:38:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/100643\/"},"modified":"2025-09-10T22:38:10","modified_gmt":"2025-09-10T22:38:10","slug":"gabbia-pensa-gia-al-derby-una-fortuna-avere-allegri","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/100643\/","title":{"rendered":"Gabbia pensa gi\u00e0 al derby: &#8220;Una fortuna avere Allegri&#8221;"},"content":{"rendered":"<p>                                Il centrale rossonero \u00e8 stato l\u2019uomo simbolo di un anno fa quando, a tempo quasi scaduto, regal\u00f2 la vittoria ai suoi con un colpo di testa votato come miglior gol rossonero della scorsa stagione al 30\u00ba premio Gentleman<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Sar\u00e0 Matteo Gabbia il volto del nuovo corso \u201callegriano\u201d del Milan? Presto per dirlo, ma di sicuro il centrale rossonero \u00e8 stato l\u2019uomo simbolo del derby dello scorso anno, quando a tempo quasi scaduto regal\u00f2 la vittoria al suo Milan. Un colpo di testa votato come miglior gol rossonero della scorsa stagione al 30\u00ba premio Gentleman: \u201cL\u2019Inter dimostra di essere una squadra forte da anni, ma lo scorso anno siamo stati bravi. Proveremo a ripeterci sapendo che per i tifosi \u00e8 importante ma \u00e8 una partita che vale 3 punti come tutte le altre\u2026\u201d.\u00a0<\/p>\n<p>    lavoro\u2014 \u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Poi Gabbia passa all\u2019attualit\u00e0, alle settimane di lavoro con Allegri: \u201cStiamo lavorando molto sulla fase difensiva, non solo di reparto ma proprio su tutta la struttura che poi la squadra deve avere nel momento in cui c\u2019\u00e8 da difendere. Stiamo assimilando, avere Allegri \u00e8 una fortuna: chiaro \u00e8 che in alcune partite si riesca di pi\u00f9 e in altre meno, ma l\u2019importante \u00e8 trovare la continuit\u00e0 che l\u2019anno scorso \u00e8 mancata. Obiettivo? Vincere tutte le partite che affrontiamo. Dichiararne uno oggi \u00e8 prematuro, un bilancio si potr\u00e0 tracciare a marzo-aprile\u201d. Gabbia poi passa ai nuovi arrivi, in particolare uno: \u201cNkunku \u00e8 fortissimo, la societ\u00e0 \u00e8 stata bravissima. Noi ce lo godremo in campo ma soprattutto sono molto contento del suo atteggiamento in allenamento. San Siro senza tifosi? Il compito nostro \u00e8 quello di giocare, ma dispiace sentire la mancanza del tifo organizzato: l\u2019atmosfera quando giocavamo in casa era incredibile, si sentiva proprio, trascinava tutto. Ma ci sono vicissitudini che non dipendono dallo sport\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Il centrale rossonero \u00e8 stato l\u2019uomo simbolo di un anno fa quando, a tempo quasi scaduto, regal\u00f2 la&hellip;\n","protected":false},"author":3,"featured_media":100644,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1452],"tags":[3076,1495,721,925,71421,71422,5371,15760,71423,5187,1740,3440,2611,24659,71424,71425,1976,71426,71427,1537,90,89,553,9611,1739,245,244],"class_list":{"0":"post-100643","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calcio","8":"tag-allegri","9":"tag-altre","10":"tag-calcio","11":"tag-centrale","12":"tag-centrale-rossonero","13":"tag-centrale-rossonero-simbolo","14":"tag-colpo","15":"tag-colpo-testa","16":"tag-colpo-testa-votato","17":"tag-derby","18":"tag-football","19":"tag-forte","20":"tag-fortuna","21":"tag-gabbia","22":"tag-gabbia-passa","23":"tag-gentleman","24":"tag-gol","25":"tag-gol-rossonero","26":"tag-gol-rossonero-scorsa","27":"tag-it","28":"tag-italia","29":"tag-italy","30":"tag-milan","31":"tag-rossonero","32":"tag-soccer","33":"tag-sport","34":"tag-sports"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/100643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=100643"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/100643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/100644"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=100643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=100643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=100643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}