{"id":17265,"date":"2025-07-30T03:55:09","date_gmt":"2025-07-30T03:55:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/17265\/"},"modified":"2025-07-30T03:55:09","modified_gmt":"2025-07-30T03:55:09","slug":"rune-due-di-picche-da-kudermetova-mi-ha-scritto-ma-sono-sposata-e-non-mi-ha-piu-salutata","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/17265\/","title":{"rendered":"Rune, due di picche da Kudermetova: \u00abMi ha scritto, ma sono sposata. E non mi ha pi\u00f9 salutata\u00bb"},"content":{"rendered":"<p>Il racconto della tennista russa: \u00abSe vedi il mio profilo Instagram, si capisce che ho un marito. Lui si \u00e8 scusato\u00bb<\/p>\n<p class=\"chapter-paragraph\">\u00c8 stato un due di picche difficile da digerire quello che ha ricevuto <b>Holger Rune, 22 anni, dopo le avances a Veronika Kudermetova<\/b>, attualmente numero 42 al mondo (\u00e8 stata nona nel 2022). Ha raccontato tutto la tennista russa: \u00abMi ha scritto Rune di recente\u00bb, ha confessato la 28enne al podcast di Elena Vesnina. \u00abIo gli ho detto &#8220;Cavolo, probabilmente sono troppo vecchia per te. <b>E se hai guardato il mio Instagram, ho un marito&#8221;. Lui si \u00e8 scusato e da allora non mi ha pi\u00f9 salutata<\/b>\u00bb, ha continuato Veronika sorridendo.<\/p>\n<p class=\"chapter-paragraph\">In effetti la tennista russa <b>\u00e8 sposata dal 2017 con Sergei Demekhine, ex tennista e suo allenatore<\/b>. \u00c8 una delle coppie pi\u00f9 solide del mondo dello sport. Si sono conosciuti quando Kudermetova aveva 15 anni, nel 2012. Tre anni dopo, nel 2015, hanno iniziato a frequentarsi, per poi sposarsi. Tutti dettagli che <a href=\"https:\/\/www.corriere.it\/sport\/tennis\/25_giugno_24\/rune-vende-racchette-spaccate-aa44266a-5cd0-4656-a031-b39511f93xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">il danese Rune<\/a> forse non conosceva, anche se in realt\u00e0 basta andare sul web e sui social per sapere del suo matrimonio e di come con il marito vada tutto a gonfie vele. Rune ha ignorato tutto questo, tanto da spingersi a un corteggiamento via Instagram. Non immaginandosi, per\u00f2, di ricevere un secco (e repentino) \u00abno\u00bb. Segnale di come le sue avances non siano state gradite per niente dalla russa. E Holger se ne far\u00e0 una ragione.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"is-last-update\" datetime=\"2025-07-29T19:48:09+02:00\">29 luglio 2025<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"Il racconto della tennista russa: \u00abSe vedi il mio profilo Instagram, si capisce che ho un marito. Lui&hellip;\n","protected":false},"author":3,"featured_media":17266,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1451],"tags":[19862,1621,1620,203,19863,230,204,1537,90,89,19860,7242,19864,19865,19859,4152,19866,988,19867,1898,19861],"class_list":["post-17265","post","type-post","status-publish","format-standard","has-post-thumbnail","category-celebrita","tag-avances","tag-celebrita","tag-celebrities","tag-entertainment","tag-holger","tag-instagram","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-kudermetova","tag-marito","tag-marito-scusato","tag-picche","tag-rune","tag-russa","tag-salutata","tag-scritto","tag-scusato","tag-tennista","tag-tennista-russa"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/17265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=17265"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/17265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/17266"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=17265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=17265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=17265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}