{"id":177525,"date":"2025-10-22T02:40:17","date_gmt":"2025-10-22T02:40:17","guid":{"rendered":"https:\/\/www.europesays.com\/it\/177525\/"},"modified":"2025-10-22T02:40:17","modified_gmt":"2025-10-22T02:40:17","slug":"eric-schmidt-ex-ceo-di-google-70enne-e-la-compagna-michelle-ritter-30-anni-soldi-stalking-e-ricatti-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/177525\/","title":{"rendered":"Eric Schmidt, ex ceo di Google (70enne) e la compagna Michelle Ritter (30 anni): soldi, stalking e ricatti"},"content":{"rendered":"<p>                Cosa succeder\u00e0? <\/p>\n<p>Ora la donne vive a Beverly Hills, da sola. Lui avrebbe avviato un arbitrato contro di lei, accusandola di abusi del sistema legale: lei aveva dichiarato di non potersi permettere le spese di difesa, ma le battaglie per la separazione e gli accordi riservati sono comunque andati avanti. Quella tra Schimt e Ritter \u00e8 una questione molto complessa che dovr\u00e0 essere analizzata, in modo razionale, da giudici e legali di pertinenza, ma una cosa \u00e8 chiara: descrive un certo tipo di dinamiche di poter tipiche dei miliardari della Silicon Valley in cui il denaro diventa un&#8217;arma contro le donne con cui hanno relazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"Cosa succeder\u00e0? Ora la donne vive a Beverly Hills, da sola. Lui avrebbe avviato un arbitrato contro di&hellip;\n","protected":false},"author":3,"featured_media":177059,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1451],"tags":[1621,1620,203,76682,682,204,1537,90,89,107665,107666,1467],"class_list":["post-177525","post","type-post","status-publish","format-standard","has-post-thumbnail","category-celebrita","tag-celebrita","tag-celebrities","tag-entertainment","tag-eric-schmidt","tag-google","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-michelle-ritter","tag-relazioni-tossiche","tag-violenza"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115415510094439437","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/177525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=177525"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/177525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/177059"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=177525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=177525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=177525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}