{"id":189601,"date":"2025-10-29T13:01:21","date_gmt":"2025-10-29T13:01:21","guid":{"rendered":"https:\/\/www.europesays.com\/it\/189601\/"},"modified":"2025-10-29T13:01:21","modified_gmt":"2025-10-29T13:01:21","slug":"montalbano-su-rai-1-trama-e-storia-vera-di-salvo-caro-livia-mia","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/189601\/","title":{"rendered":"Montalbano su Rai 1: trama e storia vera di Salvo caro Livia mia"},"content":{"rendered":"<p>                              <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/10\/montalbano.jpg\" loading=\"lazy\" alt=\"I protagonisti della puntata di oggi de Il commissario Montalbano: Sonia Bergamasco e Luca Zingaretti in Salvo amato, Livia mia\" width=\"1280\" height=\"800\"\/><\/p>\n<p class=\"img-caption\"> I protagonisti della puntata di oggi de Il commissario Montalbano: Sonia Bergamasco e Luca Zingaretti in Salvo amato, Livia mia<\/p>\n<p>\n                              <strong>LA FINE SI AVVICINA..<\/strong>. Rai 1 continua a celebrare i <strong>100 anni dalla nascita di Andrea Camilleri<\/strong> con la messa in onda, in replica, degli episodi della serie pi\u00f9 amata, tra quelle tratte dai romanzi dello scrittore siciliano: Il commissario Montalbano. Stasera (ri)vedremo Salvo amato, Livia mia. Il <strong>35mo dei 37 episodi della seri<\/strong>e (il box set completo \u00e8 in streaming su RaiPlay).\n                          <\/p>\n<p>\n                              L&#8217;appuntamento \u00e8 <strong>alle 21,30 su Rai 1 (e in contemporanea streaming sulla piattaforma).<\/strong> Andato in onda la prima volta il 9 marzo 2020 (9.377.000 spettatori, 39% di share), \u00e8 il primo dei due episodi che compongono la <strong>14ma e penultima stagione<\/strong> del classico con Luca Zingaretti. Il quale firma la regia insieme ad <strong>Alberto Sironi,<\/strong> lo storico regista della serie (dal primo episodio: Il ladro di merendine trasmesso per la prima volta il 6 maggio 1999). Quando vedemmo l&#8217;episodio di stasera, quel 9 marzo 2020, lui non c&#8217;era pi\u00f9. Sironi, tra i pi\u00f9 prolifici tra i registi televisivi, \u00e8 infatti morto, dopo una lunga malattia, il 5 agosto 2019: due giorni dopo avrebbe compiuto 79 anni.\n                          <\/p>\n<p>\n                              Salvo amato, Livia mia \u00e8 il titolo dell&#8217;episodio. E del <strong>racconto che l&#8217;ha ispirato<\/strong> (nella raccolta Gli arancini di Montalbano), dalla &#8220;inusuale&#8221; struttura epistolare. Il commissario infatti indaga &#8220;da remoto&#8221; sul caso della <strong>morte di un&#8217;amica della fidanzata<\/strong>.<strong> Camilleri non l&#8217;ha mai &#8220;ufficializzata&#8221; come ispirazione\/rivisitazione<\/strong>, ma in molti trovarono similitudini con il famoso <strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Delitto_della_Cattolica\" target=\"_blank\" rel=\"noopener nofollow external\" data-wpel-link=\"external\">delitto della Cattolica<\/a>.<\/strong> Ovvero, la morte (cold case ancora aperto: l&#8217;assassino non \u00e8 mai stato trovato) di Simonetta Ferrero, il 24 luglio 1971. La 26enne fu trovata morta, accoltellata, nei bagni dell&#8217;ateneo milanese. <strong>Il caso \u00e8, appunto, ancora senza un colpevole.\u00a0<\/strong>\n                          <\/p>\n<p>\n                              Il commissario si trova alle prese con <strong>due &#8220;strani&#8221; casi.<\/strong> Un metronotte scopre <strong>Pasquale (Fabio Costanzo), il figlio di Adelina (Ketty Governali)<\/strong>, la sua governante, mentre ruba in una villa. Riuscir\u00e0 Montalbano (Luca Zingaretti) a evitare che il ragazzo venga denunciato ed evitare altri dolori alla madre?\n                          <\/p>\n<p>\n                              Il secondo caso \u00e8 quello del <strong>cadavere di Agata Cosentino<\/strong> (Federica De Benedittis), <strong>cara amica di Livia (Sonia Bergamasco)<\/strong>, trovato nell&#8217;archivio comunale di Vigata. Qualcuno l&#8217;ha <strong>uccisa a colpi di martello.<\/strong> Ma perch\u00e9 la ragazza, timida e riservata, era l\u00ec? <strong>Gli uffici erano chiusi<\/strong> per i lavori di ristrutturazione. Nell&#8217;edificio c&#8217;erano solo <strong>alcuni operai<\/strong> impegnati nei lavori (esattamente come quel 24 luglio 1971 in Cattolica). L&#8217;indagine sveler\u00e0 una cruda e scomoda verit\u00e0. Di cui <strong>Montalbano scriver\u00e0 a Livia<\/strong>&#8230;\n                          <\/p>\n","protected":false},"excerpt":{"rendered":"I protagonisti della puntata di oggi de Il commissario Montalbano: Sonia Bergamasco e Luca Zingaretti in Salvo amato,&hellip;\n","protected":false},"author":3,"featured_media":189602,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1444],"tags":[5466,114271,114274,7074,26999,114275,114276,114277,114278,114279,18477,44168,2389,114280,114281,1046,3758,66045,446,2446,203,1230,9162,204,11204,1537,90,89,114270,6991,38718,44170,114272,52384,114273,1821,11431,83475,1567,88351,253,2475,9294,76507],"class_list":["post-189601","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tv","tag-amato","tag-amato-livia","tag-amato-livia-montalbano","tag-amica","tag-archivio","tag-archivio-comunale","tag-archivio-comunale-vigata","tag-assomiglia","tag-assomiglia-amato","tag-assomiglia-amato-livia","tag-bergamasco","tag-camilleri","tag-cast","tag-cast-amato","tag-cast-amato-livia","tag-cattolica","tag-commissario","tag-commissario-montalbano","tag-comunale","tag-delitto","tag-entertainment","tag-episodi","tag-episodio","tag-intrattenimento","tag-ispirato","tag-it","tag-italia","tag-italy","tag-livia","tag-luca","tag-luca-zingaretti","tag-montalbano","tag-montalbano-stasera","tag-scomoda","tag-scomoda-verita","tag-serie","tag-stasera","tag-stasera-tv","tag-storia","tag-storia-vera","tag-tv","tag-vera","tag-verita","tag-zingaretti"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/189601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=189601"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/189601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/189602"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=189601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=189601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=189601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}