{"id":209097,"date":"2025-11-11T01:13:15","date_gmt":"2025-11-11T01:13:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/209097\/"},"modified":"2025-11-11T01:13:15","modified_gmt":"2025-11-11T01:13:15","slug":"quattro-gol-tre-episodi-due-rigori-un-colombo-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/209097\/","title":{"rendered":"Quattro gol, tre episodi, due rigori, un Colombo"},"content":{"rendered":"<p>        <a href=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/11\/580009979_18534455575039294_160711014340296130_n.jpg\" data-caption=\"La dedica di Lorenzo Colombo (foto di Genoa CFC Tanopress)\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1800\" class=\"entry-thumb td-modal-image\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/11\/580009979_18534455575039294_160711014340296130_n.jpg\"   alt=\"Colombo Genoa\" title=\"Colombo\"\/><\/a>La dedica di Lorenzo Colombo (foto di Genoa CFC Tanopress)<\/p>\n<p>Per fortuna giunge la pausa perch\u00e9 la confusione iniziava a sovrapporre pensieri e appunti. Genoa e Fiorentina, le disorganizzatrici del campionato: in campo e in societ\u00e0. Esasperate, entrambe hanno cambiato allenatore e direttore sportivo \u2013 quasi un unicum \u2013 pescando senza convinzione dai propri vivai. Ammaccate di lividi, entrambe hanno preferito non infierire ulteriore male dopo essersele date da orbi per una settantina di minuti. La partita del Ferraris ha suscitato proprio questa impressione: una lotta truculenta tra convalescenti buttati a forza gi\u00f9 dal lettino. Una gara senza padroni, prona al ribaltone: scappa, tanto ti prendo. Vantaggio e parit\u00e0 distanti per due volte tra i tre e i cinque minuti, con la lettura Var a fare da mantice e soffiare sull\u2019impazienza. Per queste due squadre in crisi tenere in pugno la vittoria \u00e8 come stringere un tizzone estratto dal braciere: meglio attendere momenti pi\u00f9 consoni per superare le prove ordaliche.<\/p>\n<p>L\u2019incontro <a href=\"https:\/\/www.pianetagenoa1893.net\/la-partita-odierna\/genoa-fiorentina-live-match-2\/\" target=\"_blank\" rel=\"noopener nofollow\">del Ferraris<\/a> ha testimoniato quanto sar\u00e0 difficile il lavoro demandato e assunto da De Rossi e Vanoli. Uno scatenato in tribuna, tra computer e cuffiette; l\u2019altro spettinato ribelle nel recinto tecnico, gi\u00e0 ammonito sul fare della met\u00e0 del primo tempo. Se il centrocampo del Genoa avesse un poco della tecnica di quello della Fiorentina e se, viceversa, la mediana della Viola avesse appena una frazione dell\u2019interdizione che appesantisce il reparto rossobl\u00f9, allora ne uscirebbe il centrocampo perfetto. Ma cos\u00ec non pu\u00f2 essere, ed ecco che i difetti di ciascuno suonano dolorosi come una stonatura. Il Grifone \u00e8 \u2013 di certo non da ieri \u2013 piatto, prevedibile e Martin dipendente, nel senso che se la palla non esce dal sinistro educatissimo del catalano, non ha alcun senso e non procura fastidio alcuno all\u2019avversario. La Fiorentina, come visto, se aggredita alle spalle dei metodisti offre in cambio il vuoto cosmico.<\/p>\n<p>Quattro gol, tre episodi, due rigori, un Colombo. \u00c8 lui che irrompe sulla scena e la monopolizza con una sfilza di brutture cadette che, a un certo punto, hanno spazientito persino il fato calcistico. Prima la sbracciata da nuotatore che regala il pari a Gudmundsson, successivamente l\u2019elegante rifiuto dell\u2019omaggio ricambiato da Ranieri gettato tra le mani di De Gea. Bruciato un altro rigorista sotto l\u2019altare della Nord, l\u2019incarico sia affidato definitivamente ai pi\u00f9 tecnici: Martin, deputato gi\u00e0 di qualsivoglia palla inattiva, e Malinovskyi. Il Genoa non pu\u00f2 sprecare altre occasioni simili. Passati in svantaggio dopo il liscio allegro di Marcandalli su Albert, i rossobl\u00f9 hanno pareggiato in modo inconsueto: da tergo. E di terga. Pedata alla palla e ci abbracciamo. Il Colombo che diventa Grifone. Che sia la svolta buona. L\u2019azione non pu\u00f2 certo dirsi costruita, ma frutto di una grande confusione. Quella che iniziava a sovrapporre pensieri e appunti. Per fortuna giunge la pausa.<\/p>\n<p><a href=\"https:\/\/whatsapp.com\/channel\/0029VaD5MWG0LKZFhtYue71t\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-244814 size-large\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/07\/Schermata-2023-11-12-alle-17.31.33-1024x105.png\" alt=\"Genoa Pianetagenoa1893.net Gilardino Gudmundsson Whatsapp\" width=\"696\" height=\"71\"  \/><\/a><\/p>\n<p>\t\t<br clear=\"all\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"La dedica di Lorenzo Colombo (foto di Genoa CFC Tanopress) Per fortuna giunge la pausa perch\u00e9 la confusione&hellip;\n","protected":false},"author":3,"featured_media":209017,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176],"tags":[6298,119549,1537,90,89,124645,245,244],"class_list":{"0":"post-209097","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport","8":"tag-genoa","9":"tag-genoa-fiorentina","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-lorenzo-colombo","14":"tag-sport","15":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115528414599770750","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/209097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=209097"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/209097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/209017"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=209097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=209097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=209097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}