{"id":230731,"date":"2025-11-24T23:04:14","date_gmt":"2025-11-24T23:04:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/230731\/"},"modified":"2025-11-24T23:04:14","modified_gmt":"2025-11-24T23:04:14","slug":"ucraina-russia-cose-veramente-successo-a-ginevra-dallimboscata-interna-a-rubio-al-nuovo-piano-in-19-punti-perche-si-parla-di-una-svolta-per-la-pace","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/230731\/","title":{"rendered":"Ucraina-Russia, cos&#8217;\u00e8 veramente successo a Ginevra? Dall&#8217;\u00abimboscata interna\u00bb a Rubio al nuovo piano in 19 punti: perch\u00e9 si parla di una svolta per la pace"},"content":{"rendered":"<p>    di<br \/>\n    Mara Gergolet<\/p>\n<p class=\"summary-art is-line-h-12\">Dopo ore tesissime (\u00abi negoziati sono stati appesi a un capello\u00bb), i messaggi emersi da una notte di trattative sembrano segnare un deciso passo avanti. E Kiev annuncia: \u00abC&#8217;\u00e8 un nuovo piano in 19 punti, ora Trump e Zelensky parleranno dei dettagli pi\u00f9 delicati\u00bb<\/p>\n<p class=\"chapter-paragraph\">DALLA NOSTRA INVIATA<br \/>GINEVRA &#8211; Nella notte, dopo quattro anni, pare finalmente che ci sia <b>una prima svolta nella guerra in Ucraina<\/b>. Lo stallo, il ghiaccio pare rotto. Gli americani e gli ucraini fanno una dichiarazione comune, in cui affermano che si sono compiuti progressi \u00abenormi\u00bb.<\/p>\n<p class=\"chapter-paragraph\">Poi il segretario di Stato americano, <b>Marco Rubio<\/b>, che guida la delegazione qui, aggiunge: <b>\u00abMi sento molto ottimista sul fatto che ci arriveremo in un periodo di tempo molto ragionevole\u00bb<\/b>. E ancora: \u00abNon voglio dichiarare vittoria, o parlare gi\u00e0 di conclusioni, qui. C\u2019\u00e8 ancora del lavoro da fare\u00bb. Aggiunge che <b>il testo finale dell\u2019accordo avr\u00e0 bisogno dell\u2019approvazione del presidente ucraino Volodymyr Zelensky e di Donald Trump prima di essere inviato a Mosca<\/b>.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">\u00abLe discussioni hanno mostrato progressi significativi verso l\u2019allineamento delle posizioni e <b>l\u2019identificazione di chiari passi successivi<\/b>. Hanno ribadito che qualsiasi futuro accordo dovr\u00e0 <b>rispettare pienamente la sovranit\u00e0 dell\u2019Ucraina e garantire una pace sostenibile e giusta<\/b>\u00bb.\u00a0<\/p>\n<p class=\"chapter-paragraph\">E nel pomeriggio di luned\u00ec arrivano &#8211; <a href=\"https:\/\/www.ft.com\/content\/883e5a47-430c-4fc2-85ee-cd6af9bb599d?emailId=79cd785c-2f3d-4a93-a838-d7bcd01466df&amp;segmentId=ce31c7f5-c2de-09db-abdc-f2fd624da608\" rel=\"nofollow noreferrer noopener\" target=\"_blank\">anticipate dal Financial Times <\/a>&#8211; anche le dichiarazioni ucraine: certo, all&#8217;inizio le discussioni con gli americane sono state molto tese (\u00abi negoziati sono stati appesi a un capello\u00bb), ma si \u00e8 arrivati alla definizione di un <b>nuovo piano, in 19 punti<\/b>; e alla discussione tra Trump e Zelensky viene demandata la risoluzione di <b>punti delicatissimi, dalla definizione delle cessioni territoriali a quella dei rapporti con la Nato<\/b>.<\/p>\n<p class=\"chapter-paragraph\">Ginevra, l\u2019inizio della fine della guerra, forse, come tutti sperano. Dipende da come proseguiranno i colloqui, ma quello che pare certo \u00e8 che \u2014 dietro l\u2019ultimatum americano, dietro il soccorso europeo agli ucraini, dietro questi incontri ginevrini che si svolgono tra l\u2019hotel Intercontinental e la missione americana \u2014 un meccanismo si \u00e8 messo in moto.\u00a0<\/p>\n<p class=\"chapter-paragraph\">E come osserva Gideon Rachman, il commentatore principe del Financial Times,<a href=\"https:\/\/www.corriere.it\/esteri\/25_novembre_24\/ucraina-28-punti-trump-09a60d54-bdef-4cdf-9ccd-e4e99d631xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\"> rispetto al \u00abpatto Witkoff-Dmitriev\u00bb<\/a>, se \u00e8 vero che la bozza era\u00a0 inaccettabile per gli europei e per Kiev, \u00e8 vero anche che gli ucraini, sfiniti e sfibrati dall\u2019aggressione, hanno interesse a una pace che non li svenda e non li faccia capitolare.<\/p>\n<p>    L&#8217;interminabile giornata di domenica: dalla lite all&#8217;intesa<\/p>\n<p class=\"chapter-paragraph\"><b>Quella di domenica \u00e8 stata una giornata interminabile<\/b>. Da una parte <b>Rubio, il segretario di Stato  americano, forse vittima di un\u2019imboscata interna<\/b>. Dall\u2019altra <b>Andriy Yermak<\/b>, il capo dello staff presidenziale, mandato qui da Zelensky: <a href=\"\">che l\u2019Ucraina sia guidata, nell\u2019ora pi\u00f9 difficile, da \u00abcervello\u00bb politico lambito dallo scandalo corruzione<\/a>, mostra in che condizioni negozia Kiev. Con una palla al piede, almeno una mano dietro le spalle,  ma alternative migliori non ce ne sono.\u00a0<\/p>\n<p>APPROFONDISCI CON IL PODCAST<\/p>\n<p class=\"chapter-paragraph\">L\u2019Europa \u00e8 presente con i consiglieri di sicurezza nazionale dei maggiori Paesi: a fare da consulenti, e sostenere l\u2019Ucraina. A riscrivere la bozza, sulla quale Usa  e Ucraina trattano.<\/p>\n<p class=\"chapter-paragraph\">Nel pomeriggio di ieri, il primo segnale positivo. I giornalisti vengono invitati nella missione americana, dove Rubio e Yermak fanno le prime dichiarazioni.<\/p>\n<p class=\"chapter-paragraph\">Marco Rubio: \u00ab\u00c8 l\u2019incontro pi\u00f9 significativo finora\u00bb. Andriy Yermak: \u00abAbbiamo fatto ottimi progressi. Ci muoviamo avanti verso una pace giusta e duratura\u00bb. Parlano davanti a due grosse bandiere alle spalle, una americana, l\u2019altra ucraina, assicurano che tutto procede bene. \u00c8 la faccia positiva, ottimistica che mostrano alle telecamere.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Ma quanto era diversa la faccia tesa di Marco Rubio, il segretario di Stato americano, le labbra serrate, il passo veloce per evitare le domande, quando appena un\u2019ora prima usciva dalla hall dell\u2019Intercontinental. \u00c8 in questo chilometro, tra l\u2019albergo dei grandi negoziati Onu e la missione Usa, con vista sul lago, che si prova a ricucire lo strappo.<br \/>\u00a0<br \/>Nell\u2019albergo ci sono  i top player diplomatici europei:<b> Jonathan Powell<\/b> (GB, l\u2019uomo della pace in Irlanda del Nord); <b>Emmanuel Bonne<\/b>, consigliere di Macron; <b>G\u00fcnther Sutter<\/b>, il nerd diplomatico di Merz, che vedono subito gli ucraini. Per l\u2019Italia, li raggiunge il consigliere diplomatico di Meloni, l\u2019ambasciatore <b>Fabrizio Saggio<\/b>. Presente Bj\u00f6rn Seibert, il braccio destro di Ursula von der Leyen.<\/p>\n<p class=\"chapter-paragraph\">Mentre Rubio, dicevamo, usciva scuro dall\u2019albergo,<b> Donald Trump dall\u2019America tuonava<\/b>: \u00abLA \u201cLEADERSHIP\u201d UCRAINA NON HA ESPRESSO ALCUNA GRATITUDINE PER I NOSTRI SFORZI, E L\u2019EUROPA CONTINUA A COMPRARE PETROLIO DALLA RUSSIA\u00bb. Dunque, come sono andati davvero i negoziati? Barak Ravid di Axios, l\u2019uomo che ha fatto lo scoop sul piano Witkoff-Dmitriev in 28 punti, uno dei giornalisti meglio informati d\u2019America, sostiene che in stanza tra gli americani e gli ucraini la tensione era alta, che <b>si \u00e8 litigato per ore<\/b>. Per\u00f2, l\u2019importante era mostrare unit\u00e0. E la sera \u2014 e questo doveva essere un segnale di svolta, del clima costruttivo che si stava creando  \u2014 le due delegazioni sono state viste cenare insieme al ristorante italiano \u00abIl Lago\u00bb.<\/p>\n<p class=\"chapter-paragraph\">Ha capito l\u2019antifona, nel pomeriggio, a Kiev anche Zelensky, che ha prontamente reso grazie \u2014 memore dell\u2019umiliazione alla Casa Bianca \u2014 al presidente americano: l\u2019Ucraina \u00e8 \u00abgrata agli Stati Uniti, a ogni cuore americano e personalmente al presidente Trump per l\u2019assistenza\u00bb. E poi: \u00abl\u2019America ci ascolta\u00bb.<\/p>\n<p class=\"chapter-paragraph\">\u00c8 il copione da ripetere a ogni interazione con Trump. Tutti si adeguano. Per\u00f2 Ginevra \u00e8 l\u2019ultima spiaggia per tanti attori: Zelensky; l\u2019Europa; e perfino Rubio. Non si tratta di forma, ma di sostanza.<\/p>\n<p>    L&#8217;affiancamento dell&#8217;Europa all&#8217;Ucraina<\/p>\n<p class=\"chapter-paragraph\">E la sostanza \u00e8 che l\u2019Europa ha affiancato l\u2019Ucraina nel tentativo di ribaltare lo sbilanciamento filo-russo del patto Witkoff-Dmitriev. Partendo dal testo dei 28 punti e riscrivendolo. <a href=\"https:\/\/www.corriere.it\/esteri\/25_novembre_23\/ucraina-piano-europeo-28-punti-63c5c12f-b6ba-46f4-9cbc-be77b115exlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">La bozza europea, diffusa da Reuters, corregge due punti chiave per Kiev<\/a>: porta il limite dell\u2019esercito ucraino a 800.000 unit\u00e0 (sarebbe il maggiore d\u2019Europa); e chiede il cessate il fuoco sulle linee attuali del conflitto, demandando a dopo la discussione sui territori.<\/p>\n<p class=\"chapter-paragraph\">L\u2019Europa invece ha preteso lo stralcio della questione degli asset russi congelati (che secondo Bloomberg \u00e8 svanita, in effetti, dal \u00abnuovo\u00bb piano in 19 punti); ha chiesto per l\u2019Ucraina garanzie stile articolo 5, che era un\u2019idea italiana; vuole che nulla della sicurezza europea si discuta senza gli europei. Cose ovvie nell\u2019America di un tempo, conquiste da strappare con i denti in quella di Trump.<\/p>\n<p class=\"chapter-paragraph\">Infine, Marco Rubio: ieri sedeva a centrotavola, con Witkoff alla sua destra e Dan Driscoll (l\u2019uomo di JD Vance ) a sinistra a ripristinare la propria autorit\u00e0. Cosa sapeva dei 28 punti? Nulla fino all\u2019ultimo? Le clamorose smentite e gaffe (Rubio avrebbe detto a senatori repubblicani che il piano l\u2019avevano scritto i russi) hanno svelato al mondo<b> la guerra tra bande alla Casa Bianca<\/b>. Per\u00f2 Rubio \u00e8 anche il migliore, forse l\u2019unico alleato su cui possono contare gli europei e gli ucraini. E rientrato in sella, sembra condurre i giochi.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-11-24T17:02:04+01:00\">24 novembre 2025 ( modifica il 24 novembre 2025 | 17:02)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Mara Gergolet Dopo ore tesissime (\u00abi negoziati sono stati appesi a un capello\u00bb), i messaggi emersi da&hellip;\n","protected":false},"author":3,"featured_media":230732,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[6],"tags":[579,1237,13029,2537,2032,4717,2017,136667,536,6466,134728,35577,136668,842,24790,30465,41,14,1338,1102,4542,43,6632,17525,1112,1113,206,3085,2697,1727,6499,6517,2828,807,5183,1374,77,8,136669,136670,1302,136671,115607,10563,1537,90,89,400,4104,4047,31644,1351,136672,4475,136673,136674,7,15,82,9,83,10,4476,402,13278,68,7987,136675,136676,975,133633,427,492,135,31645,1292,1484,136677,136678,4477,171,7638,6366,75436,863,9614,7617,11608,13,379,170,4485,11,80,84,12,81,85,8636,134253,9488,4473],"class_list":["post-230731","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ultime-notizie","tag-accordo","tag-aggiunge","tag-albergo","tag-altra","tag-america","tag-americana","tag-americani","tag-americani-ucraini","tag-americano","tag-andriy","tag-andriy-yermak","tag-appesi","tag-appesi-capello","tag-bianca","tag-bozza","tag-capello","tag-consigliere","tag-cronaca","tag-definizione","tag-dichiarazioni","tag-diplomatico","tag-discussione","tag-discussioni","tag-dmitriev","tag-domenica","tag-donald","tag-donald-trump","tag-europa","tag-europea","tag-europei","tag-financial","tag-financial-times","tag-ginevra","tag-giornalisti","tag-giornata","tag-giusta","tag-guerra","tag-headlines","tag-imboscata","tag-imboscata-interna","tag-inizio","tag-intercontinental","tag-interminabile","tag-interna","tag-it","tag-italia","tag-italy","tag-kiev","tag-lago","tag-marco","tag-marco-rubio","tag-missione","tag-missione-americana","tag-negoziati","tag-negoziati-appesi","tag-negoziati-appesi-capello","tag-news","tag-notizie","tag-notizie-di-cronaca","tag-notizie-principali","tag-notiziedicronaca","tag-notizieprincipali","tag-notte","tag-pace","tag-pare","tag-passo","tag-patto","tag-patto-witkoff","tag-patto-witkoff-dmitriev","tag-piano","tag-piano-punti","tag-pomeriggio","tag-presente","tag-presidente","tag-progressi","tag-punti","tag-rubio","tag-rubio-segretario","tag-rubio-segretario-americano","tag-russi","tag-russia","tag-segnale","tag-segretario","tag-segretario-americano","tag-sicurezza","tag-sostanza","tag-spalle","tag-svolta","tag-titoli","tag-trump","tag-ucraina","tag-ucraini","tag-ultime-notizie","tag-ultime-notizie-di-cronaca","tag-ultime-notizie-e-news-di-oggi","tag-ultimenotizie","tag-ultimenotiziedicronaca","tag-ultimenotizieenewsdioggi","tag-witkoff","tag-witkoff-dmitriev","tag-yermak","tag-zelensky"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/230731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=230731"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/230731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/230732"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=230731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=230731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=230731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}