{"id":237424,"date":"2025-11-29T10:48:11","date_gmt":"2025-11-29T10:48:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/237424\/"},"modified":"2025-11-29T10:48:11","modified_gmt":"2025-11-29T10:48:11","slug":"morbillo-dal-2000-il-vaccino-ha-salvato-quasi-59milioni-di-vite-ma-e-allerta-per-laumento-dei-casi-il-rapporto-oms","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/237424\/","title":{"rendered":"Morbillo, dal 2000 il vaccino ha salvato quasi 59milioni di vite. Ma \u00e8 allerta per l&#8217;aumento dei casi. Il rapporto Oms"},"content":{"rendered":"<p>    di<br \/>\n    Ruggiero Corcella<\/p>\n<p class=\"summary-art is-line-h-12\">Dopo anni di calo, il contagio da morbillo torna a impennarsi nel mondo; in Europa e negli Stati Uniti in particolare si registrano focolai preoccupanti. Vaccino disponibile, ma la soglia di protezione rimane lontana<\/p>\n<p class=\"chapter-paragraph\">Negli ultimi decenni sono stati fatti<b> passi avanti significativi nella riduzione della mortalit\u00e0 <\/b>da <a href=\"https:\/\/www.corriere.it\/salute\/dizionario\/morbillo\/\" rel=\"nofollow noopener\" target=\"_blank\">morbillo<\/a>, ma i casi di contagio stanno risalendo in modo preoccupante. Nei Paesi con coperture vaccinali elevate la malattia da tempo non rappresentava pi\u00f9 una priorit\u00e0 visibile, ma ora torna al centro dell\u2019attenzione. Lo evidenzia il nuovo<b> Rapporto dell&#8217;Organizzazione mondiale della sanit\u00e0<\/b>.\u00a0\u00a0Secondo i dati forniti,\u00a0<b>i decessi per morbillo sono crollati dell\u201988 % dal 2000 al 2024.<\/b> E, tuttavia, <b>nel 2024 il virus ha mietuto ancora circa 95mila vittime, in maggioranza bambini sotto i 5 anni<\/b>. Si tratta del numero pi\u00f9 basso registrato negli ultimi 14 anni, ma che si sarebbe potuto evitare o ridurre semplicemente con la vaccinazione.\u00a0<br \/>Tuttavia, i casi di morbillo stanno crescendo in tutto il mondo, come testimoniano le cronache: sempre nel 2024 si stima un <b>incremento dei casi globali: circa 11 milioni di infezioni,<\/b> quasi 800mila in pi\u00f9\u00a0 rispetto al 2019,\u00a0 ultimo anno pre-pandemia.\u00a0<\/p>\n<p class=\"chapter-paragraph\">\u00abIl morbillo \u00e8 <a href=\"https:\/\/www.corriere.it\/salute\/dizionario\/virus\/\" rel=\"nofollow noopener\" target=\"_blank\">il virus <\/a>pi\u00f9 contagioso al mondo, e questi dati mostrano ancora una volta come sfrutter\u00e0 ogni lacuna nelle nostre difese collettive contro di esso\u00bb, sottolinea <b>Tedros Adhanom Ghebreyesus<\/b>, direttore Generale dell&#8217;OMS. \u00abIl morbillo non rispetta i confini, ma quando ogni bambino in ogni comunit\u00e0 viene vaccinato contro di esso, si possono evitare focolai costosi, salvare vite e questa malattia pu\u00f2 essere eliminata da intere nazioni\u00bb.<br \/>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p>    I numeri<\/p>\n<p class=\"chapter-paragraph\">I casi di morbillo nel 2024 <b>sono aumentati dell&#8217;86% nella Regione Mediterranea Orientale dell&#8217;OMS, del 47% nella Regione Europea e del 42% nella Regione del Sud-Est asiatico rispetto al 2019.<\/b> In particolare, la Regione Africana ha registrato un calo del 40% dei casi e del 50% dei decessi in questo periodo, in parte dovuto all&#8217;aumento della copertura vaccinale.<br \/>Sebbene recenti aumenti di morbillo si verifichino in paesi e regioni dove i bambini hanno meno probabilit\u00e0 di morire grazie a una migliore alimentazione e accesso alle cure sanitarie, <b>gli infetti restano a rischio di gravi complicazioni a vita <\/b>come cecit\u00e0, polmonite ed <a href=\"https:\/\/www.corriere.it\/salute\/dizionario\/encefalite\/\" rel=\"nofollow noopener\" target=\"_blank\">encefalite<\/a> (un&#8217;infezione che causa gonfiore cerebrale e potenzialmente danni cerebrali)<\/p>\n<p>    <b>Coperture vaccinali: troppo lontane dalla soglia critica<\/b><\/p>\n<p class=\"chapter-paragraph\">Il rapporto sottolinea che <b>una copertura efficace richiede almeno il 95 % dei bambini vaccinati con due dosi,<\/b> per fermare la trasmissione e proteggere le comunit\u00e0 dagli focolai. Eppure, i dati globali sono ben al di sotto: nel 2024 l<b>a copertura della prima dose (MCV1) \u00e8 stata l\u201984 %, mentre per la seconda dose (MCV2) la percentuale \u00e8 scesa al 76 %.<\/b><br \/>La situazione nei paesi a basso reddito \u00e8 ancora pi\u00f9 critica: MCV1 al 66 % contro un 94 % nei paesi ad alto reddito.<br \/>Non sorprende quindi che il rapporto stimi<b> oltre 30 milioni di bambini nel 2024 come \u00abnon adeguatamente protetti\u00bb<\/b>. Tre quarti di loro vivono nelle regioni africane e del Mediterraneo orientale, spesso in contesti fragili, colpiti da conflitti o vulnerabili.<\/p>\n<p>    <b>Il \u00abrimbalzo\u00bb post-pandemia e le fragilit\u00e0 emerse<\/b><\/p>\n<p class=\"chapter-paragraph\">La <a href=\"https:\/\/www.corriere.it\/salute\/dizionario\/pandemia\/\" rel=\"nofollow noopener\" target=\"_blank\">pandemia<\/a><b> di Covid-19 <\/b>ha avuto un impatto pesante anche sul controllo del morbillo: <b>campagne vaccinali sospese o ritardate, sorveglianza rallentata, servizi sanitari messi sotto stress.<\/b> Il report evidenzia che nei due anni successivi alla crisi sanitaria globale si \u00e8 ampliata la platea dei suscettibili, favorendo l\u2019accensione di nuovi focolai. <b>Nel 2024 ben 59 Paesi hanno segnalato focolai importanti, un numero quasi tre volte quello del 2021\u00a0<\/b>e il numero pi\u00f9 alto dall&#8217;inizio della pandemia di Covid-19. Tutte le regioni, tranne le Americhe, hanno avuto almeno un paese che ha vissuto un grande focolaio nel 2024. La situazione \u00e8 cambiata nel 2025, con numerosi paesi delle Americhe che hanno combattuto focolai.<\/p>\n<p>    <b>Focolai sul suolo europeo, americano e nel mondo<\/b><\/p>\n<p class=\"chapter-paragraph\">I numeri recenti raccontano una situazione in cui <b>il morbillo torna ad affacciarsi anche nei Paesi che credevano di esser fuori pericolo<\/b>. La Revisione a Medio Termine dell&#8217;Agenda Immunizzazione 2030 (IA2030), sottolinea che il morbillo \u00e8 spesso la prima malattia a ricomparire quando la copertura vaccinale diminuisce. L&#8217;aumento delle epidemie di morbillo sta mettendo in luce le debolezze dei programmi di immunizzazione e dei sistemi sanitari a livello globale, minacciando i progressi verso gli obiettivi IA2030, inclusa l&#8217;eliminazione del morbillo.<\/p>\n<ul>\n<li>In      Europa: la regione Oms Europa ha registrato <b>127.350 casi<\/b> nel 2024,      raddoppiati rispetto al 2023 e al livello pi\u00f9 alto dal 1997<\/li>\n<li>Per      i Paesi UE\/EEA: secondo l\u2019European Centre for Disease Prevention and      Control (ECDC), nel 2024 sono stati notificati <b>35.212 casi<\/b> nel      blocco UE\/EEA, contro 3.973 nel 2023 \u2014 un aumento di circa dieci volte. <\/li>\n<li>Negli      Stati Uniti: al 25 novembre 2025 i Centers for Disease Control and      Prevention (CDC) segnala <b>1.798 casi confermati<\/b> nel 2025, di cui      l\u201987 % associati a 46 focolai.\u00a0 A titolo di confronto, <b>nel 2024<\/b> sono stati segnalati 16 focolai e il 69% dei casi (198 su 285) era associato a un focolaio.<\/li>\n<\/ul>\n<p>    <b>Sorveglianza, laboratori e investimenti in stallo<\/b><\/p>\n<p class=\"chapter-paragraph\">Il rapporto evidenzia anche gli sforzi di sorveglianza: nel 2024, pi\u00f9 di 760 laboratori del <a href=\"https:\/\/www.who.int\/teams\/immunization-vaccines-and-biologicals\/immunization-analysis-and-insights\/surveillance\/surveillance-for-vpds\/laboratory-networks\/measles-and-rubella-laboratory-network\" rel=\"nofollow noreferrer noopener\" target=\"_blank\">Global Measles and Rurosles Laboratory Network<\/a> (GMRLN) <b>hanno analizzato oltre 500mila campioni , un incremento del 27 % rispetto all\u2019anno precedente<\/b>.<br \/>Tuttavia, l\u2019Oms lancia un avvertimento: <b>i tagli ai finanziamenti per campagne vaccinali, sorveglianza e risposta ai focolai <\/b>\u2014 soprattutto nei paesi fragili \u2014 possono erodere rapidamente i successi. Nel documento si specifica che tali riduzioni \u00abpotrebbero ampliare le lacune immunitarie e alimentare nuovi focolai\u00bb.<\/p>\n<p>    <b>L\u2019eliminazione torna un obiettivo in bilico<\/b><\/p>\n<p class=\"chapter-paragraph\">La conquista dell\u2019eliminazione del morbillo \u2014 <b>assenza di trasmissione endemica per almeno 12 mesi <\/b>\u2014 oggi appare messa in discussione. <b>A fine 2024 solo 81 Paesi avevano ottenuto la \u00abcertificazione\u00bb di eliminazione, tre in pi\u00f9 rispetto all\u2019anno precedente<\/b>. Ulteriori progressi sono stati fatti nel 2025 con i paesi e le aree insulari del Pacifico verificati a settembre 2025, e Cabo Verde, Mauritius e Seychelles verificate questo mese, diventando i primi paesi della Regione Africa dell&#8217;Oms ad essere verificati per l&#8217;eliminazione del morbillo. <b>Questo porta il numero totale di paesi che hanno eliminato il morbillo a 96. <\/b><br \/>Ma attenzione: la Regione delle Americhe, che aveva pi\u00f9 volte raggiunto lo status, lo ha perso nel novembre 2025 a causa della trasmissione continua in territori come il Canada. <br \/>L\u2019Oms chiede dunque: <b>\u00abServono investimenti persistenti, campagne di recupero mirate, sorveglianza capillare e risposte rapide ai focolai\u00bb.<\/b> Perch\u00e9 \u00abogni singolo decesso da morbillo \u00e8 inaccettabile\u00bb, recita il rapporto.\u00a0<\/p>\n<p class=\"is-last-update\" datetime=\"2025-11-29T06:55:09+01:00\">29 novembre 2025<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Ruggiero Corcella Dopo anni di calo, il contagio da morbillo torna a impennarsi nel mondo; in Europa&hellip;\n","protected":false},"author":3,"featured_media":237425,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[175],"tags":[839,4197,36715,13336,2109,737,788,4189,391,723,4199,140235,1045,140236,1048,931,372,86813,4185,4247,65304,77776,14335,728,3120,8087,5905,140237,16010,140234,38270,3085,30312,1342,4031,15835,13168,10427,140238,65309,4183,4224,239,19052,14794,5430,1537,90,89,20471,6110,370,3977,140239,7030,1294,1312,4483,140240,810,13812,857,31822,1316,899,111,137,22421,1270,240,786,8881,45720,5583,15839,77762],"class_list":["post-237424","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salute","tag-almeno","tag-alto","tag-americhe","tag-and","tag-attenzione","tag-aumento","tag-bambini","tag-basso","tag-ben","tag-calo","tag-campagne","tag-campagne-vaccinali","tag-casi","tag-casi-morbillo","tag-causa","tag-comunita","tag-contagio","tag-control","tag-copertura","tag-copertura-vaccinale","tag-coperture","tag-coperture-vaccinali","tag-critica","tag-dati","tag-decessi","tag-disease","tag-dose","tag-eea","tag-eliminazione","tag-eliminazione-morbillo","tag-esso","tag-europa","tag-evidenzia","tag-evitare","tag-fatti","tag-focolai","tag-focolaio","tag-for","tag-for-disease","tag-fragili","tag-globale","tag-globali","tag-health","tag-immunizzazione","tag-incremento","tag-investimenti","tag-it","tag-italia","tag-italy","tag-laboratori","tag-livello","tag-malattia","tag-morbillo","tag-morbillo-torna","tag-novembre","tag-numeri","tag-numero","tag-nuovi","tag-nuovi-focolai","tag-oms","tag-orientale","tag-paesi","tag-pandemia","tag-particolare","tag-rapporto","tag-regione","tag-regioni","tag-registrato","tag-rispetto","tag-salute","tag-situazione","tag-sorveglianza","tag-sottolinea","tag-torna","tag-trasmissione","tag-vaccinali"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/237424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=237424"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/237424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/237425"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=237424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=237424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=237424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}