{"id":237644,"date":"2025-11-29T13:54:12","date_gmt":"2025-11-29T13:54:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/237644\/"},"modified":"2025-11-29T13:54:12","modified_gmt":"2025-11-29T13:54:12","slug":"jamm-noa-lang-rapper-sempre-piu-napoletano","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/237644\/","title":{"rendered":"Jamm: Noa Lang, rapper sempre pi\u00f9 napoletano"},"content":{"rendered":"<p>                                Dopo un avvio difficile l&#8217;olandese \u00e8 sempre pi\u00f9 inserito, nella squadra e nella citt\u00e0. Scrive in dialetto, cita Diego, si \u00e8 fatto trovare pronto quando Conte lo ha fatto giocare. E si candida a una maglia da titolare<\/p>\n<p>\n                                                                    Alessandra Vaccaro\n                            <\/p>\n<p>                    29 novembre &#8211; 13:32  &#8211; MILANO<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cJamm\u201d, non \u00e8 il titolo di una sua canzone (magari potrebbe diventarlo), \u00e8 la didascalia dell\u2019ultimo album social di Noa Lang. L\u2019esterno sinistro ha pubblicato su Instagram un paio di foto tratte dalla partita di Champions giocata contro il Qarabag allo stadio Diego Armando Maradona. La sua seconda consecutiva da titolare, un\u2019altra prestazione estremamente positiva, da trequartista nell\u2019inedito 3-4-2-1, accanto a Neres e alle spalle di Hojlund. Un\u2019immagine dalla bandierina e una col cielo stellato e in tempesta alle spalle, in sottofondo le note della canzone di Geolier El Pibe de Oro. Noa ha mandato un messaggio ai tifosi del Napoli e ai follower con l\u2019esortazione napoletana per eccellenza. \u201cJamm\u201d significa \u201cAndiamo\u201d, significa unione, significa sentirsi napoletano, significa combattere insieme per un obiettivo.\u00a0<\/p>\n<p>    omaggio a diego\u2014 \u00a0<\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Non solo giocatore, Noa Lang, in arte Noano \u00e8 anche un famoso rapper, con i brani \u201cDamage\u201d e \u201cWaka\u201d ha superato i 20 milioni di visualizzazioni per ogni singolo. Giocatore dribblomane e anche cantante, \u00e8 la sublimazione della napoletanit\u00e0. Si pu\u00f2 dire, senza timore di smentita, che Noa Lang sia diventato prima napoletano che titolare. Quando ancora non aveva firmato il contratto quinquennale, che lo legher\u00e0 al Napoli fino al 2030, Noa ha pubblicato sui social un album di foto delle vacanze dal titolo \u201cLive is life\u201d, il brano che ha accompagnato il riscaldamento pi\u00f9 famoso della storia del calcio, quello di Diego Armando Maradona prima della semifinale di Coppa Uefa contro il Bayern Monaco, era il 19 aprile 1989. \u201cVedi Napoli e poi muori\u201d, un altro titolo pesante, un altro titolo napoletano. Quello scelto per l\u2019album postato su Instagram dopo la firma del contratto. Il 18 luglio scorso, dal ritiro di Dimaro, ha condiviso le emozioni delle prime ore in azzurro. L\u2019allenamento, l\u2019arrivo in charter, i primi giorni trascorsi in uno degli hotel con la vista pi\u00f9 suggestiva sulla citt\u00e0, il golfo di Napoli, le chiacchierate con De Bruyne e Lukaku, l\u2019incontro con Geolier e poi lo stadio Diego Armando Maradona.\u00a0<\/p>\n<p>    eredit\u00e0 e parole pesanti\u2014 \u00a0<\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Arrivato a Napoli dal Psv Eindhoven per 25 milioni pi\u00f9 3 di bonus, Noa si \u00e8 ritrovato nell\u2019ingrato compito di dover raccogliere l\u2019eredit\u00e0 di Khvicha Kvaratskhelia. Lang era un obiettivo concreto del mercato azzurro gi\u00e0 nella sessione invernale scorsa, acquisto condiviso dal direttore sportivo Giovanni Manna e da Antonio Conte. \u201cSono consapevole che c&#8217;\u00e8 da curare anche la fase difensiva nel calcio italiano rispetto al gioco olandese\u201d, aveva detto alla sua presentazione in conferenza stampa. E, forse, \u00e8 stato proprio questo il maggiore limite all\u2019inizio della sua esperienza a Napoli. La prima maglia da titolare \u00e8 arrivata contro il Lecce, il 28 ottobre scorso, solo 50 minuti giocati e poi il cambio per un doppio colpo. Nel frattempo, per\u00f2, \u00e8 successo di tutto: la sconfitta per 6-2 contro il Psv (la sua ex squadra), le dichiarazioni di Noa dalla sua roccaforte \u201cHo parlato solo una volta con Conte\u201d, le parole del ct dell\u2019Olanda sullo scarso minutaggio in azzurro di Lang \u201cMi ha raccontato che in 28 giorni di ritiro ha visto solo una volta il pallone\u201d e la risposta di Antonio Conte \u201cDeve lavorare, decider\u00f2 io quando mandarlo in campo\u201d. Insomma, Noa Lang ha vissuto un avvio delicato in azzurro, completamente integrato nell\u2019ambiente Napoli, ma slegato dal progetto tattico di Conte. Poi la necessit\u00e0 di passare al 3-4-2-1 per sopperire alle pesanti assenze di Anguissa, Lukaku, De Bruyne, Gilmour, tutti insieme in infermeria. In campo dal primo minuto con l\u2019Atalanta (ha segnato il primo gol in azzurro), riconfermato col Qarabag, Noa si candida a strappare una maglia da titolare anche all\u2019Olimpico. Del resto ha gi\u00e0 avvertito tutti dai social in napoletano: Jamm, vale anche contro la Roma, nel suggestivo derby del Sud.<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"Dopo un avvio difficile l&#8217;olandese \u00e8 sempre pi\u00f9 inserito, nella squadra e nella citt\u00e0. Scrive in dialetto, cita&hellip;\n","protected":false},"author":3,"featured_media":237645,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1443],"tags":[8133,119,11807,91130,118544,3732,7920,4701,721,921,52266,8115,10900,2790,6693,277,4702,8250,118547,102438,203,10899,5480,228,9630,564,230,204,1537,90,89,140386,4705,31345,2219,69396,11997,1538,1539,3603,248,95875,104332,809,6049,4979,29899,55934,6148,46985,10334,1686,26462],"class_list":{"0":"post-237644","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musica","8":"tag-album","9":"tag-antonio","10":"tag-antonio-conte","11":"tag-armando","12":"tag-armando-maradona","13":"tag-avvio","14":"tag-azzurro","15":"tag-bruyne","16":"tag-calcio","17":"tag-campo","18":"tag-candida","19":"tag-canzone","20":"tag-condiviso","21":"tag-conte","22":"tag-contratto","23":"tag-de","24":"tag-de-bruyne","25":"tag-diego","26":"tag-diego-armando","27":"tag-diego-armando-maradona","28":"tag-entertainment","29":"tag-eredita","30":"tag-famoso","31":"tag-foto","32":"tag-geolier","33":"tag-giocatore","34":"tag-instagram","35":"tag-intrattenimento","36":"tag-it","37":"tag-italia","38":"tag-italy","39":"tag-jamm","40":"tag-lang","41":"tag-lukaku","42":"tag-maglia","43":"tag-maglia-titolare","44":"tag-maradona","45":"tag-music","46":"tag-musica","47":"tag-napoletano","48":"tag-napoli","49":"tag-noa","50":"tag-noa-lang","51":"tag-obiettivo","52":"tag-olandese","53":"tag-parole","54":"tag-pesanti","55":"tag-psv","56":"tag-pubblicato","57":"tag-qarabag","58":"tag-significa","59":"tag-social","60":"tag-titolare"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/237644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=237644"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/237644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/237645"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=237644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=237644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=237644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}