{"id":243568,"date":"2025-12-03T12:51:10","date_gmt":"2025-12-03T12:51:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/243568\/"},"modified":"2025-12-03T12:51:10","modified_gmt":"2025-12-03T12:51:10","slug":"maria-de-filippi-in-lacrime-a-belve-vorrei-riportare-in-vita-maurizio-costanzo-per-chiedergli-se-ha-sofferto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/243568\/","title":{"rendered":"Maria De Filippi in lacrime a &#8220;Belve&#8221;: \u00abVorrei riportare in vita Maurizio Costanzo per chiedergli se ha sofferto\u00bb"},"content":{"rendered":"<p>    di<br \/>\n    Simona Marchetti<\/p>\n<p class=\"summary-art is-line-h-12\">Per l&#8217;ultima puntata della trasmissione la conduttrice Mediaset ha accettato di rispondere ad alcune domande di Francesca Fagnani, mostrando un lato inedito di s\u00e9 e commuovendosi parlando del marito e dei genitori<\/p>\n<p class=\"chapter-paragraph\">Un\u2019intervista breve, ma intensa, che ha mostrato un lato inedito e inaspettato di <b>Maria De Filippi,<\/b> che <b>marted\u00ec 2 dicembre<\/b> ha accettato di sedersi sullo sgabello pi\u00f9 scomodo della televisione <a href=\"https:\/\/www.raiplay.it\/video\/2025\/12\/Maria-De-Filippi---Belve-02122025-b09daacf-ab7c-4f1f-8f58-e3c07dd9af87.html\" rel=\"nofollow noreferrer noopener\" target=\"_blank\">per farsi fare \u00abqualche domanda\u00bb<\/a> da <b>Francesca<\/b> <b>Fagnani<\/b> nell\u2019ultima puntata stagionale di \u201c<b>Belve<\/b>\u201d su <b>Rai2<\/b>. \u00ab<b>Che belva si sente?<\/b>\u00bb, le ha chiesto la conduttrice, partendo da quello che \u00e8 da sempre l\u2019incipit della trasmissione. \u00abIo la seguo e ho visto tanti che a questa domanda pensavano \u201cdico quello, dico quell\u2019altro\u201d. Io le rispondo: <b>mi sento Maria De Filippi<\/b>\u00bb, ha detto la signora della tv, con la schiettezza che da sempre la contraddistingue. Non poteva ovviamente mancare la domanda sulla \u00ab<b>belvata che rivendica o di cui si pente<\/b>\u00bb e \tqui <b>Maria<\/b> ha ricordato un divertente aneddoto della sua adolescenza.\u00a0<\/p>\n<p class=\"chapter-paragraph\">\u00ab<b>Ho rubato l\u2019argenteria in casa mia<\/b> &#8211; ha risposto infatti la conduttrice, scatenando l\u2019ilarit\u00e0 della <b>Fagnani<\/b> &#8211; . Prendevo le multe con la <b>Vespa 50<\/b> e i miei erano gi\u00e0 arrabbiati per questo, cos\u00ec mi misi d\u2019accordo con il portiere, si chiamava <b>Emilio<\/b>, e lui metteva da parte le multe e non le consegnava insieme alla posta a mia madre. Quando per\u00f2 <b>queste multe sono diventate tante<\/b>, non sapendo come pagarle perch\u00e9 mio padre mi dava una paghetta settimanale molto bassa, <b>presi dei pezzi di argenteria, andai da un gioielliere lontano da casa, glieli vendetti e con quei soldi pagai le multe<\/b>\u00bb.\u00a0    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\"><b>Ma qualcosa and\u00f2 storto<\/b>. \u00abSuccesse che uno di quei pezzi di argenteria era un piccolo lingotto d\u2019argento con scritto \u201c<b>1000 Miglia&#8221;<\/b>, mio padre era un appassionato di auto d\u2019epoca e quello l\u2019aveva vinto facendo la &#8220;<b>1000 Miglia<\/b>\u201d, quindi ci teneva tanto &#8211; ha proseguito <b>De Filippi<\/b> nel racconto &#8211; . Io ho un fratello pi\u00f9 grande e all\u2019inizio venne accusato lui. Io sono stata in silenzio per un po\u2019, poi ho detto \u201c<b>sono stata io<\/b>\u201d. A quel punto venni presa, caricata in macchina, dovetti confessare anche la gioielleria dove avevo venduto i pezzi, mio padre mi port\u00f2 l\u00ec, entrai con lui dietro, dovetti ammettere che avevo rubato\u2026 <b>Me lo ricorder\u00f2 finch\u00e9 campo\u2026 una figura di m\u2026.<\/b>\u00bb.\u00a0<\/p>\n<p class=\"chapter-paragraph\">La leggerezza che aveva sin qui caratterizzato l\u2019intervista \u00e8 stata per\u00f2 spazzata via quando <b>Fagnani<\/b> ha posto alla sua ospite <b>la tradizionale domanda su chi vorrebbe riportare in vita, anche solo per due minuti e cosa gli o le chiederebbe<\/b>. \u00abPosso uscire dalla regola?\u00bb, ha chiesto <b>De Filippi<\/b> che, una volta ricevuto il consenso dalla conduttrice, ha ripreso a parlare, con <b>la voce gi\u00e0 rotta dal pianto<\/b> e gli occhi che si facevano sempre pi\u00f9 lucidi. \u00abIo <b>ne riporterei in vita tre\u2026<\/b> <b>mio padre<\/b> (cavolo che fatica) e gli direi che \u00e8 andato via troppo presto; <b>mia madre<\/b>, a cui direi un sacco di cose, tipo che ripensando a tante cose che lei ha fatto e di cui a volte io mi sono lamentata, col senno di poi\u2026. (cavolo\u2026) ne ho capito il perch\u00e9, ho capito tanti perch\u00e9 dei suoi comportamenti che prima pensavo fossero sbagliati e ho capito che invece mi sono serviti e poi <b>Maurizio<\/b> e qui faccio ancora pi\u00f9 fatica che i due sommati\u2026\u00bb, ha spiegato <b>Maria<\/b>, prima di proseguire nel ricordo del marito, <b>scomparso il 24 febbraio 2023<\/b>.\u00a0<\/p>\n<p class=\"chapter-paragraph\">\u00abPenso di aver fatto sempre in modo che lui non soffrisse, <b>parlo di dolore fisico<\/b>, per\u00f2 non so se lui all\u2019ultimo momento ha sofferto, quindi gli chiederei questo\u00bb, ha ammesso <b>De Filippi<\/b> faticando a trattenere le lacrime. \u00abCon la sua presenza, sicuramente sar\u00e0 stata una sofferenza di altro tipo, con l&#8217;amore accanto\u00bb, ha commentato a quel punto <b>Fagnani<\/b>, ringraziando la conduttrice <b>Mediaset<\/b> \u00abper il regalo immenso\u00bb fatto a lei e al programma. \u00ab<b>Mi ha fatto davvero piacere<\/b>\u00bb, ha risposto <b>Maria<\/b>, alzandosi dal suo sgabello per abbracciare la giornalista. \u00ab<b>Cerca di camminare guardando per terra, bisogna sempre camminare guardando per terra<\/b>\u00bb, ha concluso <b>De Filippi <\/b>con la voce sempre pi\u00f9 arrochita dal pianto, mentre lo studio le tributava <b>un applauso degno di una regina della televisione<\/b>.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-12-03T12:50:29+01:00\">3 dicembre 2025 ( modifica il 3 dicembre 2025 | 12:50)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Simona Marchetti Per l&#8217;ultima puntata della trasmissione la conduttrice Mediaset ha accettato di rispondere ad alcune domande&hellip;\n","protected":false},"author":3,"featured_media":243569,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1451],"tags":[8398,143875,19486,5776,143876,143877,3079,5217,1621,1620,1061,1396,113611,122,277,9304,3876,6103,2341,143878,203,98020,2882,9307,5701,19487,5230,143879,45884,1282,204,1537,90,89,20142,4045,1259,6992,5602,7242,16491,9060,6172,20414,3608,14332,143880,7248,8202,494,1918],"class_list":["post-243568","post","type-post","status-publish","format-standard","has-post-thumbnail","category-celebrita","tag-accettato","tag-argenteria","tag-belve","tag-camminare","tag-camminare-guardando","tag-camminare-guardando-terra","tag-capito","tag-cavolo","tag-celebrita","tag-celebrities","tag-chiesto","tag-conduttrice","tag-conduttrice-mediaset","tag-cose","tag-de","tag-de-filippi","tag-dico","tag-direi","tag-domanda","tag-dovetti","tag-entertainment","tag-fagnani","tag-fatica","tag-filippi","tag-francesca","tag-francesca-fagnani","tag-guardando","tag-guardando-terra","tag-inedito","tag-intervista","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-lacrime","tag-madre","tag-maria","tag-maria-de","tag-maria-de-filippi","tag-marito","tag-maurizio","tag-mediaset","tag-miglia","tag-multe","tag-padre","tag-pezzi","tag-pezzi-argenteria","tag-pianto","tag-puntata","tag-punto","tag-quei"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/243568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=243568"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/243568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/243569"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=243568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=243568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=243568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}