{"id":248984,"date":"2025-12-07T00:28:22","date_gmt":"2025-12-07T00:28:22","guid":{"rendered":"https:\/\/www.europesays.com\/it\/248984\/"},"modified":"2025-12-07T00:28:22","modified_gmt":"2025-12-07T00:28:22","slug":"aldo-giovanni-e-giacomo-recensione-documentario","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/248984\/","title":{"rendered":"Aldo, Giovanni e Giacomo: recensione documentario"},"content":{"rendered":"<p>                              <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/12\/attitudini-nessuna-documentario-aldo-giovanni-e-giacomo-inter.jpg\" loading=\"lazy\" alt=\"attitudini nessuna aldo giovanni e giacomo\" width=\"1280\" height=\"800\"\/><\/p>\n<p class=\"img-caption\"> \u00c8 nei cinema Attitudini: nessuna, il documentario su Aldo, Giovanni e Giacomo. Il trio in una delle immagini di repertorio che vediamo nel film.<\/p>\n<p>\n                              <strong>LA VITA, FUORI E DENTRO AI SET E I PALCOSCENICI,<\/strong> l&#8217;umorismo candido e geniale, l\u2019amicizia di <strong>Aldo, Giovanni e Giacomo<\/strong> tornano sullo schermo in <strong>Attitudini: nessuna<\/strong> (ora nelle sale per Medusa). Il documentario di Sophie Chiarello \u00e8 un ritratto divertente e agrodolce del celebre trio comico. Da vedere al cinema.\n                          <\/p>\n<p>\n                              Milano. Aldo Baglio, Giovanni Storti e Giacomo Poretti si raccontano &#8211; in modo schietto e senza filtri &#8211; alla <strong>regista Sophie Chiarello (autrice de Il cerchio ed ex assistente di Massimo Venier, regista \u201cstorico\u201d dei film di AG&amp;G)<\/strong>. Dall\u2019infanzia nelle case di ringhiera e l\u2019oratorio fino al successo, dai palcoscenici teatrali alla tv (Il circo di Paolo Rossi, Zelig, Mai dire gol) e al cinema. Il film si compone di <strong>interviste (al trio, alla Gialappa, a Marina Massironi, Gino e Michele\u2026), di gag, frammenti di film, tv e teatro<\/strong>. Genesi, vita e arte della risata del trio.\n                          <\/p>\n<p>                              <img decoding=\"async\" src=\"https:\/\/images2-wpc.corriereobjects.it\/EL75Ir9lkoxhhmzknxkN5Q56qQI=\/fit-in\/2560x1718\/style.corriere.it\/assets\/uploads\/2025\/12\/9-AGG-San-Siro-Naviglio__\u00a9Laila-Pozzo-3191-scaled.jpg?v=599227\" loading=\"lazy\" alt=\"attitudini nessuna aldo giovanni e giacomo\" width=\"2560\" height=\"1718\"\/><\/p>\n<p class=\"img-caption\"> Aldo, Giovanni e Giacomo a San Siro in una scena di Attitudini: nessuna. Foto Laila Pozzo\/Ufficio stampa<\/p>\n<p>\n                              \u00abHo girato i tarocchi, mi hanno letto la vita\/L\u2019ho guardata negli occhi, ma non l\u2019ho capita\u2026\u00bb. Canta Brunori Sas nel pezzo che \u00e8 ispirato a una poesia di Aldo Baglio e d\u00e0 il titolo al film su Aldo, Giovanni e Giacomo. Ovvero Attitudini: nessuna. <strong>Cosa significa il titolo? Viene dalla pagella di Aldo&#8230;\u00a0<\/strong>\n                          <\/p>\n<p>\n                              Il documentario di Sophie Chiarello non ha la pretesa di svelare i segreti della comicit\u00e0 del trio. Parafrasando Brunori: la sua magia pare indecifrabile come la vita. Eppure, <strong>sa unire frammenti di pubblico e privato come in un grande puzzle<\/strong> di tre personalit\u00e0 difformi e al contempo magnificamente complementari.\u00ab<strong>Siamo tre clown, ma insieme diventiamo uno solo\u2026\u00bb, dicono.<\/strong>\n                          <\/p>\n<p>\n                              La vita, l\u2019arte comica, la Milano migliore che oggi sembra scomparire. E invece &#8211; da qualche parte &#8211; c\u2019\u00e8 ancora\u2026 Strepitosa la sequenza in cui Giovanni Storti racconta la commozione che prova ogni volta che riascolta Per un bas\u00edn di Enzo Jannacci, evocando \u00abun mondo ingenuo\u2026 che forse non c\u2019\u00e8 pi\u00f9\u00bb.\n                          <\/p>\n<p>\n                              Se siete fan di Aldo, Giovanni e Giacomo non perdete il documentario Attitudini: nessuna. Tra <strong>risate, sketch memorabili, amicizia, nostalgia e \u201ctafazzismi\u201d, una fotografia bizzarra e appassionante<\/strong> della vis comica e dell\u2019amore (ricambiato) per il pubblico.\n                          <\/p>\n<p>\n                              Infine un piccolo test: se scriviamo \u00abMa fuori dal letto?\u00bb, rispondete \u00abnessuno \u00e8 perfetto!\u00bb? Allora questo \u00e8 il film per voi. Se invece rispondete \u00abnessuna piet\u00e0!\u00bb&#8230; anche!\n                          <\/p>\n<p>                              <img decoding=\"async\" src=\"https:\/\/images2-wpc.corriereobjects.it\/KFKgBIgb7_spI8VoAyyFQAw-Mo8=\/fit-in\/2560x1543\/style.corriere.it\/assets\/uploads\/2025\/12\/6-AGG-e-Sophie-Chiarello__\u00a9Laila-Pozzo-0060-copia-scaled.jpg?v=599239\" loading=\"lazy\" alt=\"Attitudini: nessuna, ovvero ridere fino alle lacrime con Aldo, Giovanni e Giacomo- immagine 5\" width=\"2560\" height=\"1543\"\/><\/p>\n<p class=\"img-caption\"> Con la regista durante una pausa sul set<\/p>\n<p>\n                              Da vedere o rivedere <strong>Tre uomini e una gamba<\/strong> (1997, Netflix, Amazon Prime Video, Infinity+), <strong>Cos\u00ec \u00e8 la vita<\/strong> (1998, Amazon Prime Video, Infinity+, TIMVision). <strong>Chiedimi se sono felice <\/strong>(2000, Netflix, Amazon Prime Video, TIMVision, Infinity+), <strong>La leggenda di Al, John e Jack <\/strong>(2002, Netflix, Amazon Prime Video, Infinity+) e <strong>Tu la conosci, Claudia?<\/strong> (2004, Netflix, Amazon Prime Video, Infinity+). Da recuperare inoltre <strong>Anplagghed al cinema <\/strong>(2006, disponibile in Dvd pi\u00f9 libro Rizzoli), <strong>La banda dei Babbi Natale <\/strong>(2010, Sky Cinema, NOW, Amazon Prime Video, Infinity+, Rakuten Tv), <strong>Ammutta muddica al cinema<\/strong> (2013, in Dvd Mustang). <strong>Odio l\u2019estate<\/strong> (2020, Apple Tv, Netflix, Amazon Prime Video, Infinity+, TIMVision, Rakuten Tv) e <strong>Tutti gli uomini del deficiente<\/strong> (1999, Disney+, Amazon Prime Video, Infinity+). Infine si vedano anche la serie tv documentaria <strong>Jannacci &#8211; L\u2019importante \u00e8 esagerare<\/strong> di Ranuccio Sodi e Riccardo Piferi (1991, RaiPlay) e <strong>C\u2019era una volta il Derby Club<\/strong> di Marco Spagnoli (2024, RaiPlay).\n                          <\/p>\n","protected":false},"excerpt":{"rendered":"\u00c8 nei cinema Attitudini: nessuna, il documentario su Aldo, Giovanni e Giacomo. Il trio in una delle immagini&hellip;\n","protected":false},"author":3,"featured_media":248985,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1442],"tags":[146850,9639,104396,128107,44511,7072,7073,6762,11166,1615,128115,146847,146848,146851,146852,146853,146854,146855,146856,110729,83995,2389,143672,146857,146858,640,146859,50655,126839,12548,146860,146861,5464,41712,146862,11599,146843,146844,146863,146864,79259,203,454,5500,2759,128108,16276,204,1537,90,89,1521,3166,146845,146846,4425,12341,146841,10840,146849,635,102004,143676,14724,102737,253,2392,146842],"class_list":["post-248984","post","type-post","status-publish","format-standard","has-post-thumbnail","category-film","tag-agrodolce","tag-aldo","tag-aldo-baglio","tag-aldo-giovanni","tag-aldo-giovanni-giacomo","tag-amazon","tag-amazon-prime","tag-amazon-prime-video","tag-amicizia","tag-arte","tag-attitudini","tag-attitudini-documentario","tag-attitudini-documentario-aldo","tag-attitudini-film","tag-attitudini-film-guardare","tag-attitudini-sophie","tag-attitudini-sophie-chiarello","tag-attitudini-trailer","tag-attitudini-trailer-italiano","tag-baglio","tag-brunori","tag-cast","tag-chiarello","tag-chiarello-trama","tag-chiarello-trama-cast","tag-cinema","tag-cinema-attitudini","tag-clown","tag-comica","tag-comicita","tag-comicita-pura","tag-comicita-pura-trio","tag-comico","tag-divertente","tag-divertente-agrodolce","tag-documentario","tag-documentario-aldo","tag-documentario-aldo-giovanni","tag-documentario-sophie","tag-documentario-sophie-chiarello","tag-dvd","tag-entertainment","tag-film","tag-giacomo","tag-giovanni","tag-giovanni-giacomo","tag-infinity","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-movies","tag-netflix","tag-netflix-amazon","tag-netflix-amazon-prime","tag-prime","tag-prime-video","tag-prime-video-infinity","tag-recensione","tag-recensione-attitudini","tag-regista","tag-sophie","tag-sophie-chiarello","tag-timvision","tag-trio","tag-tv","tag-video","tag-video-infinity"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/248984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=248984"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/248984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/248985"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=248984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=248984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=248984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}