{"id":249455,"date":"2025-12-07T09:05:15","date_gmt":"2025-12-07T09:05:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/249455\/"},"modified":"2025-12-07T09:05:15","modified_gmt":"2025-12-07T09:05:15","slug":"il-vincitore-di-tu-si-que-vales-e-kay-la-ferrera-mago-bambino-di-dieci-anni-vince-centomila-euro","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/249455\/","title":{"rendered":"Il vincitore di Tu si que vales \u00e8 Kay La Ferrera: mago-bambino di dieci anni, vince centomila euro"},"content":{"rendered":"<p>    di<br \/>\n    Redazione Spettacoli<\/p>\n<p class=\"summary-art is-line-h-12\">Il piccolo concorrente del programma di De Filippi non ha potuto assistere alla proclamazione visto l&#8217;ora tarda, al suo posto la madre con un suo cartonato<\/p>\n<p class=\"chapter-paragraph\">Kay La Ferrera, <b>un mago di dieci anni, ha vinto l&#8217;ultima edizione, la dodicesima, di \u00abTu s\u00ec que vales\u00bb<\/b>. Il prestigiatore-bambino \u00e8 di Roma e si \u00e8 aggiudicato il <b>montepremi da 100mila euro.\u00a0<\/b>\u00a0I suoi numeri di magia non solo hanno conquistato la giuria del programma di Canale 5: Maria De Filippi, Paolo Bonolis, Rudy Zerbi e Luciana Littizzetto. La Ferrara ha convinto anche il pubblico da casa rappresentato da Sabrina Ferilli, premiato dal 38,68% delle preferenze. Numeri che lo hanno imposto <b>sugli altri quindici finalisti in gara<\/b>, anche se purtroppo il giovane mago non potesse essere presente al momento della proclamazione, avvenuta dopo l&#8217;una di notte: essendo minorenne, <b>la madre ha ritirato il premio al suo posto<\/b>.<\/p>\n<p class=\"chapter-paragraph\">Nel raccontare la sua esperienza, durante la trasmissione, aveva detto:\u00a0\u00abDa grande voglio fare il mago, mi \u00e8 nata questa passione quando ero al compleanno di mio cugino e mio zio ha fatto alcune cose di magia, cosi mi sono incuriosito e ho provato a fare magia\u00bb. Nel commentare l&#8217;ipotetica vittoria, aveva detto che avrebbe usato il montepremi\u00a0\u00abper ripagare la mia famiglia di tutti i sacrifici che ha fatto per me\u00bb    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"is-last-update\" datetime=\"2025-12-07T09:16:21+01:00\">7 dicembre 2025 ( modifica il 7 dicembre 2025 | 09:16)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Redazione Spettacoli Il piccolo concorrente del programma di De Filippi non ha potuto assistere alla proclamazione visto&hellip;\n","protected":false},"author":3,"featured_media":249456,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1444],"tags":[694,277,9304,5316,203,724,90007,147108,9307,204,1537,90,89,91938,147109,147110,4045,21595,59376,253],"class_list":{"0":"post-249455","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-bambino","9":"tag-de","10":"tag-de-filippi","11":"tag-dieci","12":"tag-entertainment","13":"tag-euro","14":"tag-ferrera","15":"tag-ferrera-mago","16":"tag-filippi","17":"tag-intrattenimento","18":"tag-it","19":"tag-italia","20":"tag-italy","21":"tag-kay","22":"tag-kay-ferrera","23":"tag-kay-ferrera-mago","24":"tag-madre","25":"tag-magia","26":"tag-mago","27":"tag-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115677490413279141","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/249455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=249455"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/249455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/249456"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=249455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=249455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=249455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}