{"id":262222,"date":"2025-12-15T18:30:14","date_gmt":"2025-12-15T18:30:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/262222\/"},"modified":"2025-12-15T18:30:14","modified_gmt":"2025-12-15T18:30:14","slug":"se-chiami-i-carabinieri-sei-morto-picchiavano-e-rapinavano-coetanei-e-anche-un-disabile-arrestati-otto-ragazzi-bresciani","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/262222\/","title":{"rendered":"\u00abSe chiami i Carabinieri sei morto\u00bb: picchiavano e rapinavano coetanei e anche un disabile, arrestati otto ragazzi bresciani"},"content":{"rendered":"<p>    di<br \/>\n    Mara Rodella<\/p>\n<p class=\"summary-art is-line-h-12\">Impavidi, violenti, sempre \u00abin branco\u00bb: si firmavano \u00ab069\u00bb, come le ultime tre cifre del CAP di Villa Carcina, il comune dove hanno iniziato le loro azioni. Usavano cocci, cinture, avevano anche una pistola con la quale minacciavano i ragazzi.<\/p>\n<p class=\"chapter-paragraph\">Nell\u2019estate 2023, dopo gli  insulti, gli schiaffi, i pugni e una testata, <b>l\u2019hanno lasciato scalzo, per strada, a Sarezzo (Brescia). Volevano le sue Nike<\/b>. L\u2019hanno minacciato e molestato al punto \u00abda cagionargli un grave stato di ansia, tale da necessitare l\u2019accesso al pronto soccorso e una terapia farmacologica ansiolitica, e ingenerare il fondato timore per la propria incolumit\u00e0 fisica e determinare un cambiamento delle sue abitudini, riducendo le uscite da casa\u00bb. Eccoli nei pressi delle medie, dell\u2019oratorio, in paese, o nel vicolo appartato: \u00ab<b>Non devi parlare con nessuno altrimenti le prendi di nuovo<\/b>\u00bb. Il settembre successivo, primo giorno di scuola, hanno minacciato anche sua madre, davanti al cancello (\u00abDai picchialo, fallo uscire\u00bb, \u00abVieni fuori se hai coraggio, che ce la risolviamo\u00bb urlavano), mostrandole un coltello nascosto nei jeans: \u00abStai tranquilla che se picchiamo tuo figlio, prima di tutto finisce lui nei guai facendo judo\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Impavidi, violenti, sempre \u00abin branco\u00bb: si firmavano \u00ab069\u00bb, come le ultime tre cifre del CAP di Villa Carcina.<\/b> Sono entrati in azione proprio l\u00ec, oltre che a <b>Concesio e a Sarezzo<\/b> \u2014  dove vivono, per lo pi\u00f9 \u2014  tra settembre 2022 e marzo 2025.  Ora con un pugnale in tasca, o una pistola da soft air o ancora un tirapugni, un cacciavite. Aggredivano ragazzini \u2014 minorenni \u2014 per strada, vicino ai locali, sul pullman. Per rapinarli di soldi \u2014 o estorcerli \u2014  smartphone, carte prepagate, abiti firmati, zaino. Picchiavano senza piet\u00e0. <b>L\u2019hanno fatto anche con un giovane disabile, affetto da schizofrenia e invalido all\u201980%<\/b>, la sera del 7 aprile 2024,  in piazza a Concesio: prima lo hanno falsamente accusato di aver \u00abfatto sparire\u00bb una bottiglia di superalcolico in un locale, poi \u2014 nonostante la vittima, impaurita, ne avesse comprata loro una \u2014 lo hanno trascinato in un vicolo aggredendolo con i cocci e la fibbia di una cintura.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">\u00abDai, scendi che dobbiamo parlare\u00bb, hanno detto a un coetaneo, sul pullman, salvo poi  prendergli lo zaino e costringerlo a inseguirli: \u00abSe lo rivuoi devi darci trecento euro\u00bb. L\u2019hanno obbligato ad andare al bancomat e prelevare, il massimo possibile, 180 euro. E \u00abadesso devi fare il bravo. Fai il bravo\u00bb.\u00a0\u00ab<b>Se chiami i carabinieri sei morto, sappiamo chi sei<\/b>\u00bb si \u00e8 sentito dire un altro ragazzino, avvicinato  con apparente fare amichevole al McDonald di Concesio: la gang voleva il suo telefono. Ma \u00e8 riuscito a chiedere aiuto nel negozio nonostante le minacce. \u00abNon dirlo a nessuno, altrimenti ti meno\u00bb, lo dicevano spesso. Anche quando, sprezzanti, si presentavano \u00abin una ventina\u00bb sotto casa del prescelto non curanti dei genitori affacciati sui balconi: minacciavano pure loro.<\/p>\n<p class=\"chapter-paragraph\">Agli atti dell\u2019inchiesta  \u2014 coordinata dai carabinieri, che incrocia diversi filoni \u2014 <b>i  pestaggi con la  cintura, le aggressioni, le intimidazioni, gli sfregi al viso, le rapine, lo spray urticante a chi si opponeva<\/b>. O la pistola, puntata contro un ragazzino gi\u00e0 legato  con le mani dietro la schiena con le  fascette da elettricista. Oltre ai video delle aggressioni postati sui social. <br \/><b>Nel gennaio di un anno fa  alla gang \u00e8 attribuito il danneggiamento del sagrato della chiesa dei Santi Emiliano e Tirso con la  scritta \u00abVilla Carcina 069 al comando<\/b>\u00bb;  fuori dalla scuola del paese, invece, con la bomboletta era stato impresso un messaggio contro la preside. Capitava anche con i coetanei finiti nel mirino: li denigravano con l\u2019inchiostro, senza risparmiare i familiari. Su disposizione del gip del Tribunale dei minori, Mariateresa Canzi, in manette sono finiti otto ragazzini \u2014 italiani e di origine straniera \u2014  tutti minorenni all\u2019epoca dei fatti contestati. In  comunit\u00e0  un 17enne di  Lumezzane, un 19enne residente a  Villa Carcina e un 18enne di Concesio. Obbligo di permanenza in casa, invece, per  un 17enne, un 18enne e un 19 enne di Villa Carcina; per un 17enne di casa in citt\u00e0 e un  18enne di Concesio.<\/p>\n<p class=\"chapter-paragraph\">Per gli inquirenti, \u00able indagini hanno consentito di individuare un nutrito e coeso gruppo di minori, dediti alla commissione di reati predatori e contro la persona, perpetrati con efferata violenza, armi e modalit\u00e0 intimidatorie e di sopraffazione tali da incutere timore nei pari, imponendosi nel territorio come baby gang\u00bb. <b>Il pubblico ministero  aveva chiesto il carcere per nove,  25 in tutto gli indagati: 17 sono stati perquisiti, hanno tra i 15 e i 20 anni<\/b> (tre i minori). Per il giudice, alcuni ragazzi, recidivi negli ultimi mesi, hanno dimostrato  \u00abpersonalit\u00e0 dedite alla commissione dei reati, particolarmente gravi, come una sorta di \u201cabitudine\u201d, verosimilmente anche per il  contesto socio-ambientale in cui sono inseriti\u00bb.\u00a0Nel settembre 2024 erano  state eseguite sette misure cautelari a carico di altrettanti maggiorenni del gruppo, gi\u00e0 condannati a pene tra i due e gli otto anni.<\/p>\n<p class=\"is-mr-t-20 is-mr-b-20\"><b><br \/>\n                    <a href=\"https:\/\/brescia.corriere.it\/?intcmp=Notizielocali_nd_010623_corriere_ss_brescia\" target=\"_blank\" rel=\"nofollow noopener\">Vai a tutte le notizie di Brescia<\/a><br \/>\n            <\/b><\/p>\n<p class=\"chapter-paragraph\"><b><a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=62&amp;intcmp=NL-artic_nd_050624_corriere_ss_brescia\" target=\"_blank\" rel=\"nofollow noopener\">Iscriviti alla newsletter di Corriere Brescia<\/a><\/b><\/p>\n<p class=\"is-last-update\" datetime=\"2025-12-15T18:52:27+01:00\">15 dicembre 2025 ( modifica il 15 dicembre 2025 | 18:52)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Mara Rodella Impavidi, violenti, sempre \u00abin branco\u00bb: si firmavano \u00ab069\u00bb, come le ultime tre cifre del CAP&hellip;\n","protected":false},"author":3,"featured_media":262223,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[79],"tags":[2864,23008,154032,154033,19077,154034,154035,3905,154036,154030,154037,94889,154038,154039,18332,154040,154041,2020,63766,16680,2320,154042,67558,14,93,94,7882,27575,724,45641,154043,154044,154045,55610,154046,154047,154048,1537,90,89,31618,154049,33021,13750,300,7,15,5775,154050,10301,7043,1699,18879,10014,2470,83458,2061,407,3726,30601,907,154051,154052,11,84,91,12,85,92,2937,154031],"class_list":["post-262222","post","type-post","status-publish","format-standard","has-post-thumbnail","category-italia","tag-aggressioni","tag-branco","tag-branco-firmavano","tag-branco-firmavano-ultime","tag-cap","tag-cap-villa","tag-cap-villa-carcina","tag-carabinieri","tag-carabinieri-morto","tag-carcina","tag-carcina-concesio","tag-chiami","tag-chiami-carabinieri","tag-chiami-carabinieri-morto","tag-cifre","tag-cifre-cap","tag-cifre-cap-villa","tag-cintura","tag-cocci","tag-coetanei","tag-commissione","tag-commissione-reati","tag-concesio","tag-cronaca","tag-cronaca-italiana","tag-cronacaitaliana","tag-devi","tag-disabile","tag-euro","tag-finiti","tag-firmavano","tag-firmavano-ultime","tag-firmavano-ultime-cifre","tag-gang","tag-impavidi","tag-impavidi-violenti","tag-impavidi-violenti-branco","tag-it","tag-italia","tag-italy","tag-minacciato","tag-minacciavano","tag-minorenni","tag-minori","tag-morto","tag-news","tag-notizie","tag-parlare","tag-picchiavano","tag-pistola","tag-pullman","tag-ragazzi","tag-ragazzini","tag-ragazzino","tag-reati","tag-sarezzo","tag-scuola","tag-settembre","tag-strada","tag-timore","tag-ultime","tag-ultime-cifre","tag-ultime-cifre-cap","tag-ultime-notizie","tag-ultime-notizie-e-news-di-oggi","tag-ultime-notizie-italia","tag-ultimenotizie","tag-ultimenotizieenewsdioggi","tag-ultimenotizieitalia","tag-villa","tag-villa-carcina"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/262222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=262222"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/262222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/262223"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=262222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=262222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=262222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}