{"id":264027,"date":"2025-12-16T21:32:11","date_gmt":"2025-12-16T21:32:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/264027\/"},"modified":"2025-12-16T21:32:11","modified_gmt":"2025-12-16T21:32:11","slug":"gasp-vuole-zirkzee-e-studia-le-alternative-senza-ndicka-ipotesi-scambio-beto-dovbyk","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/264027\/","title":{"rendered":"Gasp vuole Zirkzee e studia le alternative senza Ndicka. Ipotesi scambio Beto-Dovbyk"},"content":{"rendered":"<p>La Roma \u00e8 alla caccia di un nuovo attaccante sul mercato di gennaio.<a href=\"https:\/\/www.forzaroma.info\/calciomercato-as-roma\/roma-casting-in-attacco-yuri-alberto-lalternativa-a-zirkzee-gasp-valuta-raspadori\/\" rel=\"nofollow noopener\" target=\"_blank\"> La richiesta di Gasperini \u00e8 Joshua Zirkzee<\/a> che considera perfetto per il suo gioco. La trattativa con il Manchester United \u00e8 stata gi\u00e0 avviata ma non sar\u00e0 semplice. La chiave \u00e8 la volont\u00e0 del ragazzo che dovr\u00e0 spingere per andare via da Old Trafford. L&#8217;alternativa resta Yuri Alberto. La Roma per\u00f2 si muove anche su altri tavoli e una delle ipotesi vagliate dalla dirigenza \u00e8 anche quella di uno <a href=\"https:\/\/www.forzaroma.info\/calciomercato-as-roma\/mercato-roma-i-friedkin-pensano-allo-scambio-beto-dovbyk\/\" rel=\"nofollow noopener\" target=\"_blank\">scambio &#8220;interno&#8221; tra Artem Dovbyk e Beto<\/a>. L&#8217;attaccante dell&#8217;Everton (propriet\u00e0 Friedkin) \u00e8 in scadenza 2027 e a Trigoria lo seguono da tempo. Difficilmente si tratterebbe di uno scambio secco, visto il diverso valore di mercato dei due giocatori e per il fatto che il contratto dell&#8217;attaccante giallorosso scade nel 2029. Da capire anche la volont\u00e0 del centravanti ucraino che si sta riprendendo dall&#8217;infortunio.<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"La Roma \u00e8 alla caccia di un nuovo attaccante sul mercato di gennaio. La richiesta di Gasperini \u00e8&hellip;\n","protected":false},"author":3,"featured_media":264028,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1452],"tags":[33548,122636,2901,2537,155196,155197,562,155041,721,554,3705,2574,155198,3177,19545,4975,1740,5593,5301,2614,5288,3412,2024,34758,13659,2460,1537,90,89,148962,155199,6248,1412,144170,987,4578,1739,245,244,5396],"class_list":["post-264027","post","type-post","status-publish","format-standard","has-post-thumbnail","category-calcio","tag-albert","tag-albert-gudmundsson","tag-alternative","tag-altra","tag-altra-suggestione","tag-altra-suggestione-albert","tag-attaccante","tag-beto","tag-calcio","tag-club","tag-como","tag-considera","tag-considera-perfetto","tag-destra","tag-dovbyk","tag-fabregas","tag-football","tag-gasp","tag-gasperini","tag-gennaio","tag-giallorosso","tag-giocatori","tag-gioco","tag-gudmundsson","tag-hermoso","tag-ipotesi","tag-it","tag-italia","tag-italy","tag-lasciar","tag-lasciar-partire","tag-mancini","tag-mercato","tag-mercato-gennaio","tag-roma","tag-scambio","tag-soccer","tag-sport","tag-sports","tag-zirkzee"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/264027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=264027"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/264027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/264028"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=264027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=264027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=264027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}