{"id":265698,"date":"2025-12-17T23:08:13","date_gmt":"2025-12-17T23:08:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/265698\/"},"modified":"2025-12-17T23:08:13","modified_gmt":"2025-12-17T23:08:13","slug":"manovra-sulle-pensioni-tensione-nel-governo-la-premier-lemendamento-sulle-lauree-va-cambiato","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/265698\/","title":{"rendered":"Manovra, sulle pensioni tensione nel governo. La premier: \u00abL\u2019emendamento sulle lauree va cambiato\u00bb"},"content":{"rendered":"<p>    di<br \/>\n    Mario Sensini<\/p>\n<p class=\"summary-art is-line-h-12 is-mr-t-20\">La premier:  non ci sar\u00e0 retroattivit\u00e0. Qualsiasi modifica che dovesse intervenire varr\u00e0 solo per il futuro. Il nodo dei conti pubblici a medio termine<\/p>\n<p class=\"chapter-paragraph\">Il giorno dopo l\u2019emendamento del governo alla manovra di bilancio, con la quale sono saltati fuori nuovi fondi per le imprese, scoppia la tempesta nella maggioranza per la nuova stretta sulle pensioni inserita nello stesso pacchetto di proposte. <b>La Lega di Matteo Salvini, che contro la legge Fornero ha da sempre fatto una battaglia, ha subito  presentato un emendamento soppressivo alla norma che inasprisce il regime varato dal governo di Mario Monti<\/b>. Anche Fratelli d\u2019Italia ha parlato di una scelta fatta per \u00abeccesso di zelo\u00bb dai tecnici del Ministero dell\u2019Economia.\u00a0<\/p>\n<p class=\"chapter-paragraph\">\u00c8 dovuta intervenire <b>la premier, Giorgia Meloni<\/b>, in serata, per correggere il tiro. \u00abUn chiarimento importante che voglio dare. Nessuno che ha riscattato la laurea vedr\u00e0 cambiata l\u2019attuale situazione, qualsiasi modifica che dovesse intervenire varr\u00e0 solo per il futuro. L\u2019emendamento in questo senso dovr\u00e0 essere corretto\u00bb ha detto in Aula al Senato, nel corso del  dibattito sul prossimo Consiglio Europeo. \u00c8 evidente, dunque, che un mezzo corto circuito nel governo ci sia stato.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p>    Lega e FdI contrarie<\/p>\n<p class=\"chapter-paragraph\">Giancarlo Giorgetti, titolare dei conti pubblici, <b>difende la struttura tecnica del ministero, a cominciare dalla Ragioneria Generale dello Stato finita sotto gli strali di Claudio Borghi e Guido Liris<\/b>, che per Lega e Forza Italia, come relatori, guidano i lavori in Senato sulla Legge di Bilancio, sulla quale solo ieri, con grandissimo ritardo, sono iniziate le votazioni. <b>La stretta sulle pensioni, che porta un gettito di 2 miliardi, ma solo  a partire dal 2031,<\/b> dunque  ben oltre l\u2019orizzonte della Legge di Bilancio triennale (che copre il periodo \u201826-\u201928), ha destato moltissime proteste tra i sindacati, l\u2019opposizione e anche grandi  perplessit\u00e0 nella stessa maggioranza, vista la sensibilit\u00e0 politica sul tema.  La Lega, soprattutto, aveva gi\u00e0 mal digerito l\u2019aumento dell\u2019et\u00e0 pensionabile, di un mese dal \u201828 e altri due dal \u201829.<\/p>\n<p>    L\u2019equilibrio dei conti<\/p>\n<p class=\"chapter-paragraph\">La verit\u00e0 \u00e8 che qualche problema sul profilo a medio termine dei conti pubblici c\u2019\u00e8. Non \u00e8 noto di quale dimensione, e quale sia la ragione, <b>ma al Ministero dell\u2019Economia sono consapevoli che sarebbe opportuno blindare il  profilo della spesa pubblica nell\u2019ultimo periodo del Piano Strutturale di Bilancio<\/b>, che copre un arco di sette anni e delinea un percorso immodificabile della spesa primaria netta. Scrupolo giustificato anche dal fatto che l\u2019Italia \u00e8 ancora formalmente in procedura di infrazione per il deficit eccessivo, dalla quale chiede di uscire con la verifica dei conti \u201825, che dovrebbero vedere il deficit sotto il 3% del prodotto interno lordo. Gi\u00e0 altre misure previste nel maxiemendamento del governo alla manovra, per giunta, portavano coperture oltre il \u201828, come la ritenuta d\u2019acconto dell\u20191% sulle fatture tra le imprese (1,3 miliardi).<\/p>\n<p>    La retroattivit\u00e0<\/p>\n<p class=\"chapter-paragraph\">La scelta di agire sulle pensioni, per\u00f2, non sarebbe stata esclusivamente tecnica. Le varie opzioni di intervento, frutto di un confronto nella maggioranza,  erano gi\u00e0 sul tavolo da tempo. Ora  ci sar\u00e0 da rimettere mano al pacchetto, per evitare almeno la retroattivit\u00e0 dello stop al riscatto della laurea breve, come ha garantito la Meloni in Parlamento, ma il problema dei conti resta.\u00a0<\/p>\n<p class=\"chapter-paragraph\"><b>\u00abNessuno si fascia la testa\u00bb, ripete Giorgetti, ma qualche pezza bisogner\u00e0 mettercela, anche se la stretta sulle finestre<\/b>, che porta il grosso del gettito, \u00e8 destinata a rimanere. L\u2019emendamento per\u00f2 dovr\u00e0 essere corretto bisogner\u00e0  trovare altre coperture, e il percorso della manovra si allunga e si complica.<\/p>\n<p>    Manovra in stallo<\/p>\n<p class=\"chapter-paragraph\">\u00abLe regole europee non sono pi\u00f9 stringenti di quelle precedenti e la ragione per la quale abbiamo fatto una legge di Bilancio seria \u00e8 che siamo persone serie\u00bb spiega   Meloni in Senato, aggiungendo che <b>\u00abl\u2019Italia ha ampiamente pagato in termini reputazionali,<\/b> e non solo, le allegre politiche che sono state portate avanti negli anni passati\u00bb. Le opposizioni attaccano a testa bassa. \u00abMai visto uno simile spregio del Parlamento. <b>Siamo al 17 dicembre e ancora in prima lettura in Commissione\u00bb attacca Matteo Renzi.<\/b>\u00a0<\/p>\n<p class=\"chapter-paragraph\">\u00abGiorgia Meloni ha annunciato che l\u2019emendamento del governo sulle pensioni cambier\u00e0: \u00e8 l\u2019ennesima, vergognosa conferma che questo governo \u00e8 diviso, nel caos\u00bb, <b>incalza Francesco Boccia<\/b>, presidente dei senatori Pd. \u00abSe siete cos\u00ec uniti, perch\u00e9 ci fate votare la manovra a 24 ore dall\u2019esercizio provvisorio?\u00bb <b>chiede Elly Schlein. <\/b>Anche i sindacati sono arrabbiati, compresa la Cisl che definisce la stretta sulle pensioni incomprensibile. Sorride invece la Confindustria, che con il maxi emendamento ha visto rifinanziate la Zes, Transizione 4.0 e l\u2019iper-ammortamento per tre anni. Per il presidente<\/p>\n<p><a href=\"https:\/\/www.corriere.it\/app-economia\/?intcmp=DL-app_nd_011024_corriere_ss_conomia\" target=\"_blank\" class=\"bck-app-banner\" rel=\"nofollow noopener\"><img decoding=\"async\" class=\"bck-app-img\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/08\/1756449670_863_app.png\"\/><\/p>\n<p>Nuova app <strong>L&#8217;Economia<\/strong>. News, approfondimenti e l&#8217;assistente virtuale al tuo servizio.<\/p>\n<p>SCARICA L&#8217; APP<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/07\/eco.png\"\/><\/a><\/p>\n<p>Iscriviti alle <a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=4\" rel=\"nofollow noopener\" target=\"_blank\">newsletter de L&#8217;Economia<\/a>. Analisi e commenti sui principali avvenimenti\u00a0economici a cura delle firme del Corriere.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-12-17T21:53:09+01:00\">17 dicembre 2025 ( modifica il 17 dicembre 2025 | 21:53)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Mario Sensini La premier: non ci sar\u00e0 retroattivit\u00e0. Qualsiasi modifica che dovesse intervenire varr\u00e0 solo per il&hellip;\n","protected":false},"author":3,"featured_media":262592,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[6],"tags":[1495,1033,16569,475,1411,32918,65304,70209,10560,14,16934,3879,156150,156151,184,2458,33362,32233,125,126,8,3709,50497,156152,1537,90,89,11913,109,1207,51496,22,6771,114,6410,131878,58,851,58670,10565,156153,156154,7,15,82,9,83,10,10567,8111,7711,491,1667,98,115,135,7904,156148,2419,54509,156149,13,11,80,84,12,81,85],"class_list":["post-265698","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ultime-notizie","tag-altre","tag-bilancio","tag-bisognera","tag-chiede","tag-conti","tag-conti-pubblici","tag-coperture","tag-copre","tag-corretto","tag-cronaca","tag-deficit","tag-dovesse","tag-dovesse-intervenire","tag-dovesse-intervenire-varra","tag-economia","tag-emendamento","tag-gettito","tag-giorgetti","tag-giorgia","tag-giorgia-meloni","tag-headlines","tag-imprese","tag-intervenire","tag-intervenire-varra","tag-it","tag-italia","tag-italy","tag-laurea","tag-lega","tag-legge","tag-legge-bilancio","tag-maggioranza","tag-manovra","tag-matteo","tag-medio","tag-medio-termine","tag-meloni","tag-ministero","tag-ministero-economia","tag-modifica","tag-modifica-dovesse","tag-modifica-dovesse-intervenire","tag-news","tag-notizie","tag-notizie-di-cronaca","tag-notizie-principali","tag-notiziedicronaca","tag-notizieprincipali","tag-pacchetto","tag-parlamento","tag-pensioni","tag-percorso","tag-periodo","tag-porta","tag-premier","tag-presidente","tag-pubblici","tag-retroattivita","tag-senato","tag-stretta","tag-stretta-pensioni","tag-titoli","tag-ultime-notizie","tag-ultime-notizie-di-cronaca","tag-ultime-notizie-e-news-di-oggi","tag-ultimenotizie","tag-ultimenotiziedicronaca","tag-ultimenotizieenewsdioggi"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/265698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=265698"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/265698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/262592"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=265698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=265698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=265698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}