{"id":283409,"date":"2025-12-30T15:01:09","date_gmt":"2025-12-30T15:01:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/283409\/"},"modified":"2025-12-30T15:01:09","modified_gmt":"2025-12-30T15:01:09","slug":"la-triatleta-erica-fox-ritrovata-morta-divorata-da-uno-squalo-su-una-spiaggia-della-california-era-scomparsa-il-21-dicembre","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/283409\/","title":{"rendered":"La triatleta Erica Fox ritrovata morta divorata da uno squalo su una spiaggia della California: era scomparsa il 21 dicembre"},"content":{"rendered":"<p>    di<br \/>\n    Salvatore Riggio<\/p>\n<p class=\"summary-art is-line-h-12\">La donna, 55 anni faceva parte di un gruppo di 12 nuotatori partiti il 21 dicembre da Lovers Point, vicino a Monterey, in California, ma non era mai tornata a riva<\/p>\n<p class=\"chapter-paragraph\">Erica Fox, triatleta americana, era scomparsa una settimana fa. Due giorni fa il suo corpo \u00e8 stato ritrovato\u00a0 su una spiaggia della California e, secondo i vigili del fuoco della zona, \u00e8 stata uccisa da uno squalo. La triatleta aveva 55 anni: faceva parte di un gruppo di 12 nuotatori partiti il 21 dicembre da Lovers Point, vicino a Monterey, in California, ma non era mai tornata a riva. Un testimone qualche giorno fa aveva raccontato al <b>\u00abSan Francisco Chronicle\u00bb<\/b> di aver visto proprio il 21 dicembre scorso emergere dall\u2019acqua uno squalo con quello che sembrava un corpo umano in bocca. Per questo motivo non c&#8217;erano molte speranze sul fatto che Erica potesse essere ritrovata ancora in vita.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Del resto quando una settimana fa\u00a0<b>Erica Fox<\/b> non era tornata a riva, suo marito <b>Jean-Fran\u00e7ois Vanreusel<\/b> aveva dato subito l\u2019allarme temendo una tragedia. Nella ricerca, effettuata su larga scala, della 55enne, erano stati coinvolti per diversi giorni equipaggi della Guardia Costiera statunitense, soccorritori dei vigili del fuoco e della polizia locale. Poi per\u00f2 si erano perse le speranze di poterla ritrovare viva, tanto che il marito aveva organizzato una passeggiata commemorativa in spiaggia in sua memoria, temendo di non poter mai ritrovarne neanche il cadavere per poter fare il funerale. A sorpresa per\u00f2 i resti del corpo sono riemersi dalle acque dell&#8217;oceano qualche giorno fa. Sono stati recuperati sulla spiaggia di Davenport, appena a sud di <b>Santa Cruz, nel nord della California<\/b>    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">Il riconoscimento \u00e8 stato fatto dal marito e dal padre di Erica. Fox era un&#8217;atleta molto in gamba avendo completato diversi triathlon (una disciplina sportiva che consiste nel praticare di seguito tre diversi sport, iniziando con 750m di nuoto, proseguendo con 20km in bici e terminando con 5km corsa)\u00a0e due \u00abmezzi\u00bb Iron Man (specialit\u00e0 in cui le distanze aumentano, in un Iron Man infatti si percorrono 3.86km a nuoto, 180km in bici, 42.195 km di corsa).\u00a0<\/p>\n<p class=\"chapter-paragraph\">La giornalista e collega nuotatrice Sara Rubin, scrivendo sul \u00abMonterey County Weekly\u00bb, ha descritto Fox come un&#8217;amica e un&#8217;atleta appassionata che aveva trovato la pace interiore nuotando nell&#8217;Oceano Pacifico.<\/p>\n<p class=\"chapter-paragraph\">\u00abVent&#8217;anni fa, Erica Fox e un&#8217;amica hanno iniziato a nuotare ogni domenica a Lovers Point, a <b>Pacific Grove<\/b>. Da allora, sono stati scritti diversi libri sulla scienza del nuoto e sui suoi benefici per il nostro cervello. Ma Erica non ha mai avuto bisogno di un libro per apprendere ci\u00f2 che sapeva per esperienza: nuotare nell&#8217;oceano \u00e8 un balsamo per il corpo e la mente, un&#8217;avventura tanto quanto una meditazione\u00bb, ha scritto Rubin. \u00abErica aveva sviluppato un rapporto profondamente intimo con l&#8217;<b>Oceano Pacifico <\/b>non studiandolo o guardandolo, ma entrandoci dentro, ancora e ancora e ancora, nei giorni di mare mosso e in quelli di calma, percorrendo quelle che posso solo immaginare siano diventate nel corso degli anni migliaia di miglia\u00bb ha sottolineato la giornalista americana.<\/p>\n<p class=\"chapter-paragraph\">Rubin ha detto che <b>Fox<\/b> \u00abcomprendeva il rischio\u00bb di nuotare in un oceano popolato da grandi squali bianchi e che \u00absi sarebbe opposta a definire questo evento come un attacco, esortandoci invece a chiamarlo incidente\u00bb.<\/p>\n<p class=\"chapter-paragraph\">Nonostante a largo della California infatti siano sempre pi\u00f9 numerosi gli avvistamenti di <b>squali bianchi<\/b>, \u00e8 raro che essi attacchino gli esseri umani. Tanto che negli ultimi 75 anni,\u00a0 prima di quello avvenuto ai danni di\u00a0 Erica, le vittime registrate nello stato americano erano state soltanto 16.\u00a0<\/p>\n<p class=\"is-last-update\" datetime=\"2025-12-30T15:10:29+01:00\">30 dicembre 2025 ( modifica il 30 dicembre 2025 | 15:10)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Salvatore Riggio La donna, 55 anni faceva parte di un gruppo di 12 nuotatori partiti il 21&hellip;\n","protected":false},"author":3,"featured_media":283410,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[4717,7074,3550,24540,3508,14836,166888,166889,3591,1276,14,164,165,1888,166890,166891,2391,166883,166884,12451,166892,783,4348,4639,166588,166885,7242,166,166886,7,15,36228,15224,8842,11615,13792,158927,13498,23515,6368,166887,166587,11,167,12,168,161,162,163],"class_list":{"0":"post-283409","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-americana","9":"tag-amica","10":"tag-atleta","11":"tag-bianchi","12":"tag-bici","13":"tag-california","14":"tag-california-tornata","15":"tag-california-tornata-riva","16":"tag-corpo","17":"tag-corsa","18":"tag-cronaca","19":"tag-dal-mondo","20":"tag-dalmondo","21":"tag-dicembre","22":"tag-dicembre-lovers","23":"tag-dicembre-lovers-point","24":"tag-diversi","25":"tag-erica","26":"tag-erica-fox","27":"tag-fox","28":"tag-fox-amica","29":"tag-fuoco","30":"tag-giornalista","31":"tag-km","32":"tag-lovers","33":"tag-lovers-point","34":"tag-marito","35":"tag-mondo","36":"tag-monterey","37":"tag-news","38":"tag-notizie","39":"tag-nuotare","40":"tag-nuoto","41":"tag-oceano","42":"tag-point","43":"tag-riva","44":"tag-rubin","45":"tag-spiaggia","46":"tag-squalo","47":"tag-tornata","48":"tag-tornata-riva","49":"tag-triatleta","50":"tag-ultime-notizie","51":"tag-ultime-notizie-di-mondo","52":"tag-ultimenotizie","53":"tag-ultimenotiziedimondo","54":"tag-world","55":"tag-world-news","56":"tag-worldnews"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/283409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=283409"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/283409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/283410"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=283409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=283409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=283409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}