{"id":286642,"date":"2026-01-01T18:32:13","date_gmt":"2026-01-01T18:32:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/286642\/"},"modified":"2026-01-01T18:32:13","modified_gmt":"2026-01-01T18:32:13","slug":"carosi-io-campione-italiano-juniores-voglio-perdere-un-paio-di-chili-per-migliorare-in-salita","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/286642\/","title":{"rendered":"Carosi: \u00abIo, campione italiano juniores, voglio perdere un paio di chili per migliorare in salita\u00bb"},"content":{"rendered":"<p><a href=\"https:\/\/www.quibicisport.it\/wp-content\/uploads\/2026\/01\/Carosi-1.jpg\" data-caption=\"Vincenzo Carosi, diciassette anni, \u00e8 il campione italiano degli juniores ed \u00e8 pronto ad affrontare la seconda stagione nella categoria (credit: Coratti Work Service).\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" data-lazyloaded=\"1\" width=\"696\" height=\"599\" class=\"entry-thumb td-modal-image\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/01\/Carosi-1-696x599.jpg\"  data- alt=\"Carosi\" title=\"Carosi-1\"\/><\/a>Vincenzo Carosi, diciassette anni, \u00e8 il campione italiano degli juniores ed \u00e8 pronto ad affrontare la seconda stagione nella categoria (credit: Coratti Work Service).<br \/>\nTempo di lettura:   4 minuti<\/p>\n<p>\u00abAl ciclismo mi sono appassionato grazie a Gabriele, mio fratello maggiore, che compir\u00e0 ventitr\u00e9 anni dopodomani\u00bb, racconta <strong>Vincenzo Carosi<\/strong>. \u00abHo cominciato da piccolo in mountain bike, poi tra gli esordienti ho deciso di cimentarmi anche nel ciclocross. \u00c8 stato allora che ho dovuto scegliere tra il ciclismo e il tennis, l\u2019altro sport che praticavo. La passione me l\u2019aveva trasmessa mia mamma, giocatrice di tennis a sua volta. Me la cavavo discretamente, il mio marchio di fabbrica erano le smorzate e ho sempre tifato per Berrettini, un tennista per niente freddo che trasmette molte emozioni. E poi siamo entrambi laziali, lui di Roma e io di Vetralla, in provincia di Viterbo. Ho scelto il ciclismo perch\u00e9 me lo sentivo dentro pi\u00f9 del tennis, che comunque seguo ancora volentieri. Su strada, tuttavia, ho cominciato a gareggiare soltanto tra gli allievi, e l\u2019attivit\u00e0 non era cos\u00ec intensa. A conti fatti, posso dire che la mia prima vera stagione da stradista \u00e8 stata la scorsa\u00bb.<\/p>\n<p><strong>Al debutto tra gli juniores, a diciassette anni, hai vinto a sorpresa il campionato italiano. A sorpresa?<\/strong><\/p>\n<p>\u00abDi certo non ero il favorito. Tutti sapevamo che Baruzzi e Maganotti avevano una marcia in pi\u00f9, e che l\u2019incognita pi\u00f9 pericolosa si chiamava Agostinacchio. Io per\u00f2 ero reduce da alcuni buoni piazzamenti: terzo a San Leolino, quinto nella classifica generale del Giro d\u2019Abruzzo e miglior giovane. Siccome mi sentivo bene ed ero adatto al percorso del campionato italiano, con chi mi segue ci siamo detti che dovevamo prepararlo come si deve, atleticamente e tatticamente\u00bb.<\/p>\n<p><strong>Hai vinto regolando in volata i compagni di fuga, dopo aver attaccato fin dalle prime battute di gara.<\/strong><\/p>\n<p>\u00abNon mi sono dato pace finch\u00e9 non sono entrato in fuga, se volevo avere una chance dovevo accumulare un certo margine sui grandi favoriti. All\u2019inizio dell\u2019ultimo giro mi sono reso conto che non ci avrebbero ripresi e ho cominciato a pensare alla volata, che poi ho vinto anticipando Pezzo Rosola e Pascarella. Tra gli allievi avevo centrato qualche corsa regionale, ma si pu\u00f2 dire che il campionato italiano degli juniores \u00e8 stata la prima vera affermazione della mia carriera. \u00c8 andato tutto per il verso giusto. All\u2019inizio non ci credevo, mi sembrava surreale, come se fossi sott\u2019acqua. Poi, smaltita l\u2019adrenalina, ho realizzato d\u2019avercela fatta\u00bb.<\/p>\n<p><img data-lazyloaded=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/01\/Carosi-2-1024x682.jpg\" alt=\"Carosi\" class=\"wp-image-269217\"  data-\/>Carosi ha cominciato pedalando nel fuoristrada, prima in mountain bike e poi nel ciclocross, cimentandosi su strada soltanto a partire dall\u2019ingresso nella categoria allievi (credit: Coratti Work Service).<\/p>\n<p><strong>Adesso viene il difficile: riconfermarsi e accettare la condizione di osservato speciale.<\/strong><\/p>\n<p>\u00abHo gi\u00e0 avuto modo di accorgermene. Indosso una maglia pi\u00f9 che riconoscibile ed \u00e8 comprensibile che gli avversari mi guardino con un occhio diverso. Per\u00f2 devo accettarlo, fa parte del gioco. Anzi, devo dire che non mi dispiace, perch\u00e9 mi sprona a dare sempre il massimo e a riconoscere il valore del simbolo che porto. Per l\u2019immediato futuro mi sono posto due obiettivi: vincere di pi\u00f9 rispetto allo scorso anno e conquistare nuovamente la maglia tricolore di campione italiano\u00bb.<\/p>\n<p><strong>Quante possibilit\u00e0 ci sono di rivederti in azione in mountain bike e nel ciclocross?<\/strong><\/p>\n<p>\u00abIn mountain bike nessuna, temo, perch\u00e9 la stagione delle gare combacia con quella della strada, a cui adesso voglio e devo dare precedenza. Nel ciclocross ci sono maggiori possibilit\u00e0, nel 2025 ho dovuto rinunciare alle corse per colpa di una mononucleosi che ha compromesso anche le ultime prove della mia stagione sulla strada. Non nascondo che il fuoristrada mi manca, ma mi metter\u00f2 l\u2019anima in pace. Sar\u00f2 per sempre grato a quel mondo per ci\u00f2 che mi ha dato: una guida del mezzo fluida e un\u2019esplosivit\u00e0 che mi torna sempre utile\u00bb.<\/p>\n<p><strong>Dunque dobbiamo considerarti un corridore da classiche?<\/strong><\/p>\n<p>\u00abCredo proprio di s\u00ec. Ho due sogni: la Parigi-Roubaix e la Milano-Sanremo. Tra l\u2019altro la Sanremo del 2018, quella vinta da Nibali, \u00e8 stata la prima grande vittoria che mi sono goduto da spettatore televisivo, diciamo cos\u00ec. Per lungo tempo, infatti, il ciclismo su strada lo seguivo di straforo. Sapevo cosa fosse, ovviamente, ma i miei idoli erano Schurter per la mountain bike e Van der Poel per il ciclocross. Tornando alla tua domanda: s\u00ec, sono un corridore adatto alle classiche, esplosivo sugli strappi e veloce a ranghi ristretti\u00bb.<\/p>\n<p><img loading=\"lazy\" data-lazyloaded=\"1\" decoding=\"async\" width=\"740\" height=\"674\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/01\/Carosi-3.jpg\" alt=\"Carosi\" class=\"wp-image-269216\" style=\"width:720px;height:auto\"  data-\/>Corridore esplosivo e veloce a ranghi ristretti, l\u2019obiettivo principale di Carosi \u00e8 migliorare sulle salite pi\u00f9 lunghe. Per riuscirci sta lavorando sul suo peso: quello attuale si attesta sui 63 chili (credit: Coratti Work Service).<\/p>\n<p><strong>Fermo restando che hai soltanto diciassette anni e una vita davanti, dove senti di dover migliorare?<\/strong><\/p>\n<p>\u00abSulle salite lunghe, altrimenti d\u2019essere rapido nelle volate di venti o trenta corridori non me ne faccio di niente. Sono alto 1,74 e durante la scorsa stagione non sono mai sceso sotto i sessantaquattro chili, ma volendo migliorare in montagna ho bisogno di asciugarmi. Adesso sono arrivato a pesare sessantatr\u00e9 chili, ma non mi dispiacerebbe attestarmi sui sessantadue\u00bb.<\/p>\n<p><strong>Hai qualche rimpianto da vendicare?<\/strong><\/p>\n<p>\u00abNon ne ho uno, ma tre. Al Liberazione ero rimasto senza compagni di squadra e quando sono scappati i due australiani che si sono giocati il successo non ho potuto fare nulla per seguirli e per riprenderli; nel gruppo non abbiamo trovato l\u2019accordo e ci hanno anticipati di qualche secondo. Al Dorigo, una settimana prima del campionato italiano, mi sentivo bene, peccato che la rottura della catena mi abbia impedito di giocarmela come avrei voluto. Infine, voglio tornare al Giro della Lunigiana senza la mononucleosi, perch\u00e9 non mi basta partecipare a certe gare soltanto per portarle a termine\u00bb.<\/p>\n<p><strong>Dopodich\u00e9, sar\u00e0 tempo di passare tra gli Under 23.<\/strong><\/p>\n<p>\u00abCi penseremo a tempo debito. Entrare a far parte di un vivaio straniero mi onorerebbe, ma devo capire se ne sono all\u2019altezza. Senza dimenticare le formazioni che abbiamo in Italia: dalla Bardiani alla Mbh Bank, passando per le continental pi\u00f9 prestigiose. La priorit\u00e0 ce l\u2019hanno la seconda stagione tra gli juniores con la mia squadra, la Coratti Work Service, e la quarta superiore. Frequento il liceo scientifico, studiare non mi dispiace ma non ho ancora deciso se frequenter\u00f2 o meno l\u2019universit\u00e0. Dipende anche da quello che raccoglier\u00f2 nel ciclismo, un mondo in cui comunque voglio provare a farmi strada\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"Vincenzo Carosi, diciassette anni, \u00e8 il campione italiano degli juniores ed \u00e8 pronto ad affrontare la seconda stagione&hellip;\n","protected":false},"author":3,"featured_media":286643,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1456],"tags":[1824,1825,1537,90,89,245,244],"class_list":{"0":"post-286642","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciclismo","8":"tag-ciclismo","9":"tag-cycling","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-sport","14":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115821277583873774","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/286642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=286642"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/286642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/286643"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=286642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=286642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=286642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}