{"id":287480,"date":"2026-01-02T10:08:11","date_gmt":"2026-01-02T10:08:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/287480\/"},"modified":"2026-01-02T10:08:11","modified_gmt":"2026-01-02T10:08:11","slug":"padre-e-figlio-finiscono-ai-domiciliari","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/287480\/","title":{"rendered":"padre e figlio finiscono ai domiciliari"},"content":{"rendered":"<p>BRINDISI &#8211; Una piantagione \u201cindoor\u201d di marijuana e hashish nella propria abitazione. Padre e figlio, entrambi incensurati, di 51 e 26 anni, sono stati arrestati nella tarda mattinata dello scorso 27 dicembre, poich\u00e9 colti in flagranza nella produzione, coltivazione e detenzione, presumibilmente ai fini di spaccio, di sostanza stupefacente. I due sono finiti ai domiciliari.<\/p>\n<p>La Squadra Mobile della questura di Brindisi, con l\u2019ausilio dei cinofili della Polizia di Frontiera del capoluogo, ha effettuato una perquisizione domiciliare che ha permesso di rinvenire e sequestrare due \u201cgrow box\u201d munite di lampade e termometri, 12 piante di varie dimensioni di marijuana, un quantitativo di 32,72 grammi di infiorescenze di marijuana, 1,66 grammi di hashish e 36,88 grammi di semi, oltre che due bilancini di precisione e materiale per il confezionamento dello stupefacente.<\/p>\n<p>Rimani aggiornato sulle notizie dalla tua provincia iscrivendoti al nostro canale whatsapp: <a href=\"https:\/\/whatsapp.com\/channel\/0029VaKWoMlHVvTdyOiOzY2a\" rel=\"nofollow noopener\" target=\"_blank\">clicca qui<\/a><\/p>\n<p>Seguici gratuitamente anche sul canale Facebook: <a href=\"https:\/\/m.me\/j\/Abampv2kioahdYYR\/?fbclid=IwZXh0bgNhZW0CMTAAAR29fhbvEPBoqO0AXcm08uabvybjbX6Vl8SoolvjtSYOebOXvXAZ-222Rrk_aem_aWYjeKkf52MbBu56JCWyxw\" target=\"_blank\" rel=\"nofollow\">https:\/\/m.me\/j\/Abampv2kioahdYYR\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"BRINDISI &#8211; Una piantagione \u201cindoor\u201d di marijuana e hashish nella propria abitazione. Padre e figlio, entrambi incensurati, di&hellip;\n","protected":false},"author":3,"featured_media":287481,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14,8,1537,90,89,7,15,82,9,83,10,13,11,80,84,12,81,85],"class_list":{"0":"post-287480","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-cronaca","9":"tag-headlines","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-news","14":"tag-notizie","15":"tag-notizie-di-cronaca","16":"tag-notizie-principali","17":"tag-notiziedicronaca","18":"tag-notizieprincipali","19":"tag-titoli","20":"tag-ultime-notizie","21":"tag-ultime-notizie-di-cronaca","22":"tag-ultime-notizie-e-news-di-oggi","23":"tag-ultimenotizie","24":"tag-ultimenotiziedicronaca","25":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115824957992630399","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/287480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=287480"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/287480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/287481"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=287480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=287480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=287480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}