{"id":299689,"date":"2026-01-10T09:41:12","date_gmt":"2026-01-10T09:41:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/299689\/"},"modified":"2026-01-10T09:41:12","modified_gmt":"2026-01-10T09:41:12","slug":"soudal-quick-step-jasper-stuyven-spiega-laddio-alla-lidl-trek-non-mi-vedevano-piu-come-leader-per-le-classiche-voglio-essere-al-via-con-lidea-di-poter-vincere","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/299689\/","title":{"rendered":"Soudal Quick-Step, Jasper Stuyven spiega l&#8217;addio alla Lidl-Trek: &#8220;Non mi vedevano pi\u00f9 come leader per le classiche. Voglio essere al via con l&#8217;idea di poter vincere&#8221;"},"content":{"rendered":"<p>\t\t<img width=\"1200\" height=\"800\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/01\/Stuyven-Soudal-Quick-Step.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" data-main-img=\"1\" decoding=\"async\" fetchpriority=\"high\"  \/><\/p>\n<p>\t\t\t\t\t<a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/scopri-lapp-ufficiale-di-spaziociclismo\/\" title=\"\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/09\/1758060682_662_Banner-App-SpazioCiclismo.png\" alt=\"\" width=\"728\" height=\"91\"\/><br \/>\n\t\t\t\t\t<\/a><\/p>\n<p><strong><a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quick-step-jasper-stuyven-non-vedo-lora-di-far-parte-del-wolfpack-mi-hanno-promesso-un-ruolo-importante\/\" target=\"_blank\" rel=\"noopener nofollow\">Jasper Stuyven<\/a>\u00a0<\/strong>ha scelto di cambiare squadra per la prima volta nella sua carriera. Durante l\u2019ultima sessione di ciclomercato, il corridore belga \u00e8 approdato nella\u00a0<a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quick-step-dylan-van-baarle-i-metodi-di-allenamento-della-visma-non-fanno-per-me-forse-per-simon-yates-era-lo-stesso\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong>Soudal Quick-Step<\/strong><\/a>, team con cui ha firmato dopo 12 anni di esperienza con la\u00a0<strong>Lidl-Trek<\/strong>. L\u2019arrivo nel Wolfpack, \u00e8 facile da intuire, sposa perfettamente l\u2019ambizione del vincitore della\u00a0<strong>Milano-Sanremo 2021\u00a0<\/strong>di tornare a vincere e a piazzarsi in maniera importante nelle classiche del nord, suo terreno di caccia preferito. In carriera, il 32enne ha ottenuto 9 successi da professionista, tra cui appunto la Classicissima, una\u00a0<strong>Omloop het Nieuwsblaad\u00a0<\/strong>e una\u00a0<strong>Kuurne-Bruxelles-Kuurne<\/strong>. L\u2019impressione, per\u00f2, \u00e8 che possa ambire a qualcosa di pi\u00f9 in futuro.<\/p>\n<p>Parlando del suo trasferimento, il classe \u201992 ha rivelato in <a href=\"https:\/\/sporza.be\/nl\/2026\/01\/08\/-natuurlijk-hoorde-ik-dat-niet-graag-jasper-stuyven-geeft-uitleg-bij-zijn-opvallende-move-van-lidl-trek-naar-the-wolfpack~1767886822365\/\" target=\"_blank\" rel=\"noopener nofollow\">un\u2019intervista a Sporza<\/a>: \u201cNon \u00e8 che fossi stanco di correre per la Lidl-Trek, ma quando sono iniziate le trattative con la Soudal Quick-Step ho sentito che era giunto il momento per una nuova squadra. <strong>Alla Lidl-Trek mi hanno detto onestamente che non mi vedevano pi\u00f9 come leader per le classiche sul pav\u00e9<\/strong>. Naturalmente non mi \u00e8 piaciuto sentirmelo dire. Per\u00f2 la squadra ha capito che ci potevano essere molte alte squadre in grado di garantirmi il ruolo di leader. Questo ha reso pi\u00f9 semplice la scelta di andarmene, perch\u00e9 <strong>penso di avere sicuramente ancora il mio valore nelle classiche di primavera<\/strong>\u201c.<\/p>\n<p>L\u2019approdo nella nuova squadra, dunque, dovrebbe concedergli pi\u00f9 spazio: \u201cL\u2019idea \u00e8 provare a far rivivere i tempi d\u2019oro del Wolfpack. Ma tutti sono abbastanza realistici: <strong>Tadej Pogacar e Mathieu van der Poel sono cos\u00ec forti da poter rapidamente forzare una situazione uomo conto uomo<\/strong>. Tuttavia, d\u00e0 pi\u00f9 fiducia e motivazione sapere di poter andare alle classiche con una squadra forte. In questo modo non devi rispondere da solo agli attacchi e puoi creare una situazione in cui non sei costretto a inseguire tutto il giorno. <strong>Come vincere una classica contro Pogacar e Van Der Poel? Vorrei dire che ho una risposta, ma non ce l\u2019ho<\/strong>. Ma sar\u00f2 ancora alla partenza di una classica con l\u2019idea che posso vincerla\u201d.<\/p>\n<p>Seguici<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMNaVhQswhaiCAw?hl=it&amp;gl=IT&amp;ceid=IT%3Ait\" title=\"Google News\" target=\"_blank\" rel=\"nofollow noopener\" class=\"post-followus-btn google-new-btn\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/themes\/jannah\/assets\/images\/google-news.svg\" alt=\"Google News\" loading=\"lazy\" width=\"120\" height=\"22\"\/><br \/>\n\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flipboard.com\/@SpazioCiclismo\" title=\"Flipboard\" target=\"_blank\" rel=\"nofollow noopener\" class=\"post-followus-btn flipboard-btn\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/themes\/jannah\/assets\/images\/flipboard.svg\" alt=\"Flipboard\" loading=\"lazy\" width=\"152\" height=\"30\"\/><br \/>\n\t\t\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Jasper Stuyven\u00a0ha scelto di cambiare squadra per la prima volta nella sua carriera. Durante l\u2019ultima sessione di ciclomercato,&hellip;\n","protected":false},"author":3,"featured_media":299690,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1456],"tags":[1824,1825,1537,90,89,23446,104173,245,244],"class_list":{"0":"post-299689","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciclismo","8":"tag-ciclismo","9":"tag-cycling","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-jasper-stuyven","14":"tag-soudal-quick-step-2026","15":"tag-sport","16":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115870150395913722","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/299689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=299689"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/299689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/299690"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=299689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=299689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=299689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}