{"id":302571,"date":"2026-01-12T06:48:13","date_gmt":"2026-01-12T06:48:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/302571\/"},"modified":"2026-01-12T06:48:13","modified_gmt":"2026-01-12T06:48:13","slug":"pallavolo-mercato-il-giovane-francese-daniel-iyegbekedo-dovrebbe-completare-il-reparto-dei-centrali-di-piacenza-ivolley-magazine","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/302571\/","title":{"rendered":"Pallavolo Mercato \u2013 Il giovane francese Daniel Iyegbekedo dovrebbe completare il reparto dei centrali di Piacenza \u2013 iVolley Magazine"},"content":{"rendered":"<p>La Gas Sales Bluenergy Piacenza \u00e8 corsa ai ripari dopo aver perduto ben due elementi del suo reparto dei centrali: prima Simon e poi Galassi per problematiche fisiche non sono disponbili in tempi brevi. Secondo riporta Matteo Marchetti su sportpiacenza.it, il club emiliano della presidente Curti, ha individuato in Daniel Iyegbekedo centrale francese classe 2007, l\u2019elemento giusto per rinforzare la rosa a disposizione di Dante Boninfante. <\/p>\n<p>Iyegbekedo nelle scorse settimane era gi\u00e0 stato a Piacenza per uno stage e nel momento della necessit\u00e0 i dirigenti biancorossi hanno deciso di ingaggiare il giovane talento, che era piaciuto nel periodo trascorso con il guppo di Bonifante. <\/p>\n","protected":false},"excerpt":{"rendered":"La Gas Sales Bluenergy Piacenza \u00e8 corsa ai ripari dopo aver perduto ben due elementi del suo reparto&hellip;\n","protected":false},"author":3,"featured_media":302572,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1474],"tags":[1537,90,89,245,244,1869],"class_list":{"0":"post-302571","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-volley","8":"tag-it","9":"tag-italia","10":"tag-italy","11":"tag-sport","12":"tag-sports","13":"tag-volley"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115880794697290827","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/302571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=302571"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/302571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/302572"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=302571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=302571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=302571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}