{"id":306470,"date":"2026-01-14T23:43:13","date_gmt":"2026-01-14T23:43:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/306470\/"},"modified":"2026-01-14T23:43:13","modified_gmt":"2026-01-14T23:43:13","slug":"quando-siamo-punto-a-punto-ci-troviamo-a-nostro-agio-video-e-pagelle","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/306470\/","title":{"rendered":"\u00abQuando siamo punto a punto ci troviamo a nostro agio\u00bb. VIDEO e pagelle"},"content":{"rendered":"<p>          <a href=\"https:\/\/www.gassalesenergia.it\/punto-fermo-piacenza\/\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" style=\"aspect-ratio:300\/233;\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/07\/sport_piacenza_banner_articoli_322x250-3.jpg\" width=\"300\" height=\"233\"\/><\/a><\/p>\n<p>Ormai la soddisfazione di <strong>Dante Boninfante<\/strong> \u00e8 costante perch\u00e9 la sua squadra in ogni gara mette in mostra sempre qualche passo avanti.<\/p>\n<p><strong>Per Piacenza \u00e8 il terzo 3-0 consecutivo. E a Milano non \u00e8 mai semplice.<\/strong><\/p>\n<p>\u00abLoro nonostante le assenze, come d\u2019altronde avevamo anche noi, sono una squadra che gioca sempre e lo hanno dimostrato soprattutto nel primo set. Alla lunga hanno un po\u2019 mollato ma hanno provato a recuperare anche nella seconda frazione, noi siamo stati bravi a mantenere quella tranquillit\u00e0 che in partite simili abbiamo gi\u00e0 dimostrato. E\u2019 stata una bella gara portata a casa\u00bb.<\/p>\n<p><strong>Sembra che questa squadra in campo si diverta.<\/strong><\/p>\n<p>\u00abEra uno degli obiettivi, dare tranquillit\u00e0 in modo che i ragazzi si possano divertire perch\u00e9 alla fine questo \u00e8 un gioco. Divertirsi non vuol dire ridere e scherzare sempre, ma gioire delle cose fatte bene e del sacrificio di un compagno e questo si sta verificando\u00bb.<\/p>\n<p><strong>Oggi ancora una volta avete subito un parziale di 7-2, avete protestato su una palla molto dubbia e da quel momento avete cambiato ritmo.<\/strong><\/p>\n<p>\u00abA noi sembrava abbastanza evidente il fallo, ma gli arbitri hanno deciso il contrario. L\u2019importante \u00e8 che anche in situazioni complicate riusciamo a restare tranquilli, consapevoli che quando siamo punto a punto ci troviamo a nostro agio\u00bb.<\/p>\n<p><strong>Non hai fatto neppure un cambio obbligato, sintomo che tutto funziona alla perfezione.<\/strong><\/p>\n<p>\u00abI ragazzi stavano facendo bene e non era il caso di modificare l\u2019assetto, ma sono consapevole che in caso di bisogno chi entra dalla panchina si esprime ad alti livelli\u00bb.<\/p>\n<p><strong>LE PAGELLE<\/strong><\/p>\n<p><strong>Porro 7,5<\/strong>: torna dove \u00e8 stato protagonista fino allo scorso anno, apre e chiude il primo set con un ace, si fa sentire anche a muro. Dimentichiamo, come al solito alza divinamente<\/p>\n<p><strong>Bovolenta 6,5<\/strong>: il muro a uno che ferma Recine, fino a quel momento immarcabile, per il 24-23 della prima frazione \u00e8 di platino. Primo set spettacolare, poi cala leggermente<\/p>\n<p><strong>Comparoni 6,5<\/strong>: si mette in fila e aspetta il suo turno. Sa che davanti a lui ci sono gli attaccanti di palla alta, ma quando Porro decide di utilizzarlo si fa trovare prontissimo<\/p>\n<p><strong>Seddik 7<\/strong>: si capisce che Reggers non gli sta simpatico. Lo mura a ripetizione, per la gioia di Piacenza<\/p>\n<p><strong>Mandiraci 7+<\/strong>: un set per scaldarsi, poi diventa l\u2019incubo di Milano. Sbaglia qualcosa in ricezione, ma in attacco e un\u2019iradiddio<\/p>\n<p><strong>Gutierrez 7,5<\/strong>: chirurgico. Ogni volta che c\u2019\u00e8 un contrattacco o un\u2019azione lunga e la palla arriva a lui, la trasforma in punto. Sempre<\/p>\n<p><strong>Pace 6,5<\/strong>: ormai \u00e8 noioso, per trovare un suo errore bisogna scavare a fondo. La parallela che difende a Reggers non \u00e8 fisicamente spiegabile<\/p>\n<p><strong>Andringa: sv<\/strong><\/p>\n<p><strong>Leon: sv<\/strong><\/p>\n<p><strong>Bergmann: sv<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Ormai la soddisfazione di Dante Boninfante \u00e8 costante perch\u00e9 la sua squadra in ogni gara mette in mostra&hellip;\n","protected":false},"author":3,"featured_media":289920,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1474],"tags":[104830,18202,1537,90,89,245,244,9406,1869],"class_list":{"0":"post-306470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-volley","8":"tag-dante-boninfante","9":"tag-gas-sales-bluenergy","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-sport","14":"tag-sports","15":"tag-superlega","16":"tag-volley"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115896110491225679","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/306470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=306470"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/306470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/289920"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=306470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=306470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=306470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}