{"id":306511,"date":"2026-01-15T00:18:13","date_gmt":"2026-01-15T00:18:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/306511\/"},"modified":"2026-01-15T00:18:13","modified_gmt":"2026-01-15T00:18:13","slug":"chiara-ferragni-la-beneficenza-quel-video-in-tuta-gli-insulti-sui-social-ecco-la-mia-verita-sono-imperfetta-anche-io-ma-sono-una-brava-persona","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/306511\/","title":{"rendered":"Chiara Ferragni: \u00abLa beneficenza, quel video in tuta, gli insulti sui social: ecco la mia verit\u00e0. Sono imperfetta anche io, ma sono una brava persona\u00bb"},"content":{"rendered":"<p>    di<br \/>\n    Giuseppe Guastella e Candida Morvillo<\/p>\n<p class=\"summary-art is-line-h-12\">Ripubblichiamo l&#8217;intervista esclusiva all&#8217;imprenditrice e influencer uscita sul \u00abCorriere\u00bb all&#8217;inizio del \u00abPandoro Gate\u00bb. Le inchieste, le polemiche,  il rapporto con Fedez: \u00abLa priorit\u00e0 \u00e8 difendere la mia famiglia. Ho avuto un successo pi\u00f9 grande dei sogni che avevo. Ora mi sento fragile per\u00f2 faccio fatica a raccontarlo\u00bb<\/p>\n<p class=\"chapter-paragraph\">Ripubblichiamo l&#8217;intervista esclusiva a Chiara Ferragni di Giuseppe Guastella e Candida Morvillo, pubblicata sul\u00a0\u00abCorriere della Sera\u00bb del 24 febbraio 2024, nel pieno del\u00a0\u00abPandoro Gate\u00bb e nei giorni delle prime voci della rottura tra l&#8217;influencer e l&#8217;allora marito Fedez.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Il giorno in cui <b><a href=\"https:\/\/milano.corriere.it\/notizie\/spettacoli\/24_marzo_03\/chiara-ferragni-fazio-che-tempo-che-fa-315f6339-793c-4928-acdc-067dbcc15xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">Chiara Ferragni<\/a><\/b> arriva sorridente <b>all\u2019appuntamento per la nostra <a href=\"https:\/\/milano.corriere.it\/notizie\/cronaca\/24_febbraio_24\/chiara-ferragni-i-am-far-from-perfect-but-i-ve-always-been-in-good-faith-fedez-it-s-right-to-keep-our-problems-to-ourselves-64ed411d-0605-4b97-9382-fc11ee5a2xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">intervista<\/a> ha al dito la fede<\/b> e, nel cuore, sembra avere la speranza che il suo matrimonio regga all\u2019onda d\u2019urto dei <a href=\"https:\/\/www.corriere.it\/economia\/consumi\/24_febbraio_05\/chiara-ferragni-e-i-brand-in-fuga-dal-boom-di-notorieta-di-sanremo-2023-al-rischio-di-5-milioni-in-fumo-744cb55e-5c9b-441a-b98e-39042c4cdxlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">problemi degli ultimi due mesi<\/a>. Quel giorno, le chiediamo: Portofino, Champoluc, Courmayeur\u2026 <b>Perch\u00e9 ha passato gli ultimi weekend senza suo marito?<\/b> Perch\u00e9 lui non le \u00e8 vicino proprio in queste settimane difficili? Chiara, per un attimo, guarda la punta delle scarpe. Dice: \u00abLui in tanti weekend non c\u2019\u00e8 stato. In altri, c\u2019\u00e8 stato\u00bb. Quindi, di nuovo, \u00e8 a testa alta: <b>\u00abComunque, \u00e8 mio marito.<\/b> E secondo me, in certe situazioni di caos esterno,<a href=\"https:\/\/www.corriere.it\/spettacoli\/24_febbraio_22\/fedez-ferragni-crisi-nata-sanremo-tre-indizi-che-hanno-certificato-fine-ab8f416a-d170-11ee-a8e6-77782b3bdabc.shtml#:~:text=leggilo%20quando%20vuoi.-,Fedez%20e%20Ferragni%3A%20la%20crisi%20nata%20a%20Sanremo%202023%20e%20i,che%20hanno%20certificato%20la%20fine&amp;text=Tre%20indizi%20fanno%20una%20prova,manca%20sempre%20l&#039;altra%20met%C3%A0.\" rel=\"nofollow noopener\" target=\"_blank\"> le altre cose \u00e8 meglio tenerle dentro la coppia<\/a>\u00bb. Noi: che intende esattamente per \u00abaltre cose\u00bb? Lei: \u00abChe <b>la priorit\u00e0 \u00e8 proteggere la famiglia e i figli.<\/b> Poi, naturalmente, qualunque cosa io faccia, se ne parla: se la faccio con lui o se la faccio senza di lui e<b> chiunque nel mondo pu\u00f2 dire la sua<\/b> e avere le sue opinioni, ma per me, piuttosto che dare spiegazioni, \u00e8 pi\u00f9 importante fare quello che reputo pi\u00f9 giusto: <a href=\"https:\/\/milano.corriere.it\/notizie\/cronaca\/24_febbraio_23\/fedez-e-la-separazione-a-pomeriggio-cinque-intervistato-sotto-casa-di-un-amico-replica-vi-pare-un-gioco-e1818f26-7537-4ced-9383-2ec9dad15xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">tenere i problemi tra le mura familiari<\/a>\u00bb.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">Era marted\u00ec 20 febbraio. <a href=\"https:\/\/www.corriere.it\/cronache\/24_febbraio_23\/fedez-ferragni-lasciati-lite-divorzista-13a429da-d1c3-11ee-a8e6-77782b3bdabc.shtml\" rel=\"nofollow noopener\" target=\"_blank\">La crisi c\u2019era, intuibile, evidente.<\/a> Ma di una famigerata, presunta uscita di casa di Fedez, ancora non si sapeva e Chiara, anche se <b>in lei si leggeva la sofferenza<\/b>, era riuscita a non farlo capire.<br \/>Non era per parlare del suo matrimonio che nasceva il nostro incontro e, ieri come oggi, Chiara non vuole aggiungere altro sull\u2019argomento. D\u2019altra parte, c\u2019era stato un momento nel corso dell\u2019intervista in cui<b> aveva confessato<\/b>, in un soffio: \u00abIo, a volte, faccio <b>fatica a mostrare le mie fragilit\u00e0 <\/b>nel momento in cui le sto vivendo\u00bb. Silenzio.<\/p>\n<p class=\"chapter-paragraph\">Silenzio. Pausa. \u00abFaccio fatica perch\u00e9, se raccontassi quanto mi sento fragile (<a href=\"https:\/\/milano.corriere.it\/notizie\/cronaca\/24_febbraio_26\/chiara-ferragni-all-inviato-di-pomeriggio-5-posso-andare-dalla-psicologa-in-pace-e-un-momento-doloroso-f512cd5c-4ed5-45e7-87eb-64a2ea57exlk.shtml\" title=\"Chiara Ferragni all&#039;inviato di Pomeriggio 5: \u00abPosso andare dalla psicologa in pace? \u00c8 un momento doloroso\u00bb\" rel=\"nofollow noopener\" target=\"_blank\">qui le parole dell&#8217;imprenditrice, intercettata luned\u00ec fuori dallo studio della sua psicologa<\/a>), <b>mi percepirei ancora pi\u00f9 debole, ancora pi\u00f9 attaccabile<\/b>\u00bb. Oggi, oggi col senno di poi, dev\u2019essere una di quelle volte in cui trovare le parole acuirebbe solo il dolore. La conversazione era partita da <b>una data spartiacque<\/b>, il 15 dicembre scorso, quando <a href=\"https:\/\/www.corriere.it\/economia\/aziende\/23_dicembre_15\/antitrust-multa-chiara-ferragni-balocco-14-milioni-sanzione-il-pandoro-griffato-6642bfdc-9b1b-11ee-83aa-b9fe93a908f7.shtml\" rel=\"nofollow noopener\" target=\"_blank\">l\u2019Antitrust comunica di aver sanzionato due societ\u00e0 di Chiara e la Balocco <\/a> per \u00abuna pratica commerciale scorretta\u00bb, per aver pubblicizzato<b> il pandoro griffato Ferragni <\/b>lasciando intendere ai consumatori che, comprandolo, avrebbero contribuito a <a href=\"https:\/\/torino.corriere.it\/notizie\/cronaca\/23_dicembre_15\/chiara-ferragni-sanzionata-dall-antitrust-per-le-donazioni-all-ospedale-regina-margherita-col-pandoro-balocco-fcbf4548-03d6-419f-ad07-d27db731axlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">una donazione all\u2019Ospedale Regina Margherita di Torino.<\/a>\u00a0<\/p>\n<p class=\"chapter-paragraph\"><b>Chiara, che cosa ricorda di quel 15 dicembre?<\/b><br \/>\u00abChe erano le otto del mattino, ero in piedi, stavo andando su un set fotografico e n\u00e9 io n\u00e9 i miei collaboratori ci aspettavamo nulla del genere. Sono rimasta completamente scioccata. Anche perch\u00e9 ho saputo la notizia dalle agenzie, contemporaneamente a tutti gli italiani. Era venerd\u00ec, ho passato anche sabato e domenica chiusa in casa, con addosso la stessa tuta, a leggere i tweet terribili su di me e dire: cosa cavolo sta succedendo?\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>La tuta \u00e8 quella che indossava nel famoso video di scuse del 18 dicembre, criticata perch\u00e9 sembrava scelta per sottolineare con sapienza il suo pentimento, sebbene costasse 600 euro?<\/b><br \/>\u00abEro vestita ancora cos\u00ec quando ho pensato che dovevo fare un video e dimostrare la buona fede mia e delle persone che lavorano con me. Da tre giorni, leggevo cose completamente false, tipo che avevo truffato i consumatori e perfino i bambini malati. Ero veramente scossa e dopo varie prove <a href=\"https:\/\/video.corriere.it\/spettacoli\/look-dimesso-voce-rotta-video-cui-ferragni-ha-chiesto-scusa-lo-spot-pandoro\/8d54c0e4-9dae-11ee-894b-33071cf732ac\" rel=\"nofollow noopener\" target=\"_blank\">ho postato il video<\/a> e facevo del mio meglio per trattenere le lacrime perch\u00e9 non volevo fare la vittima. Mi sono detta: la gente si aspetta qualcosa da me. Dovevo scusarmi, perch\u00e9, se ci sono stati dei fraintendimenti, vuol dire che qualcosa poteva essere fatto meglio. Ho detto anche che non avrei fatto mai pi\u00f9 operazioni che mischiassero pubblicit\u00e0 e beneficenza. Poi ho pensato: faccio un gesto concreto. Le persone credono che mi sia arricchita cercando di imbrogliarle? Bene, il milione di euro ricevuto dalle mie societ\u00e0 <a href=\"https:\/\/torino.corriere.it\/notizie\/cronaca\/24_gennaio_09\/caso-ferragni-e-arrivato-al-regina-margherita-il-milione-di-euro-donato-dall-influencer-4a6bffae-92d3-43cd-b704-358be96a1xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">lo dono al Regina Margherita di Torino<\/a> e far\u00f2 ricorso al Tar contro una sanzione che ritengo ingiusta e sproporzionata, ovviamente la pago e, se qualcosa otterr\u00f2 indietro, doner\u00f2 anche quello\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Perch\u00e9, a suo avviso, quel video non ha fermato l<\/b><b>\u2019<\/b><b>ondata di odio e di scherno?<\/b><br \/>\u00abProbabilmente perch\u00e9 non era il momento giusto, continuavano a uscire notizie contro di me. Forse avrei dovuto pensarci di pi\u00f9, aspettare, ma si stava mettendo in gioco tutto, si andava molto oltre i giudizi sull\u2019operazione in s\u00e9, la strumentalizzazione era completa. E, quando sei dentro una gogna mediatica, ti sembra che tutte le persone ti stiano accusando, invece, basta uscire un attimo di casa per accorgerti che non \u00e8 cos\u00ec. Da quando ho ripreso a uscire, non ho mai incontrato qualcuno che mi dicesse \u201csei una criminale\u201d, ma solo persone che mi dicono: tutto questo \u00e8 ingiusto, ne uscirai a testa alta\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Nel video, ammette \u00abun errore di comunicazione\u00bb. Sulle attivit\u00e0 di beneficenza, cosa intende fare?<\/b><br \/>\u00abCi siamo resi conto che alcuni processi di analisi interna avrebbero potuto essere gestiti meglio. E stiamo lavorando per migliorare alcuni profili organizzativi. Ho sempre pensato che, se hai trenta milioni di follower, se fai beneficenza e ne parli, crei un effetto emulativo. Durante il Covid, io e Federico abbiamo donato 50 mila euro a testa, ma comunicandolo, il crowdfunding \u00e8 risultato il pi\u00f9 sostanzioso d\u2019Europa raccogliendo quattro milioni e mezzo, grazie ai quali siamo riusciti a creare una terapia intensiva in un mese e mezzo. Ma non solo: seguendo il nostro esempio, altri hanno attivato operazioni simili per altri ospedali. Per questo, quando possibile, la mia ratio \u00e8 stata che, nell\u2019ambito di operazioni commerciali tra le mie societ\u00e0 e un partner, fosse semplicemente una buona idea provare ad aggiungere una parte di beneficenza anche piccola rispetto al contratto. Ho sempre pensato che, fra niente e poco, era comunque del bene che veniva fatto\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Nel caso del pandoro, per\u00f2, la beneficenza \u00e8 stata fatta dalla Balocco, non dalle sue societ\u00e0.<\/b><br \/>\u00abVero, cosi come \u00e8 vero che \u00e8 stata una iniziativa mia e del mio team far inserire la donazione all\u2019interno del contratto\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Allora perch\u00e9, e anche su questo indaga la Procura di Milano, la donazione \u00e8 stata fatta prima che partisse la campagna vendite?<\/b><br \/>\u00abLa donazione \u00e8 stata fatta subito dopo la firma del contratto ed \u00e8 stata fatta subito proprio perch\u00e9 l\u2019importo di 50 mila euro era certo e slegato dalle vendite e poi perch\u00e9 speravamo che il macchinario arrivasse prima della messa in vendita del pandoro\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Si indaga anche perch\u00e9, dal cartiglio sul pandoro e da come lei ha promosso l<\/b><b>\u2019<\/b><b>iniziativa, sembrava che acquistando il prodotto si contribuisse a fare beneficenza.<\/b><br \/>\u00abNel cartiglio e nei miei post, per\u00f2, abbiamo sempre scritto e detto che \u201cChiara Ferragni e Balocco sostengono l\u2019ospedale\u2026\u201d, mai che una percentuale delle vendite sarebbe andata in beneficenza\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Una cosa che ha molto colpito l<\/b><b>\u2019<\/b><b>opinione pubblica \u00e8 la sproporzione tra il suo cachet, pi\u00f9 di un milione, e la beneficenza, 50 mila euro.<\/b><br \/>\u00abParlare di cachet \u00e8 improprio, perch\u00e9 quella cifra \u00e8 il compenso dato alle mie societ\u00e0 per i miei diritti di immagine, per la promozione e l\u2019intera operazione. Non si deve far confusione tra la persona fisica Chiara Ferragni, il brand e le aziende. Inoltre, senza l\u2019operazione, la donazione non sarebbe stata fatta\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Senza la beneficenza, le sue societ\u00e0 avrebbero incassato di pi\u00f9<\/b><b>?<\/b><br \/>\u00abProbabilmente, un pochino s\u00ec. Ma l\u2019importante era fare la donazione\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>La procura dice che, nell<\/b><b>\u2019<\/b><b>operato delle societ\u00e0, c\u2019\u00e8 stato un unico disegno criminoso tra pi\u00f9 operazioni: Balocco, uova pasquali di Dolci Preziosi e bambola Trudi.<\/b><br \/>\u00abQueste operazioni rappresentavano una percentuale esigua del nostro fatturato. Non comprendo come si possa dire che ci sia stato un disegno criminoso: perch\u00e9, se cos\u00ec fosse, la maggior parte del fatturato dovrebbe dipendere da queste attivit\u00e0. E poi, sembra che io sia conosciuta per la beneficenza, ma ho fatto tantissime attivit\u00e0. Per fortuna con il nuovo Ddl beneficenza, o Ddl Ferragni (ride, ndr), tutto sar\u00e0 molto pi\u00f9 chiaro. Se ci fosse stato prima, avremmo scritto sul cartiglio \u201cChiara Ferragni e Balocco sostengono l\u2019ospedale Regina Margherita con una donazione di 50 mila euro fatta da Balocco\u201d. Nessuno avrebbe potuto dire niente e ci faceva onore comunque. Se c\u2019\u00e8 un effetto positivo di questa vicenda, \u00e8 che ora abbiamo un Ddl beneficenza\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>L<\/b><b>\u2019<\/b><b>associazione americana Stomp out bullying ha sostenuto di non aver ricevuto donazioni legate alla bambola \u00abChiara Ferragni by Trudi\u00bb. \u00c8 cos\u00ec<\/b><b>?<\/b><br \/>\u00abLa donazione \u00e8 stata fatta e ho la documentazione che lo attesta. A tempo debito, chiarir\u00f2 tutto a chi di dovere\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Qual <\/b><b>\u00e8 il suo ruolo operativo nelle societ\u00e0 sanzionate dall<\/b><b>\u2019<\/b><b>Antitrust per la vicenda del pandoro, Fenice Srl e Tbs Crew?<\/b><br \/>\u00abIn entrambe sono amministratrice delegata. In Tbs, anche presidente. Ho sempre cercato di sviluppare e far crescere i marchi legati al mio nome anche attraverso l\u2019organizzazione e la partecipazione ad eventi. Poi ho particolare attenzione per l\u2019area social media\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>L<\/b><b>\u2019<\/b><b>anno scorso avete avuto ricavi per 28 milioni di euro, un grande successo. Forse avete sottovalutato la dimensione raggiunta?<\/b><br \/>\u00abSicuramente. Non eravamo strutturati abbastanza. Siamo tutti giovani, principalmente sotto i 40 anni. Il mondo in cui opero \u00e8 nato con noi e noi avevamo la presunzione molto naif di fare un lavoro che, prima, non esisteva e che ha raggiunto fatturati da media impresa. Forse non eravamo neanche mentalmente preparati. Ci piaceva che tanti ci dicessero \u201cbravi\u201d o \u201csiete cos\u00ec smart\u201d. Quella dell\u2019Agcm \u00e8 stata la prima bastonata, la prima volta che qualcuno ci ha detto con durezza e pubblicamente che avevamo fatto male qualcosa. La prima volta in cui ho detto: \u201ccavolo, eravamo in buona fede, ma evidentemente potevamo fare meglio\u201d. Io vedo i miei numeri, ho un\u2019idea di quanto posso essere popolare, ma mi rendo conto di aver sottostimato tutto. Adesso, sono fiera dei miei ragazzi ma so che serve un rafforzamento della struttura con persone con pi\u00f9 esperienza di me e di quelle che sempre in buona fede mi hanno aiutato fin qui. Serve anche, in certi momenti, essere pi\u00f9 pronta a combattere e io non pensavo di doverlo mai fare\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Dice di essere vittima di una gogna mediatica, ma non le sembra ovvio che una persona famosa come lei finisca pi\u00f9 di altri sotto la lente dei media?<\/b><br \/>\u00ab\u00c8 stata dura. Per due mesi si \u00e8 parlato di me come se fossi una criminale e incarnassi ogni male di questo Paese. Quando \u00e8 scoppiato il caso, gli hater non hanno attaccato Balocco perch\u00e9 dicevano che ci sono gli operai e le famiglie, ma anche per le mie societ\u00e0 lavorano 50 famiglie. Sono abituata a essere un personaggio divisivo, ad avere persone che mi supportano, ma anche hater. Fa parte del gioco, ma cercare ogni giorno una notizia negativa, anche falsa, per volere la mia disfatta, \u00e8 stato eccessivo da sopportare anche per me. Poi ho l\u2019impressione che faccia fare pi\u00f9 clic dare enfasi a qualche hater piuttosto che alla maggioranza silenziosa che magari la pensa in altro modo\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Quando ha cominciato a realizzare che la situazione era pi\u00f9 grave di quanto potesse preventivare?<\/b><br \/>\u00abDalla pronuncia dell\u2019Authority, vedendo anche come si \u00e8 deciso di renderla pubblica: con un comunicato in cui c\u2019erano anche i compensi delle societ\u00e0\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Il centrodestra l<\/b><b>\u2019<\/b><b>ha attaccata identificandola come progressista, bandiera di una sinistra glamour.<\/b><br \/>\u00abNon sono dichiaratamente di una parte, non ho mai inteso fare politica. Semplicemente, mi sono sempre battuta per i diritti inalienabili delle persone, per le donne, per la comunit\u00e0 Lgbtq+, perch\u00e9 questo fa parte della mia storia e del mio modo di raccontare la realt\u00e0 in cui vivo\u00bb<b>.<\/b><\/p>\n<p class=\"chapter-paragraph\"><b>Oggi, cercando il suo nome su Google, molti risultati sono impietosi. Cerca mai il suo nome online?<\/b><br \/>\u00abPurtroppo s\u00ec. L\u2019ho sempre fatto e, adesso, lo faccio con maggiore frequenza e, quando escono nuove fake news, \u00e8 molto difficile non rispondere subito. Cerco il mio nome perch\u00e9 vorrei il controllo su tutto e per avere il polso di quello che si dice su di me, anche se poi mi deprimo di pi\u00f9 e mi sento meno forte di prima\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Il suo lavoro \u00e8 un po\u2019 <\/b><b>fondato sull<\/b><b>\u2019<\/b><b>effimero. In questo periodo, non le \u00e8 venuta voglia di maggiore concretezza?<\/b><br \/>\u00abQuello che faccio \u00e8 molto concreto, altro che effimero. Ho un\u2019azienda che produce e vende abbigliamento, calzature, make up, auricolari, gioielli. Non promuovo solo prodotti altrui. Sono diventata un riferimento sotto tanti punti di vista per tante persone che mi seguono da 14 anni, che sono cresciute con me, che hanno seguito tutte le fasi della mia vita e si sono ritrovate simili in tante cose, perch\u00e9 parlo tanto anche di me, di come mi sento, delle mie emozioni. Faccio post in cui si parla di quanto \u00e8 bella la borsa e post in cui parlo dei diritti delle donne. Non penso di fare su Instagram un racconto cos\u00ec effimero\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Immagina un futuro diverso nella sua attivit\u00e0<\/b><b>?<\/b><br \/>\u00abSono cambiate molte cose in questi due mesi, ma il futuro al momento \u00e8 un punto interrogativo. Non so se il mio \u00e8 un lavoro che far\u00f2 per tutta la vita o se vorr\u00f2 raccontare la mia vita per sempre. So che a me piace comunicare da sempre. A 16 anni, andavo in giro con il treppiedi, mi facevo l\u2019autoscatto, volevo vedermi attraverso una macchina fotografica, darmi un significato, non so: capirmi. E non c\u2019\u00e8 mai stata l\u2019idea di tenere quelle foto per me, ma sempre di condividerle col mondo e vedere cosa ne pensava nel bene e nel male\u00bb.\u00a0<\/p>\n<p class=\"chapter-paragraph\"><b>Che altro c\u2019\u00e8 da raccontare su quella sedicenne?<\/b><br \/>\u00abEro una ragazzina cresciuta a Cremona, in un contesto di provincia, pap\u00e0 dentista, mamma che aveva lasciato un lavoro nella moda per seguire mia sorella che aveva problemi di salute. La provincia mi stava stretta, ho sempre cercato di non pormi dei limiti e sognato di fare qualcosa di pi\u00f9, per questo ho colto subito l\u2019opportunit\u00e0 dei social. Poi, fino a qualche anno fa, dicevo: chi sa se questo sar\u00e0 il mio futuro, se questo lavoro andr\u00e0 avanti. Ma gi\u00e0 allora ero una che faceva le cose cercando di dare sempre il massimo. Sono una che studia, si impegna. Quando ho fatto Sanremo, non ero mai stata in tv e ho preso lezioni con un coach di improvvisazione. Non prendo mai nulla sottogamba, poi che le cose risultino perfette o tremende \u00e8 soggettivo\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Qual <\/b><b>\u00e8 il momento in cui Chiara Ferragni decolla?<\/b><br \/>\u00abHo iniziato nel 2009, ma tutto \u00e8 esploso tra il 2013 e il 2016 quando vivevo a Los Angeles. In Italia, all\u2019inizio ero vista come la blogger che non si sapeva bene cosa facesse. Poi, Harvard ha fatto un case study su di me, Forbes ha detto che ero l\u2019influencer numero uno al mondo e l\u2019Italia si \u00e8 accorta di me. Nel 2017 sono tornata, e da allora ci sono stati gli anni di grossa crescita\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Qual <\/b><b>\u00e8 il momento preciso in cui si accorge che qualcosa di grande \u00e8 successo?<\/b><br \/>\u00abQuando ho fatto il primo red carpet a Cannes, a maggio 2011. Mi hanno dato un abito rosa principesco e dei gioielli e avevo un bodyguard che mi seguiva per proteggerli: questa cosa mi faceva specie, era la prima volta che avevo una guardia del corpo, anche se non era per me. Quando ho calcato il tappeto rosso, pensavo che nessuno mi conoscesse, invece tanti fotografi italiani hanno cominciato a chiamarmi \u201cChiara, Chiara\u201d ed \u00e8 stato stupendo. Ho detto wow, \u00e8 cos\u00ec che si sentono le star, che figata!\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>In questi due mesi complicati ha avuto paura che tutto questo potesse finire per sempre?<\/b><br \/>\u00abNon \u00e8 il primo momento in cui ho questa paura: la paura \u00e8 costante. In un lavoro come il mio che \u00e8 completamente nuovo, temi sempre che il trend possa cambiare e di non piacere pi\u00f9. Poi, per non interrogarmi sugli esiti negativi, ho fatto tanto lavoro su me stessa, mi hanno insegnato che bisogna vivere solo nel presente, non nel passato n\u00e9 nella paura del futuro. E mi dico che non posso piacere a tutti, ma che alle persone a cui piaccio, piaccio perch\u00e9 sono me stessa, faccio le cose che piacciono a me e, anche se ora vengo descritta come una \u201ccriminale\u201d, cerco di ispirare le persone verso cose positive perch\u00e9 questo \u00e8 il mio modo di comunicare. Io senza comunicare non riuscirei a vivere: mi piace lo scambio di opinioni, mi piacciono anche le critiche, se fatte in modo costruttivo. Ho cambiato tante cose di me, ascoltandole\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Ci dica una cosa che ha cambiato.<\/b><br \/>\u00abTante volte mi \u00e8 stato detto che cercavo di essere troppo perfetta ed \u00e8 vero: ho sempre l\u2019idea di dare il massimo e non mostrare le fragilit\u00e0. Negli anni, mi sono sforzata di manifestarle di pi\u00f9. Per\u00f2, a volte, fatico a farlo nel momento in cui le sto vivendo, se no, mi sentirei troppo attaccabile e mi mostrerei troppo debole. Le persone, da fuori, vedono una vita perfetta: ho una famiglia, guadagno bene, faccio il lavoro dei miei sogni, viaggio eccetera. Io stessa, in primis, avevo la stessa idea delle grandi star, Da piccola, guardavo le modelle o le attrici e dicevo: wow, sono stupende, fanno la vita dei sogni, chiss\u00e0 come stanno bene con se stesse. Dopo, quando ho fatto campagne con top come Naomi Campbell, come Gisele B\u00fcndchen, mi sentivo sempre un po\u2019 diversa, nonostante facessi cose simili a loro. Poi ti rendi conto che anche Naomi, anche le star che pensi si sentano le persone pi\u00f9 fighe del pianeta hanno insicurezze che il successo non ti toglie. Quando succede a te, capisci che siamo tutti fragili, abbiamo tutti le nostre insicurezze, stiamo tutti anche male. Io sono ipergrata della mia vita, ma non sono perfetta e non voglio pi\u00f9 neanche apparire tale\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Tuttavia, \u00e8 pi\u00f9 facile accettarsi in una penthouse che in un monolocale, in una Lamborghini che in un<\/b><b>\u2019<\/b><b>utilitaria ?<\/b><br \/>\u00abMa sicuramente. Io sono una persona fortunata che ha creato una vita che va oltre i sogni che avevo da bambina. Poi, questo mi fa strano e ho sempre la paura che qualcosa possa succedere ma, allo stesso tempo, cerco di lavorare sodo affinch\u00e9 questo non avvenga\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Lei come si spiega un successo pi\u00f9 grande dei sogni che aveva?<\/b><br \/>\u00abCon una concatenazione di eventi e col fatto di seguire tanto il mio istinto. Poi, il successo c\u2019\u00e8, \u00e8 oggettivo, ma che io me lo meriti \u00e8 una cosa soggettiva. Ci saranno tanti che pensano che non me lo meriti. Pazienza\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>Sta ridendo. Lei pensa di meritarselo?<\/b><br \/>\u00abIo penso di essere una brava persona e di dare il massimo in tutto quello che faccio\u00bb.\u00a0<\/p>\n<p class=\"is-mr-t-20 is-mr-b-20\"><b><br \/>\n                    <a href=\"https:\/\/milano.corriere.it\/?intcmp=Notizielocali_nd_010623_corriere_ss_milano\" target=\"_blank\" rel=\"nofollow noopener\">Vai a tutte le notizie di Milano<\/a><br \/>\n            <\/b><\/p>\n<p class=\"chapter-paragraph\"><b><a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=41&amp;intcmp=IIIcolonna_NL_CorMilano\" target=\"_blank\" rel=\"nofollow noopener\">Iscriviti alla newsletter di Corriere Milano<\/a><\/b><\/p>\n<p class=\"is-last-update\" datetime=\"2026-01-14T16:20:09+01:00\">14 gennaio 2026 ( modifica il 14 gennaio 2026 | 16:20)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Giuseppe Guastella e Candida Morvillo Ripubblichiamo l&#8217;intervista esclusiva all&#8217;imprenditrice e influencer uscita sul \u00abCorriere\u00bb all&#8217;inizio del \u00abPandoro&hellip;\n","protected":false},"author":3,"featured_media":306512,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1451],"tags":[30943,7554,1495,94467,8560,180035,4013,1498,30038,180036,180037,17064,7001,6090,6908,35805,2295,180038,174237,5217,1621,1620,4970,1330,4018,40,1774,180039,14334,1073,1505,2570,187,2944,6693,4864,122,32100,180040,2276,112311,1277,2427,180041,3719,1888,34015,880,2448,180042,13171,180033,2429,16481,3880,180034,203,6038,724,626,1909,943,2097,2154,2882,7216,180043,9885,1595,6934,466,1778,180044,180045,18821,14414,30043,2024,11202,1975,116593,160454,38381,128,48,1233,12468,2734,6402,1302,96529,30035,1282,6043,204,1537,90,627,89,21304,775,20582,180046,7242,1285,8866,793,43506,80001,14850,37853,180047,124592,1354,14344,1693,4509,811,892,688,812,180048,180049,30040,51121,2463,5775,33414,4979,489,5238,8176,23,5239,4966,9028,21335,1915,99025,16884,4958,17736,7900,6092,978,14852,11045,26060,3277,282,438,4265,15348,5210,12056,18198,180050,1401,44133,44134,180051,9525,988,22479,11603,13243,27675,180052,28610,1272,1686,1359,9654,630,1886,659,5248,1928,66997,16897,6574,5489,2392],"class_list":["post-306511","post","type-post","status-publish","format-standard","has-post-thumbnail","category-celebrita","tag-aggiungere","tag-alta","tag-altre","tag-altre-cose","tag-antitrust","tag-attaccabile","tag-attimo","tag-attivita","tag-balocco","tag-balocco-sostengono","tag-balocco-sostengono-ospedale","tag-bambola","tag-beneficenza","tag-buona","tag-buona-fede","tag-cachet","tag-cambiato","tag-cambiato-tante","tag-cartiglio","tag-cavolo","tag-celebrita","tag-celebrities","tag-cercando","tag-cercato","tag-cerco","tag-chiara","tag-chiara-ferragni","tag-chiara-ferragni-balocco","tag-cominciato","tag-completamente","tag-comunicare","tag-concreto","tag-consumatori","tag-conto","tag-contratto","tag-corriere","tag-cose","tag-criminale","tag-criminoso","tag-dare","tag-dare-massimo","tag-dato","tag-ddl","tag-ddl-beneficenza","tag-debole","tag-dicembre","tag-dicevo","tag-diritti","tag-disegno","tag-disegno-criminoso","tag-donazione","tag-donazione-fatta","tag-donne","tag-dovevo","tag-effetto","tag-effimero","tag-entertainment","tag-esclusiva","tag-euro","tag-eventi","tag-famiglia","tag-famiglie","tag-far","tag-farlo","tag-fatica","tag-fatta","tag-fatta-balocco","tag-fatturato","tag-febbraio","tag-fede","tag-fedez","tag-ferragni","tag-ferragni-balocco","tag-ferragni-balocco-sostengono","tag-fragile","tag-fragilita","tag-gate","tag-gioco","tag-gioielli","tag-giusto","tag-gogna","tag-gogna-mediatica","tag-hater","tag-idea","tag-importante","tag-imprenditrice","tag-indaga","tag-influencer","tag-iniziativa","tag-inizio","tag-insicurezze","tag-intende","tag-intervista","tag-intervista-esclusiva","tag-intrattenimento","tag-it","tag-italia","tag-italiani","tag-italy","tag-lavorano","tag-maggiore","tag-margherita","tag-margherita-torino","tag-marito","tag-massimo","tag-matrimonio","tag-media","tag-mediatica","tag-meriti","tag-milione","tag-mostrare","tag-mostrare-fragilita","tag-naomi","tag-ne","tag-neanche","tag-nome","tag-notizia","tag-operazione","tag-operazioni","tag-opinioni","tag-ospedale","tag-ospedale-regina","tag-ospedale-regina-margherita","tag-pandoro","tag-pandoro-gate","tag-parla","tag-parlare","tag-parlo","tag-parole","tag-passato","tag-paura","tag-pensa","tag-pensato","tag-pensavo","tag-penso","tag-percentuale","tag-perfetta","tag-persona","tag-piaccio","tag-piacciono","tag-piace","tag-piacere","tag-piccola","tag-posso","tag-post","tag-potesse","tag-potuto","tag-priorita","tag-problemi","tag-procura","tag-provincia","tag-pubblica","tag-qual","tag-raccontare","tag-regina","tag-regina-margherita","tag-regina-margherita-torino","tag-ricevuto","tag-ripubblichiamo","tag-ripubblichiamo-intervista","tag-ripubblichiamo-intervista-esclusiva","tag-sapeva","tag-scritto","tag-seguire","tag-sembrava","tag-semplicemente","tag-sento","tag-sento-fragile","tag-simili","tag-so","tag-social","tag-societa","tag-sogni","tag-star","tag-successo","tag-tante","tag-tanti","tag-testa","tag-tuta","tag-uscire","tag-vendite","tag-vero","tag-video"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/306511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=306511"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/306511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/306512"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=306511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=306511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=306511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}