{"id":309941,"date":"2026-01-17T03:35:13","date_gmt":"2026-01-17T03:35:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/309941\/"},"modified":"2026-01-17T03:35:13","modified_gmt":"2026-01-17T03:35:13","slug":"il-ritorno-di-benedetta-pilato-mi-sono-trovata-ad-affrontare-una-situazione-piu-grande-di-me-a-singapore-ho-pensato-di-aver-rovinato-tutto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/309941\/","title":{"rendered":"Il ritorno di Benedetta Pilato: \u00abMi sono trovata ad affrontare una situazione pi\u00f9 grande di me. A Singapore ho pensato di aver rovinato tutto\u00bb"},"content":{"rendered":"<p class=\"has-dropcap\">\u00abMi serviva questo periodo di silenzio, ho sbagliato ma i commenti delle persone mi hanno toccato. Il cambiamento ha aiutato\u00bb. Partiamo dalla fine a raccontare il ritorno di <strong>Benedetta Pilato<\/strong> che, terminati <a href=\"https:\/\/www.vanityfair.it\/article\/benedetta-pilato-chiara-tarantino-sospese-90-giorni-dopo-caso-furto-singapore\" target=\"_blank\" rel=\"nofollow noopener\">i 90 giorni di sospensione decisi dalla Procura Federale della Federazione Italiana Nuoto<\/a>, <a href=\"https:\/\/www.vanityfair.it\/article\/benedetta-pilato-chiara-tarantino-nuotatrici-furto-singapore\" target=\"_blank\" rel=\"nofollow noopener\">dopo i fatti di Singapore<\/a>, torna in piscina e alle gare con una nuova residenza: Roma, sotto la guida tecnica di Mirko Nozzolillo.<\/p>\n<p>La ranista azzurra, ha parlato, in esclusiva, con Mario Calabresi, nel corso di una puntata di Vivavoce, le interviste di Seietrenta, podcast di Chora Media che ogni giorno racconta le storie pi\u00f9 importanti dai giornali, dai siti e dai social media. Impossibile non tornare su quanto accaduto lo scorso anno dopo i Campionati del Mondo di nuoto di Singapore 2025.<\/p>\n<p>In vasca l&#8217;atleta tarantina ha vinto il bronzo nei 50 rana. \u00abParlando prettamente delle gare della scorsa stagione, forse \u00e8 stato uno degli anni pi\u00f9 difficili della mia carriera. Vivevo a Torino, dove ho comparto casa, e stavo bene. La mia vita andava bene, la carriera un po\u2019 meno: il mio corpo non reagiva perfettamente come doveva, non reagiva agli stimoli [\u2026]. <a href=\"https:\/\/www.vanityfair.it\/article\/sindrome-ovaio-policistico-sintomi-terapie\" target=\"_blank\" rel=\"nofollow noopener\">Non ho mai nascosto le mie difficolt\u00e0 dal punto di vista ormonale.<\/a> [\u2026] <strong>La medaglia \u00e8 stata importante ed \u00e8 stata inaspettata e tanto voluta<\/strong>\u00bb.<\/p>\n<p>Fuori dalla vasca quello che definisce un pastrocchio. Al rientro dalla vacanza con un piccolo gruppo della Nazionale, a Bali, in Indonesia, all&#8217;aeroporto di Singapore Bendetta Pilato e la collega Chiara Tarantino sono state fermate e accusate del furto di alcune boccette di oli essenziali. Sono state trattenute a Singapore e poi lasciate partire per l&#8217;Italia. Una inchiesta ha appurato i fatti del 14 agosto e la conseguenza sono stati i 90 giorni di sospensione.<\/p>\n<p>\u00abCi siamo divertiti e poi \u00e8 successo un pastrocchio. <strong>Abbiamo fatto un errore, una bravata per cui abbiamo pagato le conseguenze. Abbiamo chiesto scusa, ho chiesto scusa a chi dovevo, ribadisco.<\/strong> Per fortuna, si \u00e8 risolta in pochissimo tempo e per questo dobbiamo ringraziare. \u00c8 stata dura per me e per la mia famiglia. Mi sono trovata ad affrontare una situazione pi\u00f9 grande di me. Sono fortunata perch\u00e9 ho avuto e ho persone che ci sono state e mi hanno aiutato\u00bb.<\/p>\n<p>L&#8217;azzurra ha ammesso di aver pensato di \u00abrovinato tutto\u00bb, ma ora pensa alla nuova stagione con gli Assoluti e gli  Europei in agosto a Parigi. Benedetta Pilato \u00e8 primatista italiana di 50 e 100 metri rana. Ha vinto un oro mondiale e quattro europei fra vasca lunga e corta.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00abMi serviva questo periodo di silenzio, ho sbagliato ma i commenti delle persone mi hanno toccato. Il cambiamento&hellip;\n","protected":false},"author":3,"featured_media":309942,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176],"tags":[1537,90,89,15224,245,244],"class_list":{"0":"post-309941","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport","8":"tag-it","9":"tag-italia","10":"tag-italy","11":"tag-nuoto","12":"tag-sport","13":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115908347339781939","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/309941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=309941"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/309941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/309942"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=309941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=309941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=309941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}