{"id":326247,"date":"2026-01-27T22:07:16","date_gmt":"2026-01-27T22:07:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/326247\/"},"modified":"2026-01-27T22:07:16","modified_gmt":"2026-01-27T22:07:16","slug":"scatta-lallerta-arancione-scuole-chiuse-in-provincia-di-latina","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/326247\/","title":{"rendered":"scatta l\u2019allerta arancione. Scuole chiuse in provincia di Latina"},"content":{"rendered":"<p>Scuole chiuse in alcuni comuni della provincia di Latina per il maltempo. Le notizie si stanno diffondendo in queste ore dopo che la protezione civile regionale ha diramato una <a href=\"https:\/\/www.latinatoday.it\/meteo\/latina-lazio-allerta-arancione-28-gennaio-2026.html\" rel=\"nofollow noopener\" target=\"_blank\">allerta meteo per la giornata di domani, <\/a>mercoled\u00ec 28 gennaio.<\/p>\n<p>Secondo l\u2019avviso si prevede una allerta per criticit\u00e0 idrogeologica gialla su tutte le zone di allerta del Lazio e una allerta per criticit\u00e0 idraulica di colore giallo su buona parte della regione e arancione sulle zone di allerta E &#8211; Aniene, F &#8211; Bacini Costieri Sud, e G &#8211; Bacino del Liri (come si vede nella tabella in basso). Prevista una allerta gialla su tutto il Lazio anche per il vento.\u00a0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/01\/allerta-meteo-lazio-28-gennaio-2026.jpg\" alt=\"Allerta meteo Lazio 28 gennaio 2026\" title=\"Allerta meteo Lazio 28 gennaio 2026\"\/><\/p>\n<p>Come detto in queste ore i sindaci di alcuni centri della provincia stanno predisponendo le ordinanze per la chiusura delle scuole. Lo hanno deciso, tra gli altri, i primi cittadini di Minturno, Formia, Gaeta, Fondi e Castelforte, ma anche di Terracina e Sabaudia. Come spiega il sindaco di Gaeta Cristian Leccese in un video pubblicato sui social: \u201cAbbiamo appena predisposto l\u2019ordinanza per l\u2019apertura del Coc e contestualmente stiamo predisponendo la chiusura delle scuole. Lo abbiamo condiviso con gli altri colleghi sindaci del Golfo. Per prudenze e precauzione abbiamo deciso quindi di chiudere le scuole\u201d ha detto il sindaco Leccese annunciando l\u2019ordinanza.<\/p>\n<blockquote class=\"instagram-media\" style=\"background-color:#FFF;border-radius:3px;border-width:0;box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15);margin:1px;max-width:540px;min-width:326px;padding:0;width:calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DUBe-uZCCZJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\"\/>\n<p>Lo stesso \u00e8 stato fatto anche da altri Comuni che nel tardo pomeriggio hanno annunciato le apposite ordinanze, come quelli di Minturno, dove \u00e8 stato annullato anche il mercato settimanale di Scauri, e di Formia dove oltre alla sospensione delle attivit\u00e0 scolastiche \u00e8 prevista anche la chiusura di cimiteri, parchi pubblici e mercati. Scuole chiuse con apposita ordinanza anche a Fondi dove sono state sospese anche tutte le attivit\u00e0 di pubblico intrattenimento all\u2019aperto.<\/p>\n<p>Anche il sindaco di Terracina Francesco Giannetti ha firmato l\u2019ordinanza per la chiusura di tutte le scuole di ogni ordine e grado e ha attivato a partire dall\u20191 e per tutta la durata dell\u2019emergenza il Centro Operativo Comunale di Protezione Civile \u201cal fine di assicurare, nell&#8217;ambito del territorio del Comune di Terracina la direzione e il coordinamento delle attivit\u00e0 e dei servizi di soccorso e di assistenza alla popolazione\u201d. L\u2019ordinanza \u00e8 stata formata in queste ore anche dal sindaco di Sabaudia, Alberto Mosca, disponendo la chiusura delle scuole \u201cal fine di garantire la sicurezza e l\u2019incolumit\u00e0 delle persone, in particolare degli studenti\u201d. Ordinanze analoghe sono state emanate anche a San Felice Circeo, Monte San Biagio, Santi Cosma e Damiano e Spigno Saturnia; a Itri disposta la chiusura oltre che di tutte le scuole di ogni ordine e grado anche di tutte le strutture a uso sportivo, siti culturali, cimitero, parchi e giardini pubblici, centro anziani e centro diurno.\u00a0<\/p>\n<p>Articolo in aggiornamento<\/p>\n<p>      <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Scuole chiuse in alcuni comuni della provincia di Latina per il maltempo. Le notizie si stanno diffondendo in&hellip;\n","protected":false},"author":3,"featured_media":326248,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[191606,46234,14,29444,8,1537,90,89,11225,437,7,15,82,9,83,10,438,71072,13,11,80,84,12,81,85],"class_list":{"0":"post-326247","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-28-gennaio-2026","9":"tag-allerta-arancione","10":"tag-cronaca","11":"tag-dove","12":"tag-headlines","13":"tag-it","14":"tag-italia","15":"tag-italy","16":"tag-latina","17":"tag-maltempo","18":"tag-news","19":"tag-notizie","20":"tag-notizie-di-cronaca","21":"tag-notizie-principali","22":"tag-notiziedicronaca","23":"tag-notizieprincipali","24":"tag-provincia","25":"tag-scuole-chiuse","26":"tag-titoli","27":"tag-ultime-notizie","28":"tag-ultime-notizie-di-cronaca","29":"tag-ultime-notizie-e-news-di-oggi","30":"tag-ultimenotizie","31":"tag-ultimenotiziedicronaca","32":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115969342993152629","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/326247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=326247"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/326247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/326248"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=326247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=326247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=326247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}