{"id":326653,"date":"2026-01-28T04:52:11","date_gmt":"2026-01-28T04:52:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/326653\/"},"modified":"2026-01-28T04:52:11","modified_gmt":"2026-01-28T04:52:11","slug":"spalletti-conte-polemica-sugli-ex-campioni-ditalia-il-tecnico-del-napoli-serve-rispetto-la-replica-credevo-fosse-ia","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/326653\/","title":{"rendered":"Spalletti-Conte, polemica sugli \u00abex campioni d&#8217;Italia\u00bb. Il tecnico del Napoli: \u00abServe rispetto\u00bb. La replica: \u00abCredevo fosse IA\u00bb"},"content":{"rendered":"<p>La sfida tra Juventus e Napoli prosegue. O meglio, quella tra <strong><a href=\"https:\/\/www.ilmessaggero.it\/t\/spalletti\" rel=\"nofollow noopener\" target=\"_blank\">Spalletti<\/a><\/strong> e <strong><a href=\"https:\/\/www.ilmessaggero.it\/t\/conte\" rel=\"nofollow noopener\" target=\"_blank\">Conte<\/a><\/strong>. Dopo alcune tensioni pre e post gara, i due tecnici hanno continuato a lanciarsi frecciatine, arrivando oggi ad un vero e proprio scontro a distanza. Qualche settimana fa i primi segnali di nervosismo, con Spalletti che ha risposto al collega sulle differenze strutturali che ci sono tra le due societ\u00e0: \u00abConte ha ragione, da un punto di vista tecnico non ho niente da invidiare alla sua squadra. La mia ha le carte in regola per giocare contro chiunque. Dal punto di vista strutturale ha di nuovo ragione: quando sono arrivato qui ho trovato la barriera per battere le punizioni che si muove, ma a Napoli avevo quelle che rimangono ferme\u00bb . Da quel momento c&#8217;\u00e8 stata grande attesa per la gara dello Stadium, dove hanno poi nettamente prevalso i padroni di casa. Dopo la partita, gli animi hanno iniziato ad accendersi fino ad oggi, dove il vaso si \u00e8 definitivamente rotto.<\/p>\n","protected":false},"excerpt":{"rendered":"La sfida tra Juventus e Napoli prosegue. O meglio, quella tra Spalletti e Conte. Dopo alcune tensioni pre&hellip;\n","protected":false},"author":3,"featured_media":326654,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[2790,14,8,1537,90,89,119853,7,15,82,9,83,10,1686,24806,191730,13,11,80,84,12,81,85],"class_list":{"0":"post-326653","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-conte","9":"tag-cronaca","10":"tag-headlines","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-juventus-napoli","15":"tag-news","16":"tag-notizie","17":"tag-notizie-di-cronaca","18":"tag-notizie-principali","19":"tag-notiziedicronaca","20":"tag-notizieprincipali","21":"tag-social","22":"tag-spalletti","23":"tag-spalletti-conte","24":"tag-titoli","25":"tag-ultime-notizie","26":"tag-ultime-notizie-di-cronaca","27":"tag-ultime-notizie-e-news-di-oggi","28":"tag-ultimenotizie","29":"tag-ultimenotiziedicronaca","30":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115970935501399177","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/326653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=326653"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/326653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/326654"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=326653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=326653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=326653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}