{"id":327627,"date":"2026-01-28T19:49:09","date_gmt":"2026-01-28T19:49:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/327627\/"},"modified":"2026-01-28T19:49:09","modified_gmt":"2026-01-28T19:49:09","slug":"messina-tre-cadaveri-crivellati-di-colpi-in-un-bosco-le-vittime-erano-uscite-per-una-battuta-di-caccia","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/327627\/","title":{"rendered":"Messina, tre cadaveri crivellati di colpi in un bosco. Le vittime erano uscite per una battuta di caccia"},"content":{"rendered":"<p>    di<br \/>\n    Redazione online<\/p>\n<p class=\"summary-art is-line-h-12\">L&#8217;episodio nel comune di Montagnareale. Indaga la procura di Patti<\/p>\n<p class=\"chapter-paragraph\">Tre cadaveri sono stati trovati a Montagnareale (Messina), in una zona boschiva di contrada Caristia. La segnalazione \u00e8 giunta al numero unico di emergenza 112. I corpi di tre uomini, stando alle prime informazioni, sarebbero stati crivellati da colpi d&#8217;arma da fuoco. I tre erano usciti stamattina per una battuta di caccia. Sono intervenuti i carabinieri e il magistrato di turno della Procura di Patti. Le tre vittime sono gi\u00e0 state identificate ma non sono state rese note le generalit\u00e0. Si tratterebbe di persone incensurate.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Tutti e tre le vittime sono state trovate con il fucile da caccia accanto. La zona in cui si trovavano i cadaveri, sulle montagne dei Nebrodi, \u00e8 molto impervia.\u00a0\u00c8 frequentata da appassionati di caccia al cinghiale o altre specie di fauna selvatica.\u00a0    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">notizia in aggiornamento\u00a0<\/p>\n<p class=\"is-last-update\" datetime=\"2026-01-28T20:29:52+01:00\">28 gennaio 2026 ( modifica il 28 gennaio 2026 | 20:29)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Redazione online L&#8217;episodio nel comune di Montagnareale. Indaga la procura di Patti Tre cadaveri sono stati trovati&hellip;\n","protected":false},"author":3,"featured_media":327628,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[3648,192373,6478,21974,2023,192374,192375,14,8,1537,90,89,5990,7,15,82,9,83,10,13,11,80,84,12,81,85,838],"class_list":{"0":"post-327627","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-battuta","9":"tag-battuta-caccia","10":"tag-caccia","11":"tag-cadaveri","12":"tag-colpi","13":"tag-crivellati","14":"tag-crivellati-colpi","15":"tag-cronaca","16":"tag-headlines","17":"tag-it","18":"tag-italia","19":"tag-italy","20":"tag-messina","21":"tag-news","22":"tag-notizie","23":"tag-notizie-di-cronaca","24":"tag-notizie-principali","25":"tag-notiziedicronaca","26":"tag-notizieprincipali","27":"tag-titoli","28":"tag-ultime-notizie","29":"tag-ultime-notizie-di-cronaca","30":"tag-ultime-notizie-e-news-di-oggi","31":"tag-ultimenotizie","32":"tag-ultimenotiziedicronaca","33":"tag-ultimenotizieenewsdioggi","34":"tag-vittime"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/115974462676741471","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/327627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=327627"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/327627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/327628"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=327627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=327627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=327627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}