{"id":334362,"date":"2026-02-02T06:09:09","date_gmt":"2026-02-02T06:09:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/334362\/"},"modified":"2026-02-02T06:09:09","modified_gmt":"2026-02-02T06:09:09","slug":"grammy-award-2026-contro-trump-la-protesta-per-lice-agli-oscar-della-musica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/334362\/","title":{"rendered":"Grammy Award 2026 contro Trump: la protesta per l&#8217;Ice agli Oscar della musica"},"content":{"rendered":"<p>Il presidente \u00e8 stato il convitato di pietra alla cerimonia. Il conduttore Noah: \u00abVuole la Groenlandia perch\u00e9 l&#8217;isola di Epstein non c&#8217;\u00e8 pi\u00f9\u00bb<\/p>\n<p>\u00abPrima di ringraziare Dio, dir\u00f2 una cosa: <strong>ICE fuori<\/strong>. Non siamo selvaggi, non siamo animali, non siamo alieni. Siamo esseri umani e siamo americani\u00bb. <strong>Bad Bunny<\/strong> si prende l\u2019ovazione del pubblico alla <strong>Crypto.com Arena<\/strong> di <strong>Los Angeles<\/strong> mentre accetta il premio per il miglior album di urban music alla cerimonia dei <strong>Grammy<\/strong>. Tutta la serata, ancora in svolgimento, \u00e8 diventata <strong>un attacco al presidente degli Stati Uniti<\/strong> <a href=\"https:\/\/www.open.online\/temi\/donald-trump\/\" rel=\"nofollow noopener\" target=\"_blank\">Donald Trump<\/a> e alla sua politica. A partire dal conduttore<strong> Trevor Noah<\/strong>: \u00abOgni artista vuole vincere un <strong>Grammy <\/strong>quanto <strong>Trump <\/strong>vuole la <strong>Groenlandia<\/strong>, visto che l\u2019isola di <a href=\"https:\/\/www.open.online\/temi\/jeffrey-epstein\/\" rel=\"nofollow noopener\" target=\"_blank\">Epstein<\/a> non c\u2019\u00e8 pi\u00f9 e a lui ne serve un\u2019altra in cui andare in giro\u00bb.<\/p>\n<p>Grammy contro Trump<\/p>\n<p>Il <strong>Grammy <\/strong>per la <strong>miglior canzone dell\u2019anno<\/strong> \u00e8 andato a <a href=\"https:\/\/www.open.online\/temi\/billie-eilish\/\" rel=\"nofollow noopener\" target=\"_blank\">Billie Eilish<\/a> con <strong>\u201cWildflower\u201d<\/strong>. E anche la cantante ha lanciato dal palco un messaggio a favore degli immigrati: \u00abNessuno \u00e8 illegale su una terra rubata\u00bb ai nativi americani. Il suo messaggio ha scatenato l\u2019ovazione della platea della arena di <strong>Los Angeles<\/strong>. \u00abDobbiamo continuare a combattere e a far sentire la nostra voce e protestare, le nostre voci contano e la gente conta\u00bb, ha concluso tra gli applausi. Un\u2019ovazione ha accolto invece l\u2019annuncio fatto dal conduttore quando ha detto che non era presente in platea <strong>Nicki Minaj<\/strong>, la rapper diventata una <strong>sostenitrice del presidente<\/strong>. La scelta ha deluso molti suoi fans e colleghi.<\/p>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p><a href=\"https:\/\/twitter.com\/JacobBaker613\/status\/2018133439191613552?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">February 2, 2026<\/a><\/p><\/blockquote>\n<p>Noah, alla sesta e ultima conduzione dei premi della musica, ha fatto notare che la rapper non era presente alla cerimonia. \u00abNon \u00e8 qui. \u00c8 ancora alla Casa Bianca con Donald Trump, a discutere di questioni molto importanti\u00bb. Nicki \u00e8 stata tra le poche star invitate alla prima del <a href=\"https:\/\/www.open.online\/2025\/12\/17\/melania-trump-documentario-amazon-bezos-donald-trump-rielezione-video\/\" rel=\"nofollow noopener\" target=\"_blank\">documentario<\/a> di <a href=\"https:\/\/www.open.online\/temi\/melania-trump\/\" rel=\"nofollow noopener\" target=\"_blank\">Melania Trump<\/a> gioved\u00ec al Kennedy center.<\/p>\n<p>Gli artisti e il presidente<\/p>\n<p>E ancora: la cantante di origine cubana <strong>Gloria Estefan<\/strong> parlando in sala stampa accanto al red carpet ha invitato i latinoamericani ad<strong> \u201calzare la voce\u201d<\/strong> contro politiche che ha definito disumane. \u00abNon credo che qualcuno direbbe che vogliamo un \u2018liberi tutti\u2019 alla frontiera\u00bb, ha commentato. \u00abMa quello che sta succedendo non riguarda i criminali. Queste sono persone che hanno famiglie e che contribuiscono a questo Paese da decenni. Bambini piccoli, ci sono centinaia di bambini nei centri di detenzione\u00bb. <strong>Kehlani<\/strong>, accettando il <strong>Grammy <\/strong>per la <strong>migliore performance R&amp;B<\/strong>, ha concluso il suo discorso invitando i presenti nella sala \u00aba unirsi come comunit\u00e0 di artisti e a parlare apertamente contro quello che sta succedendo\u00bb.<\/p>\n<p>La spilla per Renee Good<\/p>\n<p><strong>Shaboozey<\/strong>, vincitore del Grammy per la migliore <strong>performance country<\/strong> duo\/gruppo per \u201cAmen\u201d con<strong> Jelly Roll<\/strong>, ha brindato agli immigrati che, ha detto, \u00abhanno costruito questo Paese, letteralmente\u00bb. Kehlani \u00e8 tra gli artisti che indossano <strong>una spilla con la scritta \u201cIce Out\u201d<\/strong>, assieme a<strong> Justin Vernon <\/strong>della band indie <strong>Bon Iver<\/strong> e la cantante jazz <strong>Samara Joy<\/strong>. La campagna di sensibilizzazione \u00e8 stata lanciata ai <strong>Golden Globes<\/strong>, dove <strong>Olivia Rodrigo, Ariana Grande e Jean Smart<\/strong> erano tra coloro che indossavano spille con quel messaggio o con la scritta <strong>\u201cBe Good\u201d<\/strong>, un riferimento a <a href=\"https:\/\/www.open.online\/2026\/01\/08\/renee-nicole-good-uccisa-minneapolis-agenti-ice\/\" rel=\"nofollow noopener\" target=\"_blank\">Renee Good<\/a>, la donna di <strong>37 anni<\/strong> uccisa a sangue freddo a <strong>Minneapolis <\/strong>da un agente dell\u2019Ice.<\/p>\n<p>I premi<\/p>\n<p>Bad Bunny ha vinto il Grammy per la migliore interpretazione di musica globale con il brano \u201cEoO\u201d, battendo, tra gli altri, <strong>\u201cCantando en el Camino\u201d di Ciro Hurtado e \u201cJerusalema\u201d di Ange\u2019lique Kidjo<\/strong>. Uno dei primi premiati \u00e8 il <strong>Dalai Lama<\/strong>, che ha vinto un Grammy per la sua narrazione dell\u2019audiolibro <strong>\u201cMeditations: The Reflections of His Holiness the Dalai Lama\u201d<\/strong>. <strong>Kendrick Lamar<\/strong> ha vinto il Grammy per l\u2019album rap <strong>\u2018GNX\u2019.<\/strong> La cantante britannica <strong>Olivia Dean<\/strong> ha trionfato per il miglior debutto. Dean ha scalato le classifiche con il pezzo<strong> \u201cMan I Need\u201d<\/strong>.<\/p>\n<p>E ancora: una molto emozionata <a href=\"https:\/\/www.open.online\/temi\/lady-gaga\/\" rel=\"nofollow noopener\" target=\"_blank\">Lady Gaga<\/a> ha vinto il Grammy come miglior album pop vocal con \u201cMayhem\u201d. Anche <strong>Steven Spielberg<\/strong> \u00e8 entrato a far parte del club <strong>Egot<\/strong>, quello che raccoglie i vincitori dei premi <strong>Emmy, Grammy, Oscar e Tony Awards<\/strong>. Il regista 76enne si \u00e8 infatti aggiudicato un Grammy con il film \u201cMusic by John Williams\u201d e va a completare la sua bacheca composta anche da tre Oscar, quattro Primetime Emmy (e molti altri Emmy diurni) e un Tony vinto come produttore del musical \u201cA Strange Loop\u201d.<\/p>\n<p>L\u2019attrazione<\/p>\n<p>Ai Grammy il trionfatore dell\u2019edizione 2025 <strong>Kendrick Lamar<\/strong> era arrivato con un record di nove candidature: ha vinto cinque statuette, tra cui miglior album rap per Gmx e miglior registrazione per il track Luther con Sza, che lo hanno portato a un totale di 27 statuette. Bad Bunny \u00e8 arrivato a quota tre e Lady Gaga due (tra cui miglior album pop per Mayhem) alla pari con Sza, Leon Thomas e Turnstile. Per i fan del cartone KPop Demon Hunters, \u201cGolden\u201d non ha deluso conquistando il primo Grammy per il KPop (miglior canzone scritta per un\u2019opera audiovisiva).<\/p>\n<p> L\u2019attrazione della serata \u00e8 stata il gigantesco blocco di <strong>formaggio cheddar del Wisconsin<\/strong> \u201cscolpito\u201d con gli omaggi a tutti i generi musicali in gara, dall\u2019hiphop al pop: pesa duecentonovanta chili e ha un colore gialloarancio.<\/p>\n<p>\t\t<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Il presidente \u00e8 stato il convitato di pietra alla cerimonia. Il conduttore Noah: \u00abVuole la Groenlandia perch\u00e9 l&#8217;isola&hellip;\n","protected":false},"author":3,"featured_media":334363,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[8133,2017,5313,5295,195603,195604,8807,20155,21758,143935,788,57290,2942,1621,1620,818,8240,15948,195625,92766,18049,13035,1113,206,76351,203,6805,2097,21771,60405,195626,195623,195627,195628,42328,195629,195630,3737,49227,204,10714,195631,1537,90,89,195632,13021,6411,2197,2051,1539,43037,651,195624,13736,135,379,2200,195622,4969],"class_list":{"0":"post-334362","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-album","9":"tag-americani","10":"tag-angeles","11":"tag-arena","12":"tag-arena-los","13":"tag-arena-los-angeles","14":"tag-artisti","15":"tag-attrazione","16":"tag-bad","17":"tag-bad-bunny","18":"tag-bambini","19":"tag-bunny","20":"tag-cantante","21":"tag-celebrita","22":"tag-celebrities","23":"tag-cerimonia","24":"tag-concluso","25":"tag-conduttore","26":"tag-dalai","27":"tag-dalai-lama","28":"tag-dean","29":"tag-diventata","30":"tag-donald","31":"tag-donald-trump","32":"tag-emmy","33":"tag-entertainment","34":"tag-epstein","35":"tag-far","36":"tag-good","37":"tag-grammy","38":"tag-grammy-miglior","39":"tag-grammy-migliore","40":"tag-grammy-migliore-performance","41":"tag-grammy-trump","42":"tag-groenlandia","43":"tag-groenlandia-isola","44":"tag-groenlandia-isola-epstein","45":"tag-ice","46":"tag-immigrati","47":"tag-intrattenimento","48":"tag-isola","49":"tag-isola-epstein","50":"tag-it","51":"tag-italia","52":"tag-italy","53":"tag-kehlani","54":"tag-lama","55":"tag-messaggio","56":"tag-miglior","57":"tag-migliore","58":"tag-musica","59":"tag-noah","60":"tag-oscar","61":"tag-ovazione","62":"tag-premi","63":"tag-presidente","64":"tag-trump","65":"tag-vinto","66":"tag-vinto-grammy","67":"tag-vuole"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/334362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=334362"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/334362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/334363"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=334362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=334362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=334362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}