{"id":341744,"date":"2026-02-07T00:52:10","date_gmt":"2026-02-07T00:52:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/341744\/"},"modified":"2026-02-07T00:52:10","modified_gmt":"2026-02-07T00:52:10","slug":"il-carico-di-armi-e-i-timori-di-una-nuova-ursa-major","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/341744\/","title":{"rendered":"il carico di armi e i timori di una nuova Ursa Major"},"content":{"rendered":"<p>L&#8217;allarme nel <a href=\"https:\/\/www.ilmessaggero.it\/t\/mar-tirreno\" rel=\"nofollow noopener\" target=\"_blank\">Mar Tirreno<\/a> \u00e8 scattato tre giorni fa quando la nave cargo russa <a href=\"https:\/\/www.ilmessaggero.it\/t\/sparta-iv\" rel=\"nofollow noopener\" target=\"_blank\">Sparta IV<\/a> ha invertito la sua rotta verso nord lasciando la tratta che l&#8217;avrebbe portata ad attraversare lo Stretto di Gibilterra puntando la costa est della <a href=\"https:\/\/www.ilmessaggero.it\/t\/sardegna\" rel=\"nofollow noopener\" target=\"_blank\">Sardegna<\/a>. <a class=\"link_item\" data-linked_from=\"null\" href=\"https:\/\/www.ilmessaggero.it\/schede\/nave_russa_sardegna_cambio_rotta_improvvisa_cosa_sta_succedendo-9338895.html\" rel=\"nofollow noopener\" target=\"_blank\"> Poi i suoi movimenti a dondolo, su e gi\u00f9 sempre in acque internazionali<\/a> ma comunque di fronte all&#8217;isola italiana. <a class=\"link_item\" data-linked_from=\"null\" href=\"https:\/\/www.ilmessaggero.it\/schede\/nave_russa_sparta_iv_sardegna_transponder_spenti_cacciatorpediniere_armi_a_bordo_cosa_sta_succedendo_tirreno-9341172.html\" rel=\"nofollow noopener\" target=\"_blank\"> L&#8217;arrivo del cacciatorpediniere Severomorsk<\/a>, affiancato dalla petroliera Kama indispensabile per il rifornimento, ha ulteriormente alzato la tensione e messo in moto le difese Nato con un aereo pattugliatore Atr P-72B della Guardia di Finanza decollato dall\u2019aeroporto di Pratica di Mare e <a class=\"link_item\" data-linked_from=\"null\" href=\"https:\/\/www.ilmessaggero.it\/italia\/nato_flotta_russa_marina_italiana_pedinata_cosa_succede-9341929.html\" rel=\"nofollow noopener\" target=\"_blank\"> con la nuova fregata della Marina Militare Spartaco Schergat<\/a>. Eppure, nonostante la risposta degli Alleati, la flotta russa non si \u00e8 mossa da l\u00ec. Perch\u00e9, quindi, si trova l\u00e0? <\/p>\n","protected":false},"excerpt":{"rendered":"L&#8217;allarme nel Mar Tirreno \u00e8 scattato tre giorni fa quando la nave cargo russa Sparta IV ha invertito&hellip;\n","protected":false},"author":3,"featured_media":341745,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[14,93,94,90794,3576,1537,90,89,2737,85893,3951,7,15,171,199204,170,11,84,91,12,85,92],"class_list":{"0":"post-341744","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-italia","8":"tag-cronaca","9":"tag-cronaca-italiana","10":"tag-cronacaitaliana","11":"tag-flotta-ombra-russa","12":"tag-guerra-ucraina","13":"tag-it","14":"tag-italia","15":"tag-italy","16":"tag-nato","17":"tag-nave-russa","18":"tag-navi-russe","19":"tag-news","20":"tag-notizie","21":"tag-russia","22":"tag-sparta-iv","23":"tag-ucraina","24":"tag-ultime-notizie","25":"tag-ultime-notizie-e-news-di-oggi","26":"tag-ultime-notizie-italia","27":"tag-ultimenotizie","28":"tag-ultimenotizieenewsdioggi","29":"tag-ultimenotizieitalia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116026615057744759","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/341744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=341744"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/341744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/341745"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=341744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=341744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=341744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}