{"id":363146,"date":"2026-02-21T02:58:19","date_gmt":"2026-02-21T02:58:19","guid":{"rendered":"https:\/\/www.europesays.com\/it\/363146\/"},"modified":"2026-02-21T02:58:19","modified_gmt":"2026-02-21T02:58:19","slug":"sarah-ferguson-dove-lex-moglie-del-principe-andrea-fuggita-negli-emirati-ma-nessuno-sa-dove-si-trova","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/363146\/","title":{"rendered":"Sarah Ferguson, dov&#8217;\u00e8 l&#8217;ex moglie del principe Andrea? Fuggita negli Emirati, ma nessuno sa dove si trova"},"content":{"rendered":"<p>Mentre l&#8217;ex marito, <a href=\"https:\/\/www.ilmessaggero.it\/t\/andrew-mountbatten-windsor\" rel=\"nofollow noopener\" target=\"_blank\">Andrew Mountbatten-Windsor<\/a>, \u00e8 stato\u00a0arrestato nella sua residenza nel Norfolk la mattina del suo 66esimo compleanno e\u00a0ora si trova\u00a0in custodia cautelare, la domanda che tutti si pongono \u00e8:\u00a0dov&#8217;\u00e8 <a href=\"https:\/\/www.ilmessaggero.it\/t\/sarah-ferguson\" rel=\"nofollow noopener\" target=\"_blank\">Sarah Ferguson<\/a>,\u00a0l&#8217;ex duchessa di York?\u00a0Nonostante in passato Fergie, avesse definito il rapporto con l&#8217;ex principe Andrea\u00a0come quello della \u201ccoppia divorziata pi\u00f9 felice del mondo\u201d, la situazione \u00e8 cambiata drasticamente. E ora cosa succeder\u00e0 a lei dopo che \u00e8 stato ampiamente dimostrato il suo stretto rapporto con Epstein?<\/p>\n<p>Fergie non appare in pubblico dal 25 settembre 2025, quando fu fotografata mentre lasciava la Royal Lodge. Fino a poco tempo fa, infatti, i due continuavano a vivere insieme nella residenza di Windsor, anche dopo trent\u2019anni dalla separazione. L\u2019arresto di Andrea \u2013 ottavo nella linea di successione al trono britannico- \u2013 segna una svolta senza precedenti. Gli sviluppi delle indagini rischiano infatti di avere ripercussioni significative anche su di lei, lasciando aperti numerosi interrogativi sul suo futuro.<\/p>\n<p>Fuggita negli Emirati Arabi? <\/p>\n<p>A Fergie, 66 anni, sono stati revocati i suoi titoli e le \u00e8 stato chiesto di lasciare la sua vecchia casa al Royal Lodge di Windsor, dove viveva insieme al suo ex coniuge, Andrea. Ma mentre il fratello di Re Carlo si \u00e8 rifugiato nel suo alloggio temporaneo nella tenuta di Sandringham, nulla si sa di\u00a0Sarah. Secondo il Daily Mail \u00e8\u00a0fuggita negli Emirati Arabi Uniti.\u00a0Pare anche che, prima del suo viaggio negli Emirati, la madre della principessa Beatrice e della principessa Eugenia abbia trascorso alcuni giorni con degli amici sulle Alpi francesi, in attesa di godersi un po&#8217; di sole invernale.\u00a0<\/p>\n<p>Le vacanze con la figlia <\/p>\n<p>Si dice che Sarah abbia trascorso del tempo con la figlia, la principessa Eugenia, che \u00e8 stata avvistata a Doha, in Qatar, mentre partecipava alla fiera d&#8217;arte di Basilea in qualit\u00e0 di direttrice della galleria d&#8217;arte Hauser &amp; Wirth. Secondo il Daily Mail, l&#8217;ex duchessa sta cercando di passare inosservata ed \u00e8 alla ricerca di un nuovo team di pubbliche relazioni che la aiuti a reinserirsi nella societ\u00e0 dopo che sono venuti alla luce i suoi presunti legami con il condannato per reati sessuali Jeffrey Epstein.\u00a0<\/p>\n<p>Dove andr\u00e0 ora?\u00a0 <\/p>\n<p>Il futuro di\u00a0Fergie \u00e8 pi\u00f9 incerto che mai dopo la notizia dell&#8217;arresto dell&#8217;ex principe.\u00a0 Tuttavia, una fonte ha detto a\u00a0HELLO!\u00a0\u00a0il mese scorso che non avrebbe accompagnato Andrew nel suo trasferimento a Norfolk. &#8220;Gli \u00e8 stata accanto in tutti questi anni, ma ora \u00e8 pronta a spiccare il volo&#8221;. Non si trasferir\u00e0 con lui nella nuova casa nella tenuta di Sandringham. Non si trasferir\u00e0 nella casa di Beatrice nelle Cotswolds, per\u00f2. La casa di Eugenie in Portogallo \u00e8 una delle possibili alternative, finch\u00e9 non trover\u00e0 un posto.&#8221;<\/p>\n<p>&#13;<br \/>\n                                \u00a9 RIPRODUZIONE RISERVATA&#13;<\/p>\n<p>&#13;<\/p>\n<p>\n                            Il punto serale sulle notizie del giorno<br \/>\n                            <b>Iscriviti<\/b> e ricevi le notizie via email\n                        <\/p>\n","protected":false},"excerpt":{"rendered":"Mentre l&#8217;ex marito, Andrew Mountbatten-Windsor, \u00e8 stato\u00a0arrestato nella sua residenza nel Norfolk la mattina del suo 66esimo compleanno&hellip;\n","protected":false},"author":3,"featured_media":363147,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[203,204,1537,90,89,208830,43252],"class_list":{"0":"post-363146","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-intrattenimento","8":"tag-entertainment","9":"tag-intrattenimento","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-principe-andrea-arrestato","14":"tag-sarah-ferguson"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116106382881461245","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/363146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=363146"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/363146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/363147"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=363146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=363146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=363146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}