{"id":380124,"date":"2026-03-04T13:02:15","date_gmt":"2026-03-04T13:02:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/380124\/"},"modified":"2026-03-04T13:02:15","modified_gmt":"2026-03-04T13:02:15","slug":"torino-ha-fame-di-basket-torino-oggi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/380124\/","title":{"rendered":"&#8220;Torino ha fame di basket&#8221;\u00a0&#8211;\u00a0Torino Oggi"},"content":{"rendered":"<p>La passione per il grande basket si \u00e8 accesa a Torino: sono stati <b>pi\u00f9 di 40 mila<\/b> gli spettatori alle <b>Final Eight<\/b> di basket nei quattro giorni della competizione. La Lega Basket Italia ha registrato ben 40.014 presenze totali, di cui 12.597 per la finale di domenica, un record assoluto per una finale di Coppa Italia. <a target=\"_blank\" href=\"https:\/\/www.torinoggi.it\/2026\/02\/17\/leggi-notizia\/argomenti\/eventi-11\/articolo\/final-eight-1.html\" rel=\"nofollow noopener\">L&#8217;obiettivo annunciato<\/a> \u00e8 stato superato, dimostrando che a Torino non c&#8217;\u00e8 spazio solo per calcio e tennis.&#13;<\/p>\n<p>Venerd\u00ec hanno popolato l&#8217;Inalpi Arena <b>ulteriori 3000 spettatori <\/b>&#8211; il massimo consentito per un evento gratuito &#8211; per la finale della IBSA NextGen Cup e la partita-spettacolo LBA Showtime Game, che ha visto sfidarsi Andrea Bargnani, Marco Belinelli e stelle dello sport e dello spettacolo come Gianluca Gazzoli, Pierluigi Pardo e molti altri. Sui canali LBA l&#8217;incontro ha generato 8,2 milioni di visualizzazioni.&#13;<\/p>\n<p><strong>Ritorno sul territorio di 12,5 milioni di euro<\/strong><\/p>\n<p>Dall&#8217;analisi compiuta da StageUp, <b>l&#8217;impatto economico stimato sul territorio \u00e8 stato di 12,5 milioni di euro<\/b>, con una crescita del +3,5% rispetto al 2025. Il dato relativo al moltiplicatore degli investimenti dei partner istituzionali (Regione Piemonte, Citt\u00e0 di Torino e Camera di commercio di Torino) ha raggiunto quota 18.5: ci\u00f2 significa che ogni 100 euro investiti ne sono rientrati 18.500. Lo scorso anno l\u2019indice si attestava a 17.9, mentre uno studio del 2023 sugli eventi sostenuti dalla Regione indicava un moltiplicatore medio pari a 12.0.&#13;<\/p>\n<p><strong>Gherardini: &#8220;Torino ha fame di basket&#8221;<\/strong><\/p>\n<p>&#8220;Va dato credito a chi mi ha preceduto ed alle scelte che sono state fatte \u2013 ha dichiarato il Presidente LBA <b>Maurizio Gherardini<\/b> in apertura della conferenza stampa che ha anticipato la finale \u2013 E dare il giusto merito a Torino, una citt\u00e0 che ha fame di basket ed un territorio che ha risposto magnificamente, sia a livello di istituzioni che di interesse e di pubblico. Un&#8217;iniziativa insolita come l\u2019LBA Showtime Game ha creato prima attesa e poi presenze, ennesima conferma che c&#8217;\u00e8 voglia di basket e di ci\u00f2 che sa generare anche fuori dal campo&#8221;.&#13;<\/p>\n<p><strong>Il futuro della Final Eight a Torino<\/strong><\/p>\n<p>Per la prossima stagione \u00e8 ancora tutto da decidere, ma l&#8217;organizzazione delle Final Eight a Torino in questi anni \u00e8 piaciuta alla Lega Basket: &#8220;Sono attualmente in corso dialoghi con gli Enti territoriali. Nelle prossime settimane \u00e8 previsto un debrief con le Istituzioni per valutare margini e volont\u00e0 di proseguire un rapporto di collaborazione. Ad oggi, si \u00e8 dimostrato virtuoso e vincente&#8221;.<\/p>\n<p style=\"margin-bottom:20px; font-size:70%;\"><b>Vuoi rimanere informato sul BASKET TORINO e dire la tua?<\/b><br \/>&#13;<br \/>\n        Iscriviti al nostro servizio gratuito! Ecco come fare:<br \/>&#13;<br \/>\n        &#8211; aggiungere alla lista di contatti WhatsApp il numero 0039 <b>347 966 6498<\/b><br \/>&#13;<br \/>\n        &#8211; inviare un messaggio con il testo <b>BASKET TORINO<\/b><br \/>&#13;<br \/>\n        &#8211; la doppia spunta conferma la ricezione della richiesta.<br \/>&#13;<br \/>\n        I messaggi saranno inviati in modalit\u00e0 broadcast, quindi nessun iscritto potr\u00e0 vedere i contatti altrui, il vostro anonimato \u00e8 garantito rispetto a chiunque altro.<br \/>&#13;<br \/>\n        TorinOggi.it li utilizzer\u00e0 solo per le finalit\u00e0 di questo servizio e non li condivider\u00e0 con nessun altro.<br \/>&#13;<br \/>\n        Per disattivare il servizio, basta inviare in qualunque momento un messaggio WhatsApp con testo STOP BASKET TORINO sempre al numero 0039 347 966 6498.<\/p>\n","protected":false},"excerpt":{"rendered":"La passione per il grande basket si \u00e8 accesa a Torino: sono stati pi\u00f9 di 40 mila gli&hellip;\n","protected":false},"author":3,"featured_media":380125,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1453],"tags":[1756,1757,73882,1537,90,89,245,244],"class_list":["post-380124","post","type-post","status-publish","format-standard","has-post-thumbnail","category-basket","tag-basket","tag-basketball","tag-final-eight","tag-it","tag-italia","tag-italy","tag-sport","tag-sports"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116171043324645894","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/380124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=380124"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/380124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/380125"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=380124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=380124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=380124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}