{"id":386898,"date":"2026-03-08T20:29:15","date_gmt":"2026-03-08T20:29:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/386898\/"},"modified":"2026-03-08T20:29:15","modified_gmt":"2026-03-08T20:29:15","slug":"troppi-rischi-per-gli-equipaggi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/386898\/","title":{"rendered":"troppi rischi per gli equipaggi\u00bb"},"content":{"rendered":"<p>\u00abOccorre prudenza, molta prudenza\u00bb. <a href=\"https:\/\/www.ilmattino.it\/t\/emanuele-grimaldi\" rel=\"nofollow noopener\" target=\"_blank\">Emanuele Grimaldi<\/a>, il presidente mondiale degli armatori, guarda alle dichiarazioni provenienti dal fronte iraniano\u00a0con molto distacco. \u00abNon basta dire colpiremo solo navi americane e israeliane, Hormuz per le navi degli altri Paesi \u00e8 aperto. O, almeno, non basta agli armatori <strong>che hanno a cuore innanzitutto la sorte dei loro equipaggi<\/strong>\u00bb.  <\/p>\n<p><p>APPROFONDIMENTI<\/p>\n<\/p>\n<p><strong>Lei come presidente dell\u2019International Chamber of Shipping lo ha sottolineato con chiarezz: prima di tutto proteggere gli equipaggi?<\/strong> <\/p>\n<p>\u00abE lo ripeto anche oggi. \u00c8 ingiusto e immorale esporre a rischio gente che sta solo svolgendo il proprio lavoro. Per questo ho rivolto anche un appello a tutti i Paesi, sono necessarie misure e garanzie per tutelare le loro vite\u00bb. <\/p>\n<p><a class=\"link_item\" data-linked_from=\"9402407\" href=\"https:\/\/www.ilmattino.it\/economia\/news\/la_grande_manila_nella_flotta_grimaldi_si_rafforza_legame_le_filippine-9297940.html\" rel=\"nofollow noopener\" target=\"_blank\">La Grande Manila nella flotta Grimaldi: \u00abSi rafforza il legame con le Filippine\u00bb<\/a><\/p>\n<p><strong>Insomma \u00e8 presto per parlare di Hormuz aperto?<\/strong> <\/p>\n<p>\u00abPrestissimo. Bisogna muoversi con prudenza, osservare l\u2019evolversi della situazione. Hormuz non \u00e8 un canale con la barriera, tu passi, tu no. La situazione \u00e8 molto diversa\u00bb. <\/p>\n<p><strong>Trenta chilometri di mare in larghezza, una sessantina in lunghezza, e poi comunque si navigherebbe in acque pericolose, visto che gli iraniani\u00a0sono arrivati a colpire basi americane fino a Cipro.<\/strong> <\/p>\n<p>\u00abEd \u00e8 per questo che dico che bisogna aspettare, valutare, capire. Insomma, ci vuole prudenza non dobbiamo correre rischi. E in mare i pericoli sono tanti\u00bb. <\/p>\n<p><strong>Intanto, per\u00f2, i prezzi del petrolio salgono.<\/strong> <\/p>\n<p>\u00abLa libert\u00e0 di navigazione dovrebbe essere un principio fondamentale della convivenza tra i popoli. Il commercio non deve essere ostaggio per ricattare questo o quel Paese. Invece, la prima cosa che si blocca \u00e8 il trasporto via mare. Abbiamo visto cosa \u00e8 successo con Suez, vediamo cosa sta succedendo con Hormuz. Poi si innestano le speculazioni, e i prezzi impazziscono\u00bb. <\/p>\n<p><strong>Questa volta, per\u00f2, almeno nelle intenzioni, gli iraniani\u00a0dicono che vogliono colpire solo i nemici.<\/strong> <\/p>\n<p>\u00abMa come si fa a distinguere la reale propriet\u00e0 di una nave. La bandiera esposta, spesso, \u00e8 quella del Paese dove \u00e8 registrata la nave. Le navi americane, ad esempio, sono pochissime quelle che navigano con la bandiera a stelle e strisce. E allora? Il drone o il missile pu\u00f2 distinguere quale Paese arma quella nave? Ci vuole tempo e prudenza, questo mi sento di dire\u00bb. <\/p>\n<p><a class=\"link_item\" data-linked_from=\"9402407\" href=\"https:\/\/www.ilmattino.it\/economia\/news\/guardia_costiera_in_arrivo_40_motovedette_cosi_piloda_fara_crescere_l_occupazione-9280563.html\" rel=\"nofollow noopener\" target=\"_blank\">Guardia Costiera, in arrivo 40 motovedette: cos\u00ec \u201cPiloda\u201d far\u00e0 crescere l&#8217;occupazione<\/a><\/p>\n<p><strong>Scorrendo Marine Traffic, si nota proprio un ingorgo di navi in attesa di attraversare Hormuz o di uscire. Di bandiere italiane ne sono state individuate solo due. Entrambe di armatori napoletani.<\/strong> <\/p>\n<p>\u00abLa met\u00e0 delle navi che battono bandiera italiana sono nostre, quindi anche il Gruppo Grimaldi ha una nave nell\u2019area. Per quanto riguarda la Grande Torino ho impartito precise disposizioni di prudenza affinch\u00e9 il personale di bordo sia protetto in ogni modo\u00bb.  <\/p>\n<p><strong>E non passano?<\/strong> <\/p>\n<p>\u00abAssolutamente no. Bisogna avere pazienza e muoversi, lo ripeto, con estrema prudenza\u00bb. <\/p>\n<p><strong>Aspettare, dunque?<\/strong> <\/p>\n<p>\u00abS\u00ec, vediamo come evolve la situazione. Intanto, se gli iraniani hanno detto il vero i primi a passare saranno certamente i cinesi. La Cina \u00e8 un Paese certamente non ostile all\u2019Iran. Stessa cosa vale per le navi russe. Ecco perch\u00e9 dico che la situazione va monitorata momento per momento\u00bb. <\/p>\n<p><a class=\"link_item\" data-linked_from=\"9402407\" href=\"https:\/\/www.ilmattino.it\/cambio_di_paradigma\/italia_porto_d_europa_napoli_e_mediterraneo_cruciali_per_lo_sviluppo-9168931.html\" rel=\"nofollow noopener\" target=\"_blank\">Intervista a Edoardo Rixi: \u00abItalia porto d\u2019Europa, Napoli e Mediterraneo cruciali per lo sviluppo\u00bb<\/a><\/p>\n<p><strong>Il vicepremier e ministro degli Esteri, Antonio Tajani, ha detto che Hormus va considerato chiuso, non formalmente ma sostanzialmente.<\/strong> <\/p>\n<p>\u00abS\u00ec. E ha anche aggiunto che oggi (ieri, ndr), da Hormuz sono passate solo due o tre navi. \u00c8 esattamente quello che ripeto io, lo stretto \u00e8 sostanzialmente chiuso a chi non vuole mettere a rischio la vita dei marittimi anche se questo, come ha sottolineato anche Tajani, provocher\u00e0 in prospettiva danni all&#8217;economia mondiale\u00bb. <\/p>\n<p><strong>Potrebbero servire le scorte?<\/strong> <\/p>\n<p>\u00abLa situazione \u00e8 talmente in rapida evoluzione che non serve neanche ragionare a medio termine. L\u2019International Chamber of Shipping, che ho l\u2019onore di presiedere, monitora attentamente l\u2019evolversi. I nostri associati ricevono aggiornamenti costantemente. Aggiornamenti che, poi, sono estesi all\u2019intera comunit\u00e0 marittima. Chi non vuole correre rischi, aspetta. Per ora non si pu\u00f2 fare altro\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00abOccorre prudenza, molta prudenza\u00bb. Emanuele Grimaldi, il presidente mondiale degli armatori, guarda alle dichiarazioni provenienti dal fronte iraniano\u00a0con&hellip;\n","protected":false},"author":3,"featured_media":386899,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,222246,1282,166,7,15,11,167,12,168,161,162,163],"class_list":{"0":"post-386898","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-emanuele-grimaldi","12":"tag-intervista","13":"tag-mondo","14":"tag-news","15":"tag-notizie","16":"tag-ultime-notizie","17":"tag-ultime-notizie-di-mondo","18":"tag-ultimenotizie","19":"tag-ultimenotiziedimondo","20":"tag-world","21":"tag-world-news","22":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116195450329860099","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/386898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=386898"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/386898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/386899"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=386898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=386898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=386898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}