{"id":387796,"date":"2026-03-09T11:49:12","date_gmt":"2026-03-09T11:49:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/387796\/"},"modified":"2026-03-09T11:49:12","modified_gmt":"2026-03-09T11:49:12","slug":"patty-pravo-divina-9-ciclone-malgioglio-75-il-disagio-di-giucas","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/387796\/","title":{"rendered":"Patty Pravo divina (9), ciclone Malgioglio (7,5), il disagio di Giucas"},"content":{"rendered":"<p>La puntata di\u00a0<strong>Che Tempo Che Fa<\/strong>\u00a0dell\u2019<strong>8 marzo<\/strong>, andata in onda nella serata della\u00a0<strong>Giornata Internazionale della Donna<\/strong>,<strong>\u00a0<\/strong>non poteva che aprirsi con una riflessione profonda. E cos\u00ec, in una\u00a0ricorrenza\u00a0spesso ridotta a vuoti simbolismi,\u00a0<strong>Fabio Fazio<\/strong>\u00a0sceglie la via dell\u2019educazione e della consapevolezza, invitando nuovamente\u00a0<strong>Gino Cecchettin<\/strong>, il padre di\u00a0<strong>Giulia<\/strong>\u00a0uccisa dal suo fidanzato\u00a0<strong>Filippo Turetta<\/strong>\u00a0a novembre 2023. Il suo intervento \u00e8 un monito: la violenza di genere non \u00e8 un evento isolato, ma il precipitato di una cultura che respiriamo ogni giorno.<\/p>\n<p>Ma\u00a0il salotto di Nove \u00e8 per definizione un carosello: un luogo dove il dolore della cronaca sfuma con eleganza nel glamour della musica, per poi precipitare nel surrealismo culinario del \u201cTavolo\u201d. Dalla celebrazione di una diva come Patty Pravo al caos piccante di Giucas Casella, ecco\u00a0il nostro pagellone dell\u20198 marzo.\n<\/p>\n<p>Massimo Lopez, il maestro del garbo<\/p>\n<p><strong>Voto: 8,5<\/strong><\/p>\n<p>Sulle note di\u00a0That\u2019s Life, <a href=\"https:\/\/dilei.it\/star-e-vip\/massimo-lopez\/\" rel=\"nofollow noopener\" target=\"_blank\">Massimo Lopez<\/a> entra in studio ricordandoci cos\u2019\u00e8 la vera classe televisiva. In procinto di debuttare con il suo nuovo spettacolo (dal 7 aprile nei teatri), l\u2019attore ha regalato una carrellata di aneddoti che sanno di \u201calbum di famiglia\u201d della TV italiana.<\/p>\n<p>Dalle imitazioni politiche un tempo \u201cproibite\u201d, come quella di Sandro Pertini, alla nuova esilarante versione di Papa Leone, Lopez\u00a0<strong>domina la scena<\/strong>. Ma \u00e8 nel racconto della sua infanzia \u201cmistica\u201d che\u00a0arriva dritto al\u00a0pubblico: il sogno di diventare campanaro o addirittura suora, con tanto di velo in testa e auto-punizioni a colpi di bacchettate sulle mani. Un talento che sembrava destinato a un grigio ufficio di banca e che invece \u00e8 esploso sul palco.\u00a0<strong>Certezza assoluta.<\/strong><\/p>\n<p>Patty Pravo, l\u2019icona oltre il tempo<\/p>\n<p><strong>Voto: 9<\/strong><\/p>\n<p>Direttamente da Sanremo 2026, <a href=\"https:\/\/dilei.it\/star-e-vip\/patty-pravo\/\" rel=\"nofollow noopener\" target=\"_blank\">Patty Pravo<\/a> entra in studio e lo spazio-tempo sembra curvarsi. Elegante, imperscrutabile, semplicemente <strong>LA Diva<\/strong>. Celebrare 60 anni di carriera partendo da\u00a0Ragazzo Triste\u00a0non \u00e8 da tutti, ma lei lo fa con la naturalezza di chi ha vissuto mille vite: dalla fuga a Londra a 15 anni ai giri in macchina per Roma con\u00a0<strong>Jimi Hendrix<\/strong>.<\/p>\n<p>La sua nuova sfida\u00a0\u00e8 quella di presentare il prossimo<strong>\u00a0album<\/strong>\u00a0in\u00a0<strong>quattro musei<\/strong>. Una\u00a0<strong>scelta\u00a0fatta guardando al futuro<\/strong>, come dopotutto ha sempre fatto nella sua carriera. Come aveva gi\u00e0 specificato a\u00a0Domenica In, questa decisione \u00e8 anche un modo per\u00a0<strong>riavvicinare i giovani alla bellezza e all\u2019arte<\/strong>, in un momento storico in cui abbiamo assoluto bisogno di riflettere e di saper guardare oltre.<\/p>\n<p>Cristiano Malgioglio, un ciclone di simpatia<\/p>\n<p><strong>Voto: 7,5<\/strong><\/p>\n<p>Se Patty Pravo \u00e8 la luna, misteriosa e distante, <a href=\"https:\/\/dilei.it\/star-e-vip\/cristiano-malgioglio\/\" rel=\"nofollow noopener\" target=\"_blank\">Cristiano Malgioglio<\/a> \u00e8\u00a0il suo esatto contrario.\u00a0L\u2019artista e paroliere arriva in studio\u00a0per fare una sorpresa alla sua amica Nicoletta, ma finisce per fagocitare la scena con un\u00a0one-man show\u00a0travolgente.<\/p>\n<p>Spazia dai complimenti a <strong>Lady Gaga<\/strong> all\u2019amore per <strong>Marlon Brando<\/strong>, fino al tentativo (fallito) di trascinare la Pravo nel deserto. Il contrasto tra la pacatezza di lei e l\u2019iperattivit\u00e0 di lui \u00e8 televisione purissima. Il momento cult? Quando propone all\u2019icona della musica italiana di andare a mangiare insieme \u201cinvoltini primavera\u201d al ristorante cinese.\u00a0<strong>Imprevedibile<\/strong>.<\/p>\n<p>Luciana Littizzetto scrive la sua letterina<\/p>\n<p><strong>Voto: 7<\/strong><\/p>\n<p><a href=\"https:\/\/dilei.it\/star-e-vip\/luciana-littizzetto\/\" rel=\"nofollow noopener\" target=\"_blank\">Luciana Littizzetto<\/a> arriva con una doppia missione:\u00a0<strong>analizzare l\u2019amore celebrato a Sanremo<\/strong>\u00a0(partendo dal trionfo di <strong>Sal Da Vinci<\/strong>) e rendere omaggio al repertorio rivoluzionario di Patty Pravo. Ha il merito di ricordare che brani come\u00a0La Bambola\u00a0o\u00a0Pensiero Stupendo\u00a0sono stati veri manifesti di\u00a0<strong>emancipazione femminile<\/strong>\u00a0e sdoganamento dei tab\u00f9 quando la societ\u00e0 era ancora immobile.<\/p>\n<p>Poi, virata brusca verso il quotidiano: ci presenta \u201cClocky\u201d, la sveglia infernale che scappa per la stanza costringendo anche i pi\u00f9 pigri ad alzarsi. \u201cBrutta come il peccato\u201d, la definisce lei. Un segmento divertente, anche se il passaggio dalla sociologia musicale alla sveglia rotolante ha lasciato un po\u2019 di spaesamento.\u00a0<strong>Energica.<\/strong><\/p>\n<p>Arisa e Orietta Berti, le signore del Festival<\/p>\n<p><strong>Arisa: 7\/Orietta Berti: 8<\/strong><\/p>\n<p><strong>Arisa<\/strong>\u00a0porta la sua\u00a0Magica Favola\u00a0e un racconto\u00a0toccante\u00a0del suo ultimo Festival vissuto accanto al pap\u00e0. Una nota di dolcezza che viene per\u00f2 subito \u201cspettinata\u201d dall\u2019arrivo di\u00a0<a href=\"https:\/\/dilei.it\/star-e-vip\/orietta-berti\/\" rel=\"nofollow noopener\" target=\"_blank\">Orietta Berti<\/a>.<\/p>\n<p>La \u201cLeonessa\u201d non ha peli sulla lingua: \u201cDiciamo una volta per tutte che a Sanremo non ci si diverte!\u201d. Orietta \u00e8 un fiume in piena e ne ha anche per il padrone di casa, rinfacciandogli di averla lasciata scalza sulle scale del Festival anni fa. Tra un \u201csei stato cattivo\u201d e l\u2019altro, scopriamo la sua nuova passione: il gin tonic. Non un gin tonic qualunque, ma varianti alla mimosa (per l\u20198 marzo) e addirittura al\u00a0<strong>lardo di Colonnata<\/strong>.\u00a0<strong>Punk vero.<\/strong><\/p>\n<p>Il Tavolo,\u00a0quando il caos diventa disagio<\/p>\n<p><strong>Voto: 5<\/strong><\/p>\n<p>Come di consueto, la puntata dell\u20198 marzo si \u00e8 conclusa con <strong>Il Tavolo<\/strong>. La<strong> discussione sui peperoncini<\/strong> di Vasto usati da Orietta per \u201cschiarirsi la voce\u201d \u00e8 degenerata quando\u00a0<strong>Giucas Casella<\/strong>, sfidato da Paolo Rossi, ha deciso di mangiarne uno intero.<\/p>\n<p>Il risultato \u00e8 impietoso.\u00a0Giucas Casella viene colto da un attacco di tosse violento, pezzi di peperoncino sputati ovunque e un senso di disagio palpabile in studio. La battuta di Fazio (\u201cCerca di soffocare in silenzio\u201d) ha provato a salvare il salvabile, ma il segmento \u00e8 durato decisamente troppo, trasformando la goliardia in un momento televisivo evitabile.\u00a0<strong>Troppo piccante<\/strong>.<\/p>\n<p class=\"tp04__text\">\n\t\t\t\tScopri i personaggi in trend, le storie del momento e molto altro.<br \/>Dove? Sul <a href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\">canale WhatsApp di DiLei!<\/a>\n\t\t\t<\/p>\n<p>\t\t\t<a class=\"buttonCall\" href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Seguici su WhatsApp\"><br \/>\n\t\t\t\tSeguici su WhatsApp<br \/>\n\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La puntata di\u00a0Che Tempo Che Fa\u00a0dell\u20198 marzo, andata in onda nella serata della\u00a0Giornata Internazionale della Donna,\u00a0non poteva che&hellip;\n","protected":false},"author":3,"featured_media":387797,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[6303,14,34711,222572,8,1537,90,89,7,15,82,9,83,10,21056,214,13,11,80,84,12,81,85],"class_list":{"0":"post-387796","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-che-tempo-che-fa","9":"tag-cronaca","10":"tag-fabio-fazio","11":"tag-giucas-casella","12":"tag-headlines","13":"tag-it","14":"tag-italia","15":"tag-italy","16":"tag-news","17":"tag-notizie","18":"tag-notizie-di-cronaca","19":"tag-notizie-principali","20":"tag-notiziedicronaca","21":"tag-notizieprincipali","22":"tag-patty-pravo","23":"tag-spettacolo","24":"tag-titoli","25":"tag-ultime-notizie","26":"tag-ultime-notizie-di-cronaca","27":"tag-ultime-notizie-e-news-di-oggi","28":"tag-ultimenotizie","29":"tag-ultimenotiziedicronaca","30":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116199067691319126","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/387796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=387796"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/387796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/387797"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=387796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=387796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=387796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}