{"id":387992,"date":"2026-03-09T14:58:15","date_gmt":"2026-03-09T14:58:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/387992\/"},"modified":"2026-03-09T14:58:15","modified_gmt":"2026-03-09T14:58:15","slug":"omicidio-villa-pamphili-disposta-la-perizia-psichiatrica-per-francis-kaufmann-il-tempo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/387992\/","title":{"rendered":"Omicidio Villa Pamphili, disposta la perizia psichiatrica per Francis Kaufmann \u2013 Il Tempo"},"content":{"rendered":"<p>            <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/03\/103953661-19d680d7-b4fd-4cfe-b6f2-d686b7d5c775.jpg\" class=\"lazy\" alt=\"\"\/><\/p>\n<p>        Foto: Lapresse<\/p>\n<p>\t\t\t\t\t\t\t<a href=\"\" class=\"author\">Gianni Di Capua<\/a><\/p>\n<p>\t\t\t\t\t\t\t09 marzo 2026<\/p>\n<p>Perizia psichiatrica per Francis Kaufmann, alias Rexal Ford, accusato del duplice omicidio della figlia Andromeda di 11 mesi e della compagna Anastasia Trofimova, trovate senza vita lo scorso 7 giugno a Villa Pamphili, a Roma. A deciderlo sono stati i giudici della Prima Corte di Assise che hanno sciolto la riserva accogliendo la richiesta di perizia della difesa per accertare la capacit\u00e0 di stare nel processo di Kaufmann. Incaricato Giovanni De Girolamo, consulente psichiatrico, che dovr\u00e0 depositare la consulenza in 30 giorni: la relazione medica verr\u00e0 discussa in contraddittorio tra le parti il 21 aprile, mentre il processo proseguir\u00e0 secondo il calendario gi\u00e0 stabilito.<\/p>\n<p>\u00a0<\/p>\n<p>\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.iltempo.it\/attualita\/2026\/03\/09\/news\/stakanovisti-corsia-medico-record-lavora-442-ore-mese-46719544\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.iltempo.it\/images\/2026\/03\/09\/081335791-44ca29d5-e374-4998-9ca1-9d0470fe4388.jpg\" class=\"lazy\" alt=\"Il medico dei record ha lavorato 442 ore al mese\" bad-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/07\/placeholder_iltempo.png\"\/><\/p>\n<p>\t\t\t\t\t\t\t\t<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Le accuse a Kaufmann sono quelle di duplice omicidio aggravato dai motivi futili e abietti, dalla minorata difesa, dalla relazione affettiva con la compagna e dalla discendenza in relazione alla figlia oltre all&#8217;occultamento di cadavere. Nell&#8217;udienza di questa mattina, davanti alla Corte, ha parlato Pamela Franconieri, Direttore dell&#8217;ufficio reati contro le persone dello Sco della polizia di stato: &#8220;Sono stata avvisata da un mio collega mentre non ero in servizio. Mi sono fatta accompagnare a Villa Pampili, il corpo era tra i rovi e appariva come un bambolotto &#8211; ha ricostruito attraverso delle diapositive -. Il piedino della bambina era pulito, mentre gli operanti erano sul posto, un&#8217;altra persona ha allertato la polizia della presenza di un sacco da cui fuoriusciva un arto\u201d. A sollecitare l&#8217;accertamento era stata la difesa di Kaufmann, che nel frattempo \u00e8 stato trasferito dal carcere di Rebibbia a quello di Regina Coeli.<\/p>\n<p>\u00a0<\/p>\n<p>\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.iltempo.it\/attualita\/2026\/03\/09\/news\/toghe-smemorate-magistrati-dimenticano-prigione-imputati-scarcerare-46718073\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.iltempo.it\/images\/2026\/03\/09\/063715644-362455c2-e9c8-4c9c-9afc-573c1e0b39a3.jpg\" class=\"lazy\" alt=\"Magistrati che dimenticano in cella imputati da scarcerare\" bad-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/07\/placeholder_iltempo.png\"\/><\/p>\n<p>\t\t\t\t\t\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Foto: Lapresse Gianni Di Capua 09 marzo 2026 Perizia psichiatrica per Francis Kaufmann, alias Rexal Ford, accusato del&hellip;\n","protected":false},"author":3,"featured_media":387993,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[14,93,94,19609,1537,90,89,7,15,987,11,84,91,12,85,92,37636],"class_list":{"0":"post-387992","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-italia","8":"tag-cronaca","9":"tag-cronaca-italiana","10":"tag-cronacaitaliana","11":"tag-francis-kaufmann","12":"tag-it","13":"tag-italia","14":"tag-italy","15":"tag-news","16":"tag-notizie","17":"tag-roma","18":"tag-ultime-notizie","19":"tag-ultime-notizie-e-news-di-oggi","20":"tag-ultime-notizie-italia","21":"tag-ultimenotizie","22":"tag-ultimenotizieenewsdioggi","23":"tag-ultimenotizieitalia","24":"tag-villa-pamphili"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116199811280209506","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/387992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=387992"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/387992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/387993"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=387992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=387992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=387992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}