{"id":396389,"date":"2026-03-15T01:37:14","date_gmt":"2026-03-15T01:37:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/396389\/"},"modified":"2026-03-15T01:37:14","modified_gmt":"2026-03-15T01:37:14","slug":"squadra-bene-comune-dobbiamo-andare-in-champions-se-resto-lintenzione-e-quella","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/396389\/","title":{"rendered":"\u00abSquadra bene comune. Dobbiamo andare in Champions. Se resto? L&#8217;intenzione \u00e8 quella\u00bb"},"content":{"rendered":"<p>\n                            Ogni giorno le notizie della tua squadra del cuore<br \/>\n                            <b>Iscriviti<\/b> e ricevi le notizie via email\n                        <\/p>\n<p>Ancora tre punti, e ancora 2-1. Il Napoli di <strong>Antonio Conte <\/strong>sembra ormai affezionato a questo risultato, che gli ha regalato nove punti nelle ultime tre partite. Questa volta, \u00e8 il Napoli ad andare in svantaggio, con <strong>Siebert<\/strong>, ma poi ci pensano <strong>Hojlund <\/strong>prima e <strong>Politano <\/strong>poi a togliere le castagne dal fuoco e a regalare la vittoria a mister Conte, che ora \u00e8 a -9 dalla vetta.<\/p>\n<p>&#13;<\/p>\n<p>APPROFONDIMENTI<\/p>\n<p>&#13;<br \/>\n    &#13;<\/p>\n<p>Queste le parole di <strong>Conte <\/strong>dopo la partita:\u00a0\u00abNon guardo le statistiche, preferisco concentrarmi sul lavoro da fare. Scoprire che la mia media punti \u00e8 di <strong>2.21<\/strong> e stare davanti a grandissimi allenatori non pu\u00f2 che riempirmi di soddisfazione. Quando Banda si \u00e8 accasciato a terra ero l\u00ec. Mi stavo avvicinando perch\u00e8 stavo preparando la barriera e ho visto che si stava accasciando. <strong>Quando ha messo le mani sul petto mi sono scaraventato in campo.<\/strong> Mi auguro che stia bene e che si riprenda presto. <\/p>\n<p>Stiamo parlando di un giocatore forte. La moglie \u00e8 incinta e gli auguriamo il meglio per tutto\u00bb.<\/p>\n<p><a class=\"link_item\" data-linked_from=\"9415662\" href=\"https:\/\/www.ilmattino.it\/schede\/napoli_lecce_malore_in_campo_per_banda_come_sta_il_giocatore-9416096.html\" rel=\"nofollow noopener\" target=\"_blank\">Napoli-Lecce, malore in campo per Banda: come sta il giocatore<\/a><\/p>\n<p>\u00abLa mia formazione? Quelle che mi fate vedere sono interessanti. Avere un play in uno dei centrocampisti \u00e8 pi\u00f9 consona come situazione. Avere due assaltatori come <strong>Anguissa <\/strong>e <strong>McTominay <\/strong>la vedo meno. Anche se durante una partita si pu\u00f2 mettere gente strutturata. Noi stiamo recuperando dei giocatori che sono stati fuori per tanti mesi, non possiamo pensare che tornano e abbiamo gi\u00e0 la condizione. Sono giocatori forti, ma bisogna dargli tempo di riabituarsi. Loro devono avere fiducia di quello che vedo e di quello che sento. Il bene comune deve essere il Napoli, non ci devono essere egoismi. Alla fine del primo tempo ho inserito un giocatore che era fuori da un mese e uno da 4 mesi e mezzo. Se c&#8217;\u00e8 da giocare pochi minuti tutti lo devono fare. Dobbiamo centrare la qualificazione in Champions\u00bb, ha continuato Conte dopo un siparietto con Ferrara e Giaccherini.<\/p>\n<p><strong>Queste le parole di Conte in conferenza:\u00a0<\/strong>\u00abQuando eravamo in campo Banda mi ha detto che aveva male al petto, queste cose vanno fuori dal calcio. Mi sono spaventato e gli auguriamo il meglio, sua aspetta anche un bambino. Il Lecce \u00e8 partito forte, potevamo fare meglio sui corner. Non stiamo facendo bene nella fase difensiva sui calci d&#8217;angolo. <strong>Loro erano in ottima salute ed sono allenati da un grande allenatore. <\/strong>Nel secondo tempo c&#8217;\u00e8 stata un&#8217;altra partita. Abbiamo voluto andare a prenderci la vittoria in maniera ragionata. Dobbiamo continuare e andare avanti\u00bb.<\/p>\n<p>\u00ab<strong>Napoli a due facce stasera?<\/strong> Stanno recuperando dei calciatori che sono stati fuori per tantissimo tempo. Non possono essere sempre al 100%. Possono diventare un problema. Oggi <strong>Anguissa <\/strong>\u00e8 partito dall&#8217;inizio, ma poi l&#8217;ho tolto all&#8217;intervallo. Prima di entrare nella giusta intensit\u00e0 ci vuole tempo e io devo essere bravo. I ragazzi devono avere fiducia. Devo cercare il fare il bene comune, che si chiama Napoli. Io ho dei ragazzi seri. Devono sapere che devono lavorare per avere i 95&#8242; minuti nelle gambe. <strong>Hojlund<\/strong>? Sicuramente \u00e8 cresciuto tanto. Da poco ha compiuto 23 anni. Pu\u00f2 migliorare in tante cose, come i colpi di testa, ma ha enormi margini di crescita. Questa settimana \u00e8 stato a casa qualche giorno ha causa della dissenteria. <strong>Ma oggi \u00e8 un giocatore importante<\/strong>. Fa reparto e lavora per tutta la partita. Deve rimanere umile e dipende da lui dove deve arrivare\u00bb.<\/p>\n<p>\u00abIo quando ho firmato l&#8217;ho fatto per tre anni. Il progetto sarebbe di tre anni. Quando sono arrivato al Napoli dissi che volevo lasciare delle fondamenta solide. Siamo al secondo anno e abbiamo vinto due trofei e giocato la Champions. Sento gli allenatori dei top club che mettono come obiettivo la Champions. Se lo fanno loro, figuriamoci se non dobbiamo farlo noi, visto che parliamo di valori patrimoniali diversi. Ci incontreremo con il presidente e faremo le valutazioni di questi due anni. Se saremo contenti continueremo. Io sono uno che non lega il Napoli al proprio contratto. Se non ci dovesse essere pi\u00f9 sintonia, saluter\u00f2 con grande affetto. Io qui mi trovo benissimo, anche la mia famiglia. La voglia sarebbe quella di continuare, se ci saranno i presupposti lo faremo. So che io porto aspettativa e porto richiesta. Per i media, per le altre squadre. Io devo arrivare primo o secondo, cos\u00ec dice la storia. Gli altri si stanno preparando per i fuochi d&#8217;artificio e noi cercheremo di rispondere sul campo\u00bb, ha concluso Conte.<\/p>\n","protected":false},"excerpt":{"rendered":"Ogni giorno le notizie della tua squadra del cuore Iscriviti e ricevi le notizie via email Ancora tre&hellip;\n","protected":false},"author":3,"featured_media":396390,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176],"tags":[11807,1537,90,89,225606,251,245,244],"class_list":{"0":"post-396389","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport","8":"tag-antonio-conte","9":"tag-it","10":"tag-italia","11":"tag-italy","12":"tag-napoli-lecce","13":"tag-serie-a","14":"tag-sport","15":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116230635192461550","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/396389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=396389"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/396389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/396390"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=396389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=396389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=396389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}