{"id":399937,"date":"2026-03-17T12:40:23","date_gmt":"2026-03-17T12:40:23","guid":{"rendered":"https:\/\/www.europesays.com\/it\/399937\/"},"modified":"2026-03-17T12:40:23","modified_gmt":"2026-03-17T12:40:23","slug":"perche-sean-penn-non-era-presente-agli-oscar-2026","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/399937\/","title":{"rendered":"Perch\u00e9 Sean Penn non era presente agli Oscar 2026"},"content":{"rendered":"<p>La 98esima edizione degli Academy Awards sar\u00e0 ricordata per molti motivi, ma soprattutto, pi\u00f9 di ogni discorso strappalacrime, per l\u2019assenza di uno dei grandi nomi della serata. Quando\u00a0<strong>Sean Penn<\/strong>\u00a0\u00e8 stato eletto come vincitore del premio come\u00a0<strong>Miglior attore non protagonista<\/strong>\u00a0per la sua viscerale interpretazione in\u00a0Una battaglia dopo l\u2019altra, l\u2019applauso della platea del Dolby Theatre si \u00e8 mescolato a un senso di inevitabile dej\u00e0-v\u00f9.\u00a0Perch\u00e9 Sean Penn non c\u2019era.<\/p>\n<p>A fare le veci dell\u2019assente \u00e8 stato\u00a0<strong>Kieran Culkin<\/strong>, che con la sua nota ironia tagliente ha ritirato la statuetta commentando: \u201cPenn non \u00e8 qui perch\u00e9 non ha potuto o non ha voluto, quindi la prendo io\u201d. Una battuta che ha sciolto l\u2019imbarazzo, ma che ha lasciato una domanda\u00a0aleggiare nell\u2019aria: dove finisce l\u2019impegno civile e dove inizia la ribellione di uno degli ultimi \u201coutsider\u201d di Hollywood?\n<\/p>\n<p>Sean Penn diserta gli Oscar 2026, il motivo<\/p>\n<p>Secondo quanto filtrato dalle colonne del\u00a0New York Times, la motivazione ufficiale dietro l\u2019assenza sarebbe di natura umanitaria. <a href=\"https:\/\/dilei.it\/star-e-vip\/sean-penn\/\" rel=\"nofollow noopener\" target=\"_blank\">Sean Penn<\/a> si troverebbe in\u00a0<strong>Ucraina<\/strong>, un fronte che l\u2019attore frequenta ormai con costanza sin dall\u2019inizio del conflitto. Non \u00e8 un mistero che il suo\u00a0<strong>legame con la resistenza di Kiev<\/strong>\u00a0sia profondo, quasi viscerale: basti pensare alla\u00a0<strong>provocatoria dichiarazione<\/strong>\u00a0di voler<strong>\u00a0fondere i suoi vecchi Oscar<\/strong>\u00a0per trasformarli in proiettili simbolici a sostegno dell\u2019esercito ucraino.<\/p>\n<p>Per Penn, evidentemente, il tappeto rosso degli <a href=\"https:\/\/dilei.it\/spettacolo\/oscar-2026-trionfo-paul-thomas-anderson-tutti-vincitori\/2211208\/\" rel=\"nofollow noopener\" target=\"_blank\">Oscar 2026<\/a> \u00e8 apparso <strong>troppo distante dalle trincee<\/strong>\u00a0che ha scelto di raccontare. La sua \u201caward season\u201d era stata del resto un lungo bollettino di assenze: ha disertato i\u00a0<strong>BAFTA<\/strong>, gli\u00a0<strong>Actor Awards<\/strong>\u00a0e persino quando si \u00e8 presentato ai\u00a0<strong>Golden Globe<\/strong>, lo ha fatto a modo suo, fumando con\u00a0nonchalance\u00a0all\u2019interno del Beverly Hilton prima di veder sfumare il premio.<\/p>\n<p>L\u2019imprevedibilit\u00e0 di un fuoriclasse<\/p>\n<p>Perch\u00e9 l\u2019assenza di Sean Penn pesa cos\u00ec tanto? Perch\u00e9, piaccia o meno, Penn \u00e8 uno dei pochi artisti possono trasformare una cerimonia patinata in un momento di\u00a0<strong>verit\u00e0 politica<\/strong>.<\/p>\n<p>Senza di lui, gli Oscar perdono quel\u00a0<strong>brivido di imprevedibilit\u00e0<\/strong>\u00a0che ha segnato la storia del cinema. Impossibile non ricordare il suo discorso per\u00a0Milk, quando trasform\u00f2 il ringraziamento in un manifesto per i diritti civili, o la difesa a spada tratta di <a href=\"https:\/\/dilei.it\/star-e-vip\/jude-law\/\" rel=\"nofollow noopener\" target=\"_blank\">Jude Law<\/a> contro le battute di Chris Rock. Anche i suoi\u00a0<strong>momenti pi\u00f9 controversi<\/strong>, come la celebre e discussa battuta sulla \u201cgreen card\u201d rivolta all\u2019amico\u00a0<strong>Alejandro I\u00f1\u00e1rritu<\/strong>\u00a0durante la vittoria di\u00a0Birdman, facevano parte di un codice comunicativo schietto, privo dei filtri del politicamente corretto che oggi dominano la scena.<\/p>\n<p>Il cinema di oggi tende spesso a proteggersi dietro<strong>\u00a0discorsi preconfezionati e sorrisi di circostanza<\/strong>. Sean Penn, decidendo di non esserci, ha ribadito la sua natura di uomo che mette\u00a0<strong>le proprie convinzioni davanti alla gloria personale<\/strong>. Sebbene\u00a0<strong>Javier Bardem<\/strong>\u00a0abbia provato a mantenere viva la fiamma dell\u2019impegno politico\u00a0<strong>invocando la pace in Palestina<\/strong>, la sua assenza si \u00e8 fatta sentire.<\/p>\n<p>Ormai \u00e8 chiaro che Sean Penn non appartenga pi\u00f9 (e forse non \u00e8 mai appartenuto) alle<strong>\u00a0logiche della passerella<\/strong>. La sua statuetta viagger\u00e0 verso casa, o forse verso qualche officina per diventare un simbolo di lotta, mentre noi restiamo a chiederci quanto manchi al cinema quella sua capacit\u00e0 di essere, allo stesso tempo, ruvido, scomodo e assolutamente necessario.<\/p>\n<p>\t\t\t\tScopri i personaggi in trend, le storie del momento e molto altro.<br \/>Dove? Sul <a href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\">canale WhatsApp di DiLei!<\/a><\/p>\n<p>\t\t\t<a class=\"buttonCall\" href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Seguici su WhatsApp\"><br \/>\n\t\t\t\tSeguici su WhatsApp<br \/>\n\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La 98esima edizione degli Academy Awards sar\u00e0 ricordata per molti motivi, ma soprattutto, pi\u00f9 di ogni discorso strappalacrime,&hellip;\n","protected":false},"author":3,"featured_media":399938,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[1621,1620,640,203,204,1537,90,89,13188,214],"class_list":{"0":"post-399937","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-celebrita","9":"tag-celebrities","10":"tag-cinema","11":"tag-entertainment","12":"tag-intrattenimento","13":"tag-it","14":"tag-italia","15":"tag-italy","16":"tag-sean-penn","17":"tag-spettacolo"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116244566982332735","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/399937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=399937"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/399937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/399938"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=399937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=399937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=399937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}