{"id":400445,"date":"2026-03-17T19:35:13","date_gmt":"2026-03-17T19:35:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/400445\/"},"modified":"2026-03-17T19:35:13","modified_gmt":"2026-03-17T19:35:13","slug":"fiorello-a-la-pennicanza-arriva-la-conferma-e-poi-lannuncio-a-sorpresa","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/400445\/","title":{"rendered":"Fiorello a La Pennicanza, arriva la conferma e poi l&#8217;annuncio a sorpresa"},"content":{"rendered":"<p><strong>Fiorello e Fabrizio Biggio<\/strong> hanno condotto una nuova puntata de La Pennicanza, marted\u00ec 17 marzo e finalmente \u00e8 arrivata la conferma. Tutto vero, timbrato e vidimato dai vertici Rai. Dal 18 marzo l\u2019appuntamento quotidiano raddoppia e <strong>La Pennicanza <\/strong>diventa anche <strong>La Mattinanza<\/strong> perch\u00e9 sbarca su Rai 2 alle 7.10 in replica, ma con anche contenuti inediti, creati appositamente per i pi\u00f9 piccoli che a quell\u2019ora si preparano per andare a scuola.<\/p>\n<p>Fiorello va in pensione<\/p>\n<p>Dopo aver confermato quanto comunicato il giorno prima <a href=\"https:\/\/dilei.it\/spettacolo\/fiorello-la-pennicanza-puntata-16-marzo-2026\/2211514\/\" rel=\"nofollow noopener\" target=\"_blank\">sul ritorno in tv,<\/a> nello stesso orario che era di Viva Rai2, tra le gag di giornata, <a href=\"https:\/\/dilei.it\/star-e-vip\/fiorello\/\" rel=\"nofollow noopener\" target=\"_blank\">Fiorello<\/a><strong> scherza sul suo futuro<\/strong>: \u201cDal 2027 si andr\u00e0 in pensione a 67 anni\u2026 <strong>tra poco pi\u00f9 di un anno sar\u00f2 pensionato!<\/strong> Vi posso dire che mi sento benissimo, \u00e8 una bellissima sensazione. Poi far\u00f2 un programma nuovo, La Pensionanza!\u201d.<\/p>\n<p>Fiorello, la telefonata (finta) di Pier Silvio Berlusconi<\/p>\n<p>Si passa quindi alla satira televisiva: \u201c<strong>Stasera inizia il GF Vip<\/strong>. I primi eliminati saranno costretti a guardare la fiction di Biggio\u2026\u201d, scherza. Poi in studio arriva la surreale telefonata di Piersilvio Berlusconi: \u201cIl GF Vip stasera dar\u00e0 una sonora randellata alla fiction di Rai1, che ricordiamo vede tra i protagonisti <strong>sedicenti attori<\/strong> come <a href=\"https:\/\/dilei.it\/star-e-vip\/fabrizio-biggio\/\" rel=\"nofollow noopener\" target=\"_blank\">Fabrizio Biggio<\/a>\u2026 a Rete4 non gli farebbero fare nemmeno la finta comparsa a Forum! Dispiace per il povero Lino Guanciale, per lui le porte in una delle nostre fiction turche sono sempre aperte!\u201d.<\/p>\n<p>Fiorello, l\u2019annuncio a sorpresa dopo la videochiamata di Annalisa<\/p>\n<p>Grande ospite in <strong>videochiamata in diretta \u00e8 Annalisa<\/strong>, che insieme a Fiorello canticchia il suo nuovo pezzo \u2018Canzone estiva\u2019 e racconta aneddoti della sua infanzia: \u201cUna delle canzoni che porto nel cuore \u00e8 \u2018Mare mare\u2019 di Luca Carboni, mi ricorda i viaggi con mia madre nei fine settimana per andare al mare, dall\u2019entroterra ligure\u2026\u201d. Dopo aver intonato il pezzo, lo showman la esalta: \u201cDevi fare un disco al telefono, la prossima volta\u2026\u201d. E la cantante replica: \u201c<strong>Facciamolo insieme, Fiore!<\/strong>\u201d.<\/p>\n<p>Ma non finisce qui, perch\u00e9 Fiorello anticipa una grande sorpresa: nella puntata di domani \u2013 in videocollegamento con La Pennicanza \u2013 ci sar\u00e0 <a href=\"https:\/\/dilei.it\/vip\/andrea-kimi-antonelli-chi-mamma-veronica\/2211689\/\" rel=\"nofollow noopener\" target=\"_blank\">Kimi Antonelli<\/a>, giovanissimo campione italiano di Formula 1.<\/p>\n<p>Fiorello, l\u2019ironia sull\u2019ad Rai<\/p>\n<p>Poi, l\u2019ironia sull\u2019assenza dell\u2019ad Rai, Giampaolo Rossi, all\u2019incontro in Vaticano con Papa Leone. \u00c8 lo stesso \u2013 surreale \u2013 pontefice ad intervenire: \u201cAvete per caso visto il vostro CEO? Noi lo stiamo ancora aspettando\u2026 forse \u00e8 rimasto chiuso nel suo ufficio a <strong>cercare di capire il regolamento di Canzonissima!\u201d<\/strong>.<\/p>\n<p>Fiorello e Fabrizio Biggio tornano con una nuova puntata de La Pennicanza mercoled\u00ec 18 marzo alle 13.45 su Rai Radio 2 e sul canale 202 del digitale terrestre. Ma prima ancora su Rai 2 alle 7.10 con il titolo <strong>La Mattinanza<\/strong>, nella trasmissione ci saranno contenuti inediti.<\/p>\n<p>\t\t\t\tScopri i personaggi in trend, le storie del momento e molto altro.<br \/>Dove? Sul <a href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\">canale WhatsApp di DiLei!<\/a><\/p>\n<p>\t\t\t<a class=\"buttonCall\" href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Seguici su WhatsApp\"><br \/>\n\t\t\t\tSeguici su WhatsApp<br \/>\n\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Fiorello e Fabrizio Biggio hanno condotto una nuova puntata de La Pennicanza, marted\u00ec 17 marzo e finalmente \u00e8&hellip;\n","protected":false},"author":3,"featured_media":400446,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[203,75700,27064,204,1537,90,89,214],"class_list":{"0":"post-400445","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-intrattenimento","8":"tag-entertainment","9":"tag-fabrizio-biggio","10":"tag-fiorello","11":"tag-intrattenimento","12":"tag-it","13":"tag-italia","14":"tag-italy","15":"tag-spettacolo"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116246198647248471","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/400445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=400445"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/400445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/400446"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=400445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=400445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=400445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}