{"id":401028,"date":"2026-03-18T04:35:19","date_gmt":"2026-03-18T04:35:19","guid":{"rendered":"https:\/\/www.europesays.com\/it\/401028\/"},"modified":"2026-03-18T04:35:19","modified_gmt":"2026-03-18T04:35:19","slug":"felicita-quotidiana-il-metodo-gasp-per-costruirla-e-stare-bene-anche-al-lavoro","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/401028\/","title":{"rendered":"Felicit\u00e0 quotidiana: il \u00abmetodo GASP\u00bb, per costruirla e stare bene (anche al lavoro)"},"content":{"rendered":"<p>La dipendenza digitale, che atrofizza il cervello<\/p>\n<p>Oggi la felicit\u00e0 \u00e8 messa alla prova anche dall\u2019<strong>abuso di tecnologia.<\/strong> \u00abStiamo <strong>atrofizzando il nostro cervello<\/strong> con un eccesso di digitale\u00bb, avverte Rolfo. Nelle aziende questo problema \u00e8 sempre pi\u00f9 evidente, tanto che molte organizzazioni partecipano a progetti chiamati palestre della mente, pensati per allenare nuovamente le capacit\u00e0 cognitive. L\u2019uso continuo di strumenti digitali rischia infatti di ridurre alcune funzioni del cervello. \u00abUn esempio classico \u00e8 il navigatore GPS: utilizzandolo ogni giorno <strong>si stimola meno<\/strong> l\u2019<strong>ippocampo<\/strong>, l\u2019area legata all\u2019orientamento e alla visione strategica. \u00abNon avere un cervello allenato, anche al di fuori dell\u2019ufficio, non aiuta la felicit\u00e0, perch\u00e9 diminuisce quella che in psicologia si chiama <strong>autoefficacia<\/strong>, cio\u00e8 la <strong>consapevolezza<\/strong> della <strong>capacit\u00e0<\/strong> che noi stessi abbiamo di <strong>risolvere un problema<\/strong> quando ci si para davanti\u00bb.<\/p>\n<p>Il metodo GASP per essere felici<\/p>\n<p>Rolfo riassume la felicit\u00e0 in un metodo semplice, che chiama <strong>GASP<\/strong>. Come spiega lui stesso (nell&#8217;ultimo libro <a data-offer-url=\"https:\/\/www.sperling.it\/libri\/le-aziende-felici-lo-fanno-meglio-il-budget-walter-rolfo\" class=\"external-link\" data-event-click=\"{&quot;element&quot;:&quot;ExternalLink&quot;,&quot;outgoingURL&quot;:&quot;https:\/\/www.sperling.it\/libri\/le-aziende-felici-lo-fanno-meglio-il-budget-walter-rolfo&quot;}\" href=\"https:\/\/www.sperling.it\/libri\/le-aziende-felici-lo-fanno-meglio-il-budget-walter-rolfo\" rel=\"nofollow noopener\" target=\"_blank\">Le aziende felici lo fanno meglio il Budget, Sperling &amp; Kupfer<\/a>): \u00abLa felicit\u00e0 \u00e8 semplice, se sai come costruirla\u00bb. Ecco allora quattro regole semplici, ma fondamentali, per regalarsi <strong>ogni giorno<\/strong> il proprio happy moment:<\/p>\n<p>La prima lettera, <strong>G<\/strong>, sta per godersela. \u00abGodetevi quello che avete, siate grati, ringraziate per il mondo in cui viviamo\u00bb, sottolinea. In altre zone e aree geografiche, le persone lottano per i bisogni essenziali, mentre noi viviamo in un contesto fortunato, in cui possiamo mangiare ogni giorno\u00bb. La <strong>gratitudine<\/strong> \u00e8 quindi il primo passo verso il benessere.<\/p>\n<p>La seconda lettera, <strong>A<\/strong>, significa accogliere. \u00abBisogna imparare ad <strong>accogliere<\/strong> anche i bassi della vita e a trasformarli in lezioni\u00bb, spiega Rolfo. I <strong>momenti negativi fanno parte della vita<\/strong>: accettarli e usarli come <strong>occasione di crescita<\/strong> permette di costruire, su quelle esperienze, nuovi momenti di soddisfazione.<\/p>\n<p>La terza lettera, <strong>S<\/strong>, \u00e8 sognare. \u00abI <strong>sogni<\/strong> sono la <strong>chiave<\/strong> per <strong>reagire<\/strong> nei momenti down\u00bb, dice. Quando ci si sente bloccati o senza via d\u2019uscita, i <strong>sogni funzionano come punti di appiglio<\/strong>: \u00bbSono i chiodi che pianti nel muro nero per romperlo e far entrare la luce\u00bb. E la raccomandazione \u00e8 anche \u00abdream big, sogna in grande: il sogno gi\u00e0 ti mette nella direzione giusta per raggiungerlo\u00bb.<\/p>\n<p>Infine la <strong>P<\/strong>, che indica le persone. \u00abNoi siamo le persone che frequentiamo\u00bb, ricorda Rolfo. Circondarsi di <strong>persone positive<\/strong>, che <strong>fanno stare bene<\/strong> e danno serenit\u00e0, \u00e8 fondamentale. Allo stesso tempo bisogna cercare di <strong>essere<\/strong> a propria volta una <strong>presenza positiva<\/strong> per chi ci sta accanto. Le relazioni giocano un ruolo decisivo: chi ha rapporti positivi in famiglia, tra amici e colleghi ha fino al <strong>47%<\/strong> di probabilit\u00e0 in pi\u00f9 di superare gli <strong>85 anni (come si legge sulla ricerca che l&#8217;Universit\u00e0 di Harvard rinnova dal 1938 (<a data-offer-url=\"https:\/\/www.adultdevelopmentstudy.org\/\" class=\"external-link\" data-event-click=\"{&quot;element&quot;:&quot;ExternalLink&quot;,&quot;outgoingURL&quot;:&quot;https:\/\/www.adultdevelopmentstudy.org\/&quot;}\" href=\"https:\/\/www.adultdevelopmentstudy.org\/\" rel=\"nofollow noopener\" target=\"_blank\">Harvard Study on Adult Development<\/a>)<\/strong>. <strong>Avere relazioni sane e significative<\/strong> \u00e8 quindi uno dei fattori pi\u00f9 importanti per il benessere e la longevit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"La dipendenza digitale, che atrofizza il cervello Oggi la felicit\u00e0 \u00e8 messa alla prova anche dall\u2019abuso di tecnologia.&hellip;\n","protected":false},"author":3,"featured_media":401029,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[1719,203,204,1537,90,89,12571],"class_list":{"0":"post-401028","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-intrattenimento","8":"tag-benessere","9":"tag-entertainment","10":"tag-intrattenimento","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-psicologia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116248322147375297","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/401028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=401028"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/401028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/401029"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=401028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=401028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=401028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}