{"id":40241,"date":"2025-08-11T00:10:12","date_gmt":"2025-08-11T00:10:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/40241\/"},"modified":"2025-08-11T00:10:12","modified_gmt":"2025-08-11T00:10:12","slug":"rifiuti-lanciati-dalle-auto-multe-fino-a-18-mila-euro-e-nelle-aree-protette-ce-anche-larresto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/40241\/","title":{"rendered":"Rifiuti lanciati dalle auto: multe fino a 18 mila euro e nelle aree protette c\u2019\u00e8 anche l\u2019arresto"},"content":{"rendered":"<p>            <a href=\"https:\/\/www.corriere.it\/firme\/alessio-ribaudo\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>                    <img decoding=\"async\" class=\"is-rounded\" alt=\"desc img\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/08\/alessio-ribaudo.jpg\"\/><br \/>\n                    di Alessio Ribaudo<\/p>\n<p>        <\/a><\/p>\n<p class=\"summary-art is-line-h-12\">Con il decreto legge, in vigore da sabato 9 agosto, le telecamere potranno incastrare gli automobilisti, pure senza fermo in strada. Arresto, sospensione della patente fino a sei mesi e confisca del veicolo per le violazioni pi\u00f9 gravi<\/p>\n<p class=\"chapter-paragraph\">Un fazzoletto di carta sporco avvolto nel suo involucro di plastica, una lattina o una bottiglia in vetro di una bevanda, un sacchetto di rifiuti. Un finestrino che si abbassa da un\u2019auto in sosta o, peggio, in corsa e, in pochi secondi, il rifiuto vola via lasciando dietro una cicatrice ambientale destinata a restare per anni. Succede, purtroppo, ovunque, ogni giorno: in citt\u00e0, lungo le provinciali, in autostrada.\u00a0Fino a venerd\u00ec scorso, per\u00f2, per multare l\u2019incivile serviva che una pattuglia lo cogliesse sul fatto e fermasse l\u2019auto.<\/p>\n<p>    Le nuove norme<\/p>\n<p class=\"chapter-paragraph\"><b>Da sabato 9 agosto, invece, sono tempi duri per chi viene sorpreso a sporcare<\/b>: con il decreto-legge 8 agosto 2025, n. 116 (Disposizioni urgenti per il contrasto alle attivita&#8217; illecite in\u00a0materia di rifiuti, per la bonifica dell&#8217;area denominata Terra dei\u00a0fuochi, nonch\u00e9 in materia di assistenza alla popolazione colpita da\u00a0eventi calamitosi), gettare un rifiuto da un mezzo a motore, in marcia o in sosta, pu\u00f2 costare davvero caro. <b>Anche se si pensa di averla scampata: il \u00abconto\u00bb, adesso, potrebbe arrivare anche casa, giorni dopo.\u00a0<\/b>\u00abFinalmente \u2014 commenta Luigi Altamura, comandante della polizia locale di Verona e referente Anci per Viabilit\u00e0 Italia \u2014 perch\u00e9 non \u00e8 solo una questione di decoro urbano: un rifiuto lanciato da un mezzo pu\u00f2 colpire un motociclista o costringere il veicolo dietro a una frenata improvvisa, provocando magari un tamponamento a catena. E, se finisce in un tombino o in un fosso, diventa un danno ambientale. Ora potremo intervenire in modo pi\u00f9 efficace grazie alle telecamere\u00bb.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p>    Le videocamere e gli arresti<\/p>\n<p class=\"chapter-paragraph\">Il testo del decreto, infatti, ha modificato anche l\u2019articolo 15 del Codice della strada: <b>\u00abPotremo acquisire e visionare immagini da qualsiasi impianto di videosorveglianza comunale, autostradale o privato, dentro e fuori i centri abitati, e usarle come prova per multare chi lancia rifiuti. <\/b>Basta un fotogramma nitido della targa, interrogare la banca dati della Motorizzazione, risalire al proprietario e la sanzione sar\u00e0 valida, a differenza del passato, anche senza il fermo dell\u2019auto e la contestazione immediata\u00bb.<br \/>Per un guidatore sar\u00e0 doloroso se verr\u00e0 \u00abpizzicato\u00bb mentre abbandona rifiuti non pericolosi da un mezzo a motore. <b>\u00abSe si tratta di un fazzoletto o di un mozzicone di sigaretta \u2014 avverte il comandante \u2014 la multa arriva fino a 1.188 euro, ma se si fa volare via una bevanda in lattina o in vetro dopo averla bevuta o un sacchetto di rifiuti \u00e8 prevista la segnalazione alla Procura con un\u2019ammenda da 1.500 a 18.000 euro.<\/b> Inoltre, <b>se il gesto avviene vicino a fiumi, in aree protette o in zone gi\u00e0 inquinate e comporta un pericolo concreto per le persone o per l\u2019ambiente, scatter\u00e0 l\u2019arresto, pure differito entro 48 ore, e una pena da sei mesi a cinque anni e mezzo. <\/b>Nei casi pi\u00f9 gravi, si arriva fino a sette anni\u00bb.<\/p>\n<p>    La sospensione della patente<\/p>\n<p class=\"chapter-paragraph\">C\u2019\u00e8 di pi\u00f9: <b>la sospensione della patente. \u00abPu\u00f2 essere comminata fino a sei mesi per le violazioni penali \u2014 dice Altamura \u2014 ma se il lancio o lo smaltimento illecito avvengono con un mezzo di un\u2019azienda privata pu\u00f2 scattare pure la confisca del veicolo<\/b>, salvo che appartenga a un terzo completamente estraneo\u00bb.\u00a0Il decreto non si ferma, quindi, alle cartacce lanciate dai guidatori ineducati. \u00abNo, anzi: colpisce chi usa auto o furgoni per scaricare rifiuti in campagne, zone industriali dismesse o aree naturali. Per i rifiuti pericolosi la reclusione va da uno a cinque anni, che salgono da un anno e sei mesi a sei anni nei casi aggravati. Se a violare la legge \u00e8 un dipendente con un mezzo aziendale, il titolare risponde per omessa vigilanza: fino a cinque anni e sei mesi\u00bb.<\/p>\n<p>    L&#8217;obiettivo<\/p>\n<p class=\"chapter-paragraph\">L\u2019obiettivo del decreto, per il colonnello Altamura, \u00e8 chiaro: \u00abPunire un comportamento incivile che pu\u00f2 mettere a rischio vite e ambiente\u00bb.<br \/>Insomma, chi finora ha contato sull\u2019assenza di divise nei dintorni per farla franca, adesso, dovr\u00e0 rassegnarsi: le telecamere saranno anche sentinelle invisibili, pronte a coglierli in fallo a qualsiasi ora, anche nei giorni di festa.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-08-10T22:16:21+02:00\">10 agosto 2025<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Alessio Ribaudo Con il decreto legge, in vigore da sabato 9 agosto, le telecamere potranno incastrare gli&hellip;\n","protected":false},"author":3,"featured_media":40242,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[2699,27139,4912,4924,1018,36386,453,2478,2765,22155,36387,1045,631,6154,35023,36388,14,2582,36389,724,36390,541,946,8,36391,1537,90,89,36392,1207,2346,1309,36108,7,15,82,9,83,10,809,6727,36393,36394,36395,14522,14659,36396,2433,2841,36397,13025,36398,10547,36385,17462,3726,7045,13,11,80,84,12,81,85,10556],"class_list":{"0":"post-40241","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-agosto","9":"tag-altamura","10":"tag-ambientale","11":"tag-ambiente","12":"tag-aree","13":"tag-aree-protette","14":"tag-arresto","15":"tag-arriva","16":"tag-auto","17":"tag-averla","18":"tag-bevanda","19":"tag-casi","20":"tag-cinque","21":"tag-comandante","22":"tag-confisca","23":"tag-confisca-veicolo","24":"tag-cronaca","25":"tag-decreto","26":"tag-decreto-legge","27":"tag-euro","28":"tag-fazzoletto","29":"tag-fermo","30":"tag-gravi","31":"tag-headlines","32":"tag-incivile","33":"tag-it","34":"tag-italia","35":"tag-italy","36":"tag-lattina","37":"tag-legge","38":"tag-materia","39":"tag-motore","40":"tag-multare","41":"tag-news","42":"tag-notizie","43":"tag-notizie-di-cronaca","44":"tag-notizie-principali","45":"tag-notiziedicronaca","46":"tag-notizieprincipali","47":"tag-obiettivo","48":"tag-patente","49":"tag-pericolosi","50":"tag-potremo","51":"tag-protette","52":"tag-qualsiasi","53":"tag-rifiuti","54":"tag-rifiuti-pericolosi","55":"tag-rifiuto","56":"tag-sabato","57":"tag-sabato-agosto","58":"tag-sacchetto","59":"tag-sacchetto-rifiuti","60":"tag-sospensione","61":"tag-sospensione-patente","62":"tag-sosta","63":"tag-strada","64":"tag-telecamere","65":"tag-titoli","66":"tag-ultime-notizie","67":"tag-ultime-notizie-di-cronaca","68":"tag-ultime-notizie-e-news-di-oggi","69":"tag-ultimenotizie","70":"tag-ultimenotiziedicronaca","71":"tag-ultimenotizieenewsdioggi","72":"tag-veicolo"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/40241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=40241"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/40241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/40242"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=40241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=40241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=40241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}