{"id":40939,"date":"2025-08-11T10:06:09","date_gmt":"2025-08-11T10:06:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/40939\/"},"modified":"2025-08-11T10:06:09","modified_gmt":"2025-08-11T10:06:09","slug":"frammenti-di-ferruccio-de-bortoli-vendi-chip-alla-cina-allora-dammi-una-percentuale","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/40939\/","title":{"rendered":"Frammenti di Ferruccio de Bortoli | Vendi chip alla Cina? Allora, dammi una percentuale"},"content":{"rendered":"<p class=\"chapter-paragraph\">L\u2019evoluzione creativa dei dazi americani \u00e8 nell\u2019accordo raggiunto poche ore fa tra i <b>colossi dei semiconduttori Nvidia e AMD e l\u2019amministrazione Trump<\/b>. Le due multinazionali americane potranno ottenere la licenza per vendere chip ai cinesi a patto di riconoscere il <b>15 per cento<\/b> dei relativi incassi all\u2019erario statunitense.<\/p>\n<p class=\"chapter-paragraph\">Il divieto all\u2019esportazione era stato imposto ai tempi della presidenza Biden per<b> impedire che Pechino potesse recuperare lo svantaggio, <\/b>vero o presunto,  accumulato nello sviluppo dell\u2019Intelligenza artificiale (Ai). Cio\u00e8 per ragioni strategiche, legate alla sicurezza nazionale. Con l\u2019accordo <a href=\"https:\/\/www.ft.com\/content\/cd1a0729-a8ab-41e1-a4d2-8907f4c01cac\" rel=\"nofollow noreferrer noopener\" target=\"_blank\">anticipato dal Financial Times <\/a>&#8211; e commentato all\u2019alba dalla newsletter di Franco Quillico del Politecnico di Milano &#8211; siamo entrati in una nuova dimensione della politica trumpiana.\u00a0<b>Si poteva far pagare il dazio ai cinesi anzich\u00e9 gravare un\u2019azienda statunitense<\/b> di una sorta di tassa per la concessione di una licenza, quasi un \u201cpizzo di Stato\u201d.\u00a0    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">L\u2019ordine liberal-democratico del mondo degli affari subisce un altro duro colpo. \u00abSiamo di fronte &#8211; commenta Alessandro Aresu, autore del fortunato saggio Geopolitica dell\u2019intelligenza artificiale (Feltrinelli) &#8211; a una ulteriore dimostrazione della logica transattiva-padronale di Trump.<b> Ogni licenza di esportazione ha un costo<\/b>. Le preoccupazioni strategiche legate alla sicurezza passano in secondo piano. La certezza del diritto svanisce anche perch\u00e9 non si capisce a questo punto quale sia il prezzo giusto di un bene. <b>Tutto \u00e8 trattabile<\/b>\u00bb.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-08-11T11:33:39+02:00\" content=\"2025-08-11\">11 agosto 2025, 11:16  &#8211; modifica il 11 agosto 2025 | 11:33<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019evoluzione creativa dei dazi americani \u00e8 nell\u2019accordo raggiunto poche ore fa tra i colossi dei semiconduttori Nvidia e&hellip;\n","protected":false},"author":3,"featured_media":13628,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[172],"tags":[579,178,36918,666,177,14661,4081,35219,28550,36919,667,668,1537,90,89,10564,36920,36917,36706,36921,23276,36922,4411],"class_list":["post-40939","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affari","tag-accordo","tag-affari","tag-amd","tag-artificiale","tag-business","tag-chip","tag-cinesi","tag-concessione","tag-esportazione","tag-incassi","tag-intelligenza","tag-intelligenza-artificiale","tag-it","tag-italia","tag-italy","tag-legate","tag-legate-sicurezza","tag-licenza","tag-nvidia","tag-nvidia-amd","tag-ottenere","tag-ottenere-licenza","tag-raggiunto"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/40939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=40939"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/40939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/13628"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=40939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=40939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=40939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}