{"id":410871,"date":"2026-03-24T16:39:10","date_gmt":"2026-03-24T16:39:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/410871\/"},"modified":"2026-03-24T16:39:10","modified_gmt":"2026-03-24T16:39:10","slug":"roma-gasperini-aspetta-i-rientri-soule-in-gruppo-kone","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/410871\/","title":{"rendered":"Roma, Gasperini aspetta i rientri: Soul\u00e9 in gruppo, Kon\u00e9&#8230;"},"content":{"rendered":"<p>Archiviato il successo sul Lecce prima della sosta,\u00a0<strong>la Roma potr\u00e0 ricaricare le batteria in vista del big match con l&#8217;Inter in programma alla ripresa,\u00a0<\/strong><a href=\"https:\/\/www.fantacalcio.it\/probabili-formazioni-serie-a\" target=\"_blank\" rel=\"nofollow noopener\">crocevia per il finale di stagione<\/a> della squadra di Gian Piero Gasperini.<\/p>\n<p>Roma, le ultime dall&#8217;infermeria<\/p>\n<p>Dopo la sosta del campionato inizier\u00e0 a svuotarsi l&#8217;infermeria:\u00a0<strong>il primo a recuperare sar\u00e0 Matia Soul\u00e9<\/strong>, fermo da un mese circa a causa di una fastidiosa pubalgia. <strong>L&#8217;argentino oggi \u00e8 tornato ad allenarsi in gruppo<\/strong> e dovrebbe recuperare in tempo utile per la sfida alla capolista.<\/p>\n<p>Diversa la situazione relativa a Manu <strong>Kon\u00e9, frenato da una lesione del bicipite femorale della gamba destra.\u00a0<\/strong>Il centrocampista potrebbe tornare a disposizione di Gasperini per il match del 25 aprile quando i giallorossi affronteranno il Bologna.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Archiviato il successo sul Lecce prima della sosta,\u00a0la Roma potr\u00e0 ricaricare le batteria in vista del big match&hellip;\n","protected":false},"author":3,"featured_media":410872,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1452],"tags":[721,719,720,1740,1537,90,89,251,1739,245,244],"class_list":{"0":"post-410871","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calcio","8":"tag-calcio","9":"tag-fanta","10":"tag-fantacalcio","11":"tag-football","12":"tag-it","13":"tag-italia","14":"tag-italy","15":"tag-serie-a","16":"tag-soccer","17":"tag-sport","18":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116285142940945651","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/410871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=410871"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/410871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/410872"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=410871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=410871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=410871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}