{"id":421603,"date":"2026-03-31T16:20:14","date_gmt":"2026-03-31T16:20:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/421603\/"},"modified":"2026-03-31T16:20:14","modified_gmt":"2026-03-31T16:20:14","slug":"beatrice-ed-eugenia-di-york-bandite-dalla-messa-di-pasqua-e-re-carlo-vola-in-america","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/421603\/","title":{"rendered":"Beatrice ed Eugenia di York bandite dalla messa di Pasqua e Re Carlo vola in America"},"content":{"rendered":"<p><strong>Beatrice ed Eugenia di York<\/strong> non prenderanno parte alla <strong>messa di Pasqua<\/strong> con Re Carlo, Camilla, William e Kate Middleton, come erano solite fare da quando erano bambine. Lo scandalo Epstein ha colpito anche loro, nonostante non siano minimamente coinvolte nella vicenda. Ma essendo figlie di Andrea e Sarah Ferguson sono diventate automaticamente persone non gradite a Corte.<\/p>\n<p>Beatrice ed Eugenia di York saltano la messa di Pasqua<\/p>\n<p>Dunque, per la prima volta <a href=\"https:\/\/dilei.it\/star-e-vip\/beatrice-di-york\/\" rel=\"nofollow noopener\" target=\"_blank\">Beatrice<\/a> ed <a href=\"https:\/\/dilei.it\/star-e-vip\/eugenia-di-york\/\" rel=\"nofollow noopener\" target=\"_blank\">Eugenia di York<\/a> <strong>non sono gradite alla messa di Pasqua<\/strong> con la Famiglia Reale. Le Principesse hanno rinunciato a mostrarsi accanto a Re Carlo durante la funzione religiosa. Le figlie di Andrea Mountbatten Windsor e Sarah Ferguson avrebbero deciso in autonomia di rinunciare alla messa pasquale, ma <strong>in accordo con il Sovrano<\/strong>.<\/p>\n<p><strong>Carlo non si lascia influenzare dai legami famigliari<\/strong> e, <a href=\"https:\/\/dilei.it\/reali\/re-carlo-ultime-notizie-31-marzo-2026\/2228910\/\" rel=\"nofollow noopener\" target=\"_blank\">come per suo figlio Harry e i nipotini Archie e Lilibet<\/a>, antepone la Monarchia agli affetti.<\/p>\n<p>D\u2019altro canto, lo scandalo Epstein sta rivoluzionando l\u2019esistenza di Eugenia e Beatrice. Quest\u2019ultima tra l\u2019altro<a href=\"https:\/\/dilei.it\/reali\/beatrice-eugenia-york-matrimonio-crisi-doppio-divorzio\/2212159\/\" rel=\"nofollow noopener\" target=\"_blank\"> sarebbe in crisi col marito<\/a> proprio a causa delle indagini su Andrea.<\/p>\n<p>Re Carlo non si cura delle nipoti<\/p>\n<p>Carlo non ha rilasciato commenti sulla decisione delle nipoti. Il Palazzo si \u00e8 semplicemente limitato a comunicare <strong>il programma delle funzioni pasquali<\/strong>, a partire da gioved\u00ec santo. Poi saranno presenti alle Lodi mattutine di Pasqua nella cappella di San Giorgio, all\u2019interno del complesso del Castello di Windsor, e alla messa dove saranno raggiunti dai membri della Famiglia Reale.<\/p>\n<p>Ma non da Beatrice ed Eugenia di York che appunto <strong>non saranno presenti<\/strong>. Cos\u00ec come non parteciperanno al <strong>Royal Ascot<\/strong>. Una fonte vicina alle Principesse aveva dichiarato qualche tempo fa: \u201cHo parlato con un mio amico che lavora ad Ascot e mi ha detto che alle ragazze \u00e8 stato comunicato che non potranno essere presenti quest\u2019anno. <strong>Beatrice \u00e8 quella che l\u2019ha presa peggio<\/strong>. \u00c8 stata completamente colta di sorpresa da tutto questo\u201d.<\/p>\n<p>Beatrice ed Eugenia hanno deciso di mantenere <strong>un profilo basso<\/strong> da quando il padre \u00e8 stato travolto dal caso Epstein, per evitare di compromettere ulteriormente la Corona e per proteggere la privacy della loro famiglia e dei loro figli. Beatrice starebbe meditando di <strong>trasferirsi in America<\/strong>. L\u00ec forse potrebbe contare sull\u2019appoggio di Harry. Tra l\u2019altro anche<a href=\"https:\/\/dilei.it\/reali\/re-carlo-ultime-notizie-26-marzo-2026\/2226321\/\" rel=\"nofollow noopener\" target=\"_blank\"> Sarah Ferguson \u00e8 stata avvistata negli Stati Uniti<\/a>, ospite di Priscilla Presley.<\/p>\n<p>Re Carlo e Camilla volano negli USA<\/p>\n<p>Intanto, il Palazzo ha comunicato che Re Carlo e Camilla <strong>voleranno negli Stati Uniti<\/strong> il prossimo mese, per rinforzare i \u201clegami storici e le moderne relazioni bilaterali\u201d tra i due Paesi. Quindi i Sovrani incontreranno nuovamente Donald e Melania Trump a pochi mesi di distanza dalla loro visita nel Regno Unito lo scorso autunno. Il viaggio di Stato prevede una visita alle Bermuda. Ma \u00e8 impensabile che in occasione della visita Carlo veda Harry.<\/p>\n<p>\t\t\t\tScopri i personaggi in trend, le storie del momento e molto altro.<br \/>Dove? Sul <a href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\">canale WhatsApp di DiLei!<\/a><\/p>\n<p>\t\t\t<a class=\"buttonCall\" href=\"https:\/\/whatsapp.com\/channel\/0029Vb68mVyHVvTWezDm7d0R\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Seguici su WhatsApp\"><br \/>\n\t\t\t\tSeguici su WhatsApp<br \/>\n\t\t\t<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Beatrice ed Eugenia di York non prenderanno parte alla messa di Pasqua con Re Carlo, Camilla, William e&hellip;\n","protected":false},"author":3,"featured_media":421604,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[33814,1448,1621,1620,203,100684,204,1537,90,89,144848,1447,43252],"class_list":{"0":"post-421603","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-beatrice-di-york","9":"tag-carlo-dinghilterra","10":"tag-celebrita","11":"tag-celebrities","12":"tag-entertainment","13":"tag-eugenia-di-york","14":"tag-intrattenimento","15":"tag-it","16":"tag-italia","17":"tag-italy","18":"tag-pasqua","19":"tag-reali","20":"tag-sarah-ferguson"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116324704338667366","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/421603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=421603"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/421603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/421604"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=421603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=421603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=421603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}