{"id":429299,"date":"2026-04-05T15:13:13","date_gmt":"2026-04-05T15:13:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/429299\/"},"modified":"2026-04-05T15:13:13","modified_gmt":"2026-04-05T15:13:13","slug":"riccardo-piatti-sinner-alcaraz-la-terra-rossa-e","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/429299\/","title":{"rendered":"Riccardo Piatti: &#8220;Sinner, Alcaraz, la terra rossa e&#8230;&#8221;"},"content":{"rendered":"<p>                                Lo storico ex coach di Jannik al Corriere: &#8220;Lui e Alcaraz di un livello superiore, poi viene su bene Fils, forte come un toro. Fonseca? Vorrei vederlo in una stagione a tutta&#8230;&#8221;<\/p>\n<p>                    5 aprile 2026 (modifica alle 15:20)  &#8211; MILANO<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">La terra non perdona, di certo non regala nulla. Non esiste superficie pi\u00f9 rivelatrice. &#8220;Il tennis su terra, meglio se tre set su cinque, \u00e8 il pi\u00f9 bello e difficile. Devi saper scivolare, muovere la palla, avere pazienza. Ci sono componenti che sulle altre superfici mancano&#8221;, spiega Riccardo Piatti &#8211; il coach dei grandi: Djokovic, Sharapova, Sinner, tra gli altri &#8211; intervistato dal Corriere. E infatti Montecarlo \u00e8 solo un intermezzo e come tale va vissuto: \u201cNon aspettiamoci che i big giochino alla grande da subito. Montecarlo serve per trovare i bilanciamenti, un nuovo modo di stare in campo dopo il cemento. E badate bene: non c\u2019\u00e8 una terra uguale all\u2019altra&#8221;.  Il problema, semmai, \u00e8 il tempo. \u201cDue settimane minimo. Ma i tennisti non ce le hanno. Vanno usati bene i giorni. La mia regola \u00e8: fare almeno 5-6 partite prima del torneo dove si vuole far bene\u201d. Con una differenza netta: i primi due del mondo, secondo Piatti, fanno storia a parte. \u201cAlcaraz e Sinner sono un livello sopra gli altri: a loro per fare lo switch basta poco. Alcaraz sul rosso ha una facilit\u00e0 di adattamento maggiore, a Jan potrebbe servire pi\u00f9 tempo\u201d.\u00a0<\/p>\n<p>        duello\u2014 \u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Il circuito, a oggi, \u00e8 una corsa a due. \u201cAbbiamo visto un inizio a pieno regime di Alcaraz, ora ad andare a mille \u00e8 Jannik. Nel mirino hanno entrambi Parigi: chi ci arriva meglio, vince. Vediamo come Alcaraz si rimetter\u00e0 in riga, e lo far\u00e0, e come Sinner gestir\u00e0 l\u2019avvicinamento: il suo obiettivo \u00e8 conquistare il Roland Garros e, sulla strada, Roma\u201d. I primi due al mondo hanno fatto il vuoto ma per Piatti non \u00e8 una novit\u00e0: \u201cEra successo anche ai tempi di Roger Federer\u201d. Dietro, per\u00f2, anche se a settemila punti di lontananza, qualcosa si muove: \u201cPer me, l\u2019unico che pu\u00f2 impensierire quei due sulla terra \u00e8 Zverev. \u00c8 un gran lavoratore per\u00f2 non cambia mai punto di vista: va bene il padre coach, lui si trova bene cos\u00ec, ma magari dotarsi di un allenatore che gli dica qualcosa di diverso non guasterebbe\u201d. E attenzione anche a Lorenzo Musetti: \u201cSul rosso mi aspetto buone cose anche da lui, che a Parigi gioca sempre bene\u201d.<\/p>\n<p>        nuovi talenti\u2014 \u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Tra i giovani, Piatti osserva da vicino Arthur Fils: \u201c\u00c8 forte come un toro, ha il tennis da rosso e zero punti da difendere. Qualche tempo fa, mandato dal presidente della Federtennis francese, \u00e8 venuto alla mia Academy, a Bordighera. \u00c8 intelligente, ambizioso e ha preso Ivanisevic come coach\u201d. Pi\u00f9 cauto invece su Jo\u00e3o Fonseca: \u201cIo ragiono sempre con i numeri: il brasiliano non gioca moltissimo, ha fatto 70-80 match Atp, vorrei vederlo investire una stagione a tutta birra. Quando avr\u00e0 fatto 150 match, ne riparliamo. Negli Usa ha affrontato sia Alcaraz che Sinner: ha capito cosa gli manca per vincere? Non dovrebbe dormirci la notte\u2026\u201d. Il discorso terzo incomodo \u00e8 quindi da rimandare a data da destinarsi. &#8220;Con molto lavoro, Fils potrebbe metterci un anno, a Fonseca servono 150 match nelle gambe. Un\u2019altra stagione, la prossima, passa tutta&#8221;.<\/p>\n<p>        il salto di sinner\u2014 \u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Tornando a Sinner, fresco vincitore del Sunshine Double, Piatti vede oltre il un servizio micidiale: \u201cJannik ha migliorato tutto il pacchetto, non solo il servizio. Inoltre, \u00e8 cresciuto fisicamente. Vediamo come interpreta la terra: sar\u00e0 subito aggressivo? Nel momento decisivo, sulla seconda di servizio, dovrebbe per forza esserlo\u201d. La chiave su questa superficie \u00e8 mentale e tattica, soprattutto perch\u00e9 \u201cAlcaraz \u00e8 molto produttivo nei game in risposta: viene avanti, mette pressione\u201d. Ma Piatti nella lotta per gli Slam tra i due predestinati ci infila anche c\u2019\u00e8 Novak Djokovic: \u201cNole arriver\u00e0 a Parigi senza essersi massacrato sulla terra. L\u00ec e a Wimbledon verr\u00e0 fuori il vero Djoker. Io sono un suo fan: un altro Slam pu\u00f2 vincerlo.\u201d.\u00a0<\/p>\n<p><a class=\"is-partner-link\" href=\"https:\/\/ad.doubleclick.net\/ddm\/trackclk\/N1792338.340088CAIRORCSMEDIAS.P.\/B35025367.439884924;dc_trk_aid=632943189;dc_trk_cid=249314339;dc_dbm_token=%24%7bDC_DBM_TOKEN%7d;dc_lat=;dc_rdid=;tag_for_child_directed_treatment=;tfua=;gdpr=%24%7bGDPR%7d;gdpr_consent=%24%7bGDPR_CONSENT_755%7d;ltd=;dc_tdv=1\" rel=\"nofollow noopener\" target=\"_blank\">Guarda il Rolex Monte-Carlo Masters dal 5 al 12 aprile in esclusiva streaming su NOW! Attiva il Pass Sport da 19,99\u20ac al mese<\/a><\/p>\n<p>        testa e scelte\u2014 \u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u00a0Il filo conduttore dei grandi? Piatti non ha dubbi: \u201cLa chiarezza sulle priorit\u00e0: a Jannik, non a caso, portavo l\u2019esempio di Maria Sharapova. E la brama di vincere: a tutto, anche a burraco\u201d. Chiarezza anche nelle scelte importanti, come il divorzio di Alcaraz da Ferrero che Piatti commenta cos\u00ec: \u201cQuesti ragazzi, Carlos e Jan, non guardano al passato. \u00c8 gente che bada al presente, a cosa si deve fare per vincere gli Slam. Pensano che sia meglio cambiare coach? Lo fanno, punto&#8221;. Ma basta cos\u00ec: Piatti non prevede imminenti cambiamenti nello staff dello spagnolo, nonostante le premature uscite da\u00a0Indian Wells e Miami: &#8220;Penso che non cambier\u00e0 a breve. Intanto non \u00e8 facile trovare un super coach per Alcaraz: a me piace tanto Moya. E poi perch\u00e9 ha intorno persone che gli lasciano fare quello che vuole. Per dire, con Ferrero forse <a href=\"https:\/\/video.gazzetta.it\/alcaraz-il-nuovo-yacht-e-una-meraviglia-carlos-si-fa-filmare-a-bordo-del-catamarano\/9c0ef2fa-49d3-40ae-907c-575ca4087xlk\" title=\"Alcaraz si fa filmare a bordo del suo nuovo yacht: vale 9 milioni!\" rel=\"nofollow noopener\" target=\"_blank\">uno yacht da 9 milioni di dollari<\/a> non lo comprava. Anche Nadal a un certo punto voleva lo yacht, ma zio Toni gli disse che se lo poteva scordare: doveva giocare a tennis. \u00c8 distrattivo. Quante volte all\u2019anno lo user\u00e0? Boh&#8221;.\u00a0 Per quanto riguarda invece lo staff di Sinner, Piatti esclude suggestioni romantiche. &#8220;Andre Agassi? Non credo\u201d. Meglio un profilo diverso: \u201cIo vedrei bene Andy Murray: intelligente, esperto, solido. Nel 2021, a Stoccolma, sconfisse un giovane Sinner in due set. Dopo il match andai a parlare con Andy: l\u2019avrei preso subito ma lui aveva deciso di andare avanti a giocare, accidenti\u201d.\u00a0<\/p>\n<p class=\"is-above-copyright is-mr-r-10\" spellcheck=\"true\">La Gazzetta dello Sport<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"Lo storico ex coach di Jannik al Corriere: &#8220;Lui e Alcaraz di un livello superiore, poi viene su&hellip;\n","protected":false},"author":3,"featured_media":429300,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1457],"tags":[11384,243315,243316,6094,1265,243307,83915,2537,32,7733,6911,1275,4864,5225,26568,6018,42627,243308,76965,243309,243310,41970,3440,243311,5360,1889,1251,37470,1537,90,89,61886,1269,6110,1894,15117,44460,1289,25081,8559,3338,1292,494,11835,50410,669,3645,97193,366,3423,245,244,6194,243312,577,21564,1273,3185,5517,5186,48120,4981,243313,2529,4968,5325,243314,4969,2747],"class_list":["post-429299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tennis","tag-academy","tag-academy-bordighera","tag-academy-bordighera-intelligente","tag-adattamento","tag-alcaraz","tag-alcaraz-ferrero","tag-alcaraz-sinner","tag-altra","tag-andare","tag-andy","tag-chiarezza","tag-coach","tag-corriere","tag-diverso","tag-djokovic","tag-dovrebbe","tag-ferrero","tag-ferrero-yacht","tag-fils","tag-fils-forte","tag-fils-forte-toro","tag-fonseca","tag-forte","tag-forte-toro","tag-gioca","tag-giocare","tag-grandi","tag-intelligente","tag-it","tag-italia","tag-italy","tag-jan","tag-jannik","tag-livello","tag-match","tag-montecarlo","tag-murray","tag-parigi","tag-piatti","tag-preso","tag-primi","tag-punti","tag-punto","tag-rosso","tag-scelte","tag-servizio","tag-set","tag-sharapova","tag-sinner","tag-slam","tag-sport","tag-sports","tag-staff","tag-staff-sinner","tag-stagione","tag-superficie","tag-tennis","tag-terra","tag-toro","tag-trovare","tag-vederlo","tag-vediamo","tag-vedrei","tag-viene","tag-vincere","tag-vorrei","tag-vorrei-vederlo","tag-vuole","tag-yacht"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/429299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=429299"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/429299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/429300"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=429299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=429299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=429299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}