{"id":439229,"date":"2026-04-12T00:17:16","date_gmt":"2026-04-12T00:17:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/439229\/"},"modified":"2026-04-12T00:17:16","modified_gmt":"2026-04-12T00:17:16","slug":"cosenza-nel-quartiere-casali-nasce-largo-mario-gualtieri","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/439229\/","title":{"rendered":"Cosenza, nel quartiere Casali nasce Largo Mario Gualtieri"},"content":{"rendered":"<p>L\u2019intitolazione questa mattina alla presenza del sindaco Franz Caruso e della famiglia del cantante, icona della cosentinit\u00e0<\/p>\n<p>Nel quartiere di Casali, a cento passi dal murales inaugurato il 27 dicembre del 2019 e che lo raffigura sul muro di cinta del Palazzetto dello Sport, da oggi e a futura memoria ci sar\u00e0 anche largo Mario Gualtieri, proprio accanto alla casa museo dove il cantante ed artista simbolo della cosentinit\u00e0 ha trascorso i suoi ultimi anni di vita prima della scomparsa, avvenuta nel 2018. La cerimonia ufficiale si \u00e8 svolta questa mattina, presenti moltissimi cosentini ed estimatori di Mario Gualtieri e a scoprire la targa che indica il nuovo Largo \u00e8 stato il Sindaco di Cosenza, Franz Caruso, insieme alla moglie del cantante, signora Bianca, al figlio Massimiliano e alla figlia Nadia. La vera sorpresa della giornata \u00e8 stata la presenza del cantautore cosentino Dario Brunori che non ha voluto mancare all\u2019appuntamento per far sentire la sua vicinanza alla famiglia di Mario Gualtieri, ma anche in segno di rispetto per l\u2019icona musicale cosentina che, come molti ricorderanno, aveva omaggiato durante il concerto di Capodanno in Piazza dei Bruzi intonando \u201cBuonanotte Cosenza\u201d, uno dei cavalli di battaglia di Gualtieri. Gli interventi sono stati introdotti dal popolare dee jay Franco Siciliano. Il Sindaco Franz Caruso ha ricordato il percorso che \u00e8 stato seguito per arrivare all\u2019intitolazione ufficiale. \u201cEra un dovere che io ho avvertito \u2013 ha detto Franz Caruso &#8211; nei confronti di Mario Gualtieri, della sua famiglia e di tutti i cosentini che lo hanno conosciuto ed amato. Sono orgoglioso di scoprire oggi questa targa ufficiale che grazie anche alla sensibilit\u00e0 e all\u2019aiuto del nostro Prefetto, Rosa Maria Padovano e della vicaria, dott.ssa Rosa Correale (assente per impegni sopravvenuti all\u2019ultimo momento) abbiamo potuto portare a compimento, superando i vincoli normativi che non ci consentivano prima del decorso dei dieci anni dalla morte di Mario Gualtieri di intitolargli questo largo ufficialmente. Se siamo riusciti a raggiungere questo traguardo \u00e8 perch\u00e9 ci abbiamo messo un po\u2019 di testardaggine cosentina, trovando la disponibilit\u00e0 del nostro prefetto e del prefetto vicario e riuscendo a fare \u2013 ha ribadito il primo cittadino &#8211; ci\u00f2 che era giusto fare, riconoscere a Mario questo spazio che da oggi e per sempre sar\u00e0 Largo Mario Gualtieri\u201d. Quindi il Sindaco ha invitato i presenti a visitare la casa Museo. \u201cHo avuto il piacere e l\u2019onore di entrare in casa Gualtieri e l\u00ec ho visto la storia di Mario che non tutti conosciamo. A lui siamo affezionati perch\u00e9 ci ha dedicato tante canzoni, perch\u00e9 \u00e8 stato il riferimento musicale anche del nostro calcio cittadino, regalandoci momenti emozionanti, ma lo abbiamo spesso circoscritto alla nostra realt\u00e0 territoriale. Invece \u2013 ha aggiunto Franz Caruso &#8211; andare nel museo significa entrare in contatto con il percorso artistico e umano che ha compiuto durante la sua esistenza, non solo dal punto di vista musicale. Se ci inoltriamo nella casa museo ci si imbatte in quello che \u00e8 un riferimento cosentino, calabrese e nazionale nel mondo, perch\u00e9 Mario ha girato il mondo ed \u00e8 stato molto apprezzato dal mondo forse pi\u00f9 di noi stessi ed \u00e8 questa la grande pecca che noi abbiamo, perch\u00e9 forse riconosciamo i talenti quando non ci sono pi\u00f9, ma ci vuole qualcuno che ce li ricorda e la Casa museo di Mario Gualtieri ha avuto proprio questa funzione. E\u2019 importante \u2013 ha concluso il Sindaco &#8211; intitolare il luogo dove Mario ha vissuto, dove ha creato i suoi affetti, dove ha elaborato la sua musica, ma \u00e8 altrettanto importante conoscere quello che ha seminato e tutte le targhe presenti nel museo testimoniano del suo lungo cammino, non solo per soddisfare un\u2019esigenza canora, ma soprattutto per diffondere quella che \u00e8 la cultura della solidariet\u00e0, dell\u2019amicizia, degli affetti che i cosentini e i calabresi hanno e che sanno trasmettere\u201d.<\/p>\n<p>Chi si \u00e8 speso molto perch\u00e9 la figura di Mario Gualtieri restasse nella memoria dei cosentini \u00e8 l\u2019imprenditore Federico Morabito, che ha consentito non solo la realizzazione a Casali del murales del 2019, ma anche di un\u2019altra opera dedicata al cantante cosentino su uno dei piloni della sopraelevata di via Padre Giglio, nell\u2019ambito di un progetto di riqualificazione avviato su impulso dell\u2019Amministrazione comunale guidata dal Sindaco Franz Caruso. Morabito, intervenuto anche a sostegno dell\u2019intitolazione di Largo Mario Gualtieri, era presente anche alla cerimonia di questa mattina nel corso della quale ha ricordato l\u2019iter travagliato che ha preceduto la realizzazione del murales e l\u2019ottima collaborazione con il Sindaco Franz Caruso. \u201cSi \u00e8 giunti \u2013 ha detto \u2013 all\u2019intitolazione di oggi grazie alla testardaggine, disponibilit\u00e0 e all\u2019immenso cuore del nostro Sindaco\u201d. Soddisfazione ed emozione anche nelle parole di Dario Brunori, special guest della giornata. \u201cSono molto contento che intorno alla musica, alle canzoni e a una figura come quella di Mario Gualtieri ci sia questo tipo di approccio che traduce il nostro modo di essere. Per me \u00e8 stato bellissimo, nell\u2019esperienza post sanremese \u2013ha proseguito il cantautore &#8211; ritrovare quell\u2019affetto popolare che \u00e8 arrivato dopo e che si \u00e8 rivelato un\u2019ondata incredibile. Sono sempre felice di ricevere queste manifestazioni di affetto. Anch\u2019io cerco di tenere insieme l\u2019aspetto artistico con quello solidale e umano perch\u00e9 \u00e8 importante che attraverso le canzoni e la popolarit\u00e0 che le canzoni riescono a dare, si riesca a mettere insieme un\u2019umanit\u00e0 che va in una direzione diversa da quella che stiamo vedendo nel resto del mondo\u201d. E\u2019 stata poi la volta di Sergio Crocco, responsabile dell\u2019Associazione \u201cLa Terra di Piero\u201d che a Mario Gualtieri ha dedicato anche un libro, \u201cUn divo nella nebbia\u201d, scritto insieme al figlio Max Gualtieri, a Claudio Dionesalvi e Marco Cozza. \u201cSono davvero felice \u2013 ha detto Crocco. E\u2019 questo un momento storico perch\u00e9 mettere l\u2019ufficialit\u00e0 e il nome di Mario Gualtieri in questo largo e in questo quartiere \u00e8 una cosa meravigliosa. Un debito di riconoscenza che avevamo nei suoi confronti per tutto ci\u00f2 che ha fatto per la nostra citt\u00e0 e per tutto quello che noi non sapevamo, ad esempio che amava fare beneficenza in silenzio\u201d. Quindi l\u2019annuncio, importantissimo, di Sergio Crocco. \u201cPartir\u00f2 il 20 in Tanzania, a Zanzibar, dove il 27 aprile andremo a posare la prima pietra per il parco \u201cMario Gualtieri\u201d, un parco totalmente accessibile ai bambini disabili. Lo costruiremo in un orfanotrofio dove ci sono 85 bambini, la maggior parte dei quali non udenti ed una trentina con grandi difficolt\u00e0 motorie. Daremo loro la possibilit\u00e0 di giocare come tutti gli altri bambini e giocheranno sotto la targa con il nome di Mario Gualtieri\u201d. La giornata dedicata al cantante cosentino \u00e8 stata poi suggellata dalle parole del figlio Max che, felice ed emozionato, ha rivolto un particolare ringraziamento al Sindaco Franz Caruso, \u201cche \u2013 ha detto &#8211; in questa avventura \u00e8 stato determinante\u201d e al vicario del prefetto, dottoressa Rosa Correale. Subito dopo, lo svelamento della targa, preceduto dal suono della tromba di Andrea Filice che, tra la commozione generale, ha intonato le note di \u201cBuonanotte Cosenza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019intitolazione questa mattina alla presenza del sindaco Franz Caruso e della famiglia del cantante, icona della cosentinit\u00e0 Nel&hellip;\n","protected":false},"author":3,"featured_media":439230,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1446],"tags":[1615,1613,1614,1611,1610,1612,203,204,1537,90,89],"class_list":{"0":"post-439229","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-e-design","8":"tag-arte","9":"tag-arte-e-design","10":"tag-arteedesign","11":"tag-arts","12":"tag-arts-and-design","13":"tag-design","14":"tag-entertainment","15":"tag-intrattenimento","16":"tag-it","17":"tag-italia","18":"tag-italy"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116388865358760979","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=439229"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/439230"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=439229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=439229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=439229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}